{"id":999975,"date":"2026-05-12T14:07:43","date_gmt":"2026-05-12T18:07:43","guid":{"rendered":"https:\/\/noticel.com\/?p=999975"},"modified":"2026-05-12T14:17:40","modified_gmt":"2026-05-12T18:17:40","slug":"gobernadora-entrega-proclamas-y-medallas-a-los-hermanos-irad-y-jose-luis-ortiz","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/gobierno\/20260512\/gobernadora-entrega-proclamas-y-medallas-a-los-hermanos-irad-y-jose-luis-ortiz\/","title":{"rendered":"Gobernadora entrega proclamas y medallas a los hermanos Irad y Jos\u00e9 Luis Ortiz"},"content":{"rendered":"<p>La gobernadora Jenniffer Gonz\u00e1lez Col\u00f3n recibi\u00f3 en La Fortaleza a los ganadores de la primera y segunda posici\u00f3n del Kentucky Derby, Jos\u00e9 Luis Ortiz e Irad Ortiz Jr., para reconocer la gesta de estos hermanos puertorrique\u00f1os condecor\u00e1ndolos con la otorgaci\u00f3n de la Medalla de Gobernadora y la entrega de proclamas.<\/p>\n\n\n\n<p>Esta es la primera vez que la mandataria entrega la Medalla de la Gobernadora a deportistas. Adem\u00e1s de las proclamas a ambos jinetes, la gobernadora le entreg\u00f3 una proclama a la entrenadora Cherie DeVaux por ser la primera mujer en m\u00e1s de 150 a\u00f1os de historia de la competencia en haber triunfado.<br>\u00a0<br>El campe\u00f3n Jos\u00e9 Luis Ortiz estuvo acompa\u00f1ado de su esposa Taylor Rice y el subcampe\u00f3n<br>Irad Ortiz Jr. Estuvo junto a esposa Meliza Betancourt.<br>\u00a0<br>La mandataria estuvo acompa\u00f1ada del secretario de Recreaci\u00f3n y Deportes H\u00e9ctor V\u00e1zquez Mu\u00f1iz, la directora ejecutiva de la Compa\u00f1\u00eda de Turismo Willianette Robles, el director ejecutivo de la Comisi\u00f3n de Juegos Juan Carlos Santaella March\u00e1n, la directora del Negociado H\u00edpico M\u00f3nica Andreu Mart\u00ednez, el vicepresidente del Hip\u00f3dromo-\u00a0Alberto Rodr\u00edguez\u00a0y su esposa\u00a0Mar\u00eda Elena V\u00e1zquez Graciani; y el se\u00f1or Ray Charlie- quien trae a los hermanos Ortiz, entre otros invitados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama-1024x683.jpg\" alt=\"\" class=\"wp-image-999983\" srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama-1024x683.jpg 1024w, https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama-300x200.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama-768x512.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama-1536x1024.jpg 1536w, https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama-18x12.jpg 18w, https:\/\/cdn.noticel.com\/2026\/05\/12141554\/proclama.jpg 1620w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Momento en que la gobernadora entrega la proclama a Irad Ortiz. (Nickolas N. Torres\/NotiCel)<\/em><\/figcaption><\/figure>\n\n\n\n<p><br><strong>\u00a1El Cl\u00e1sico del Caribe vuelve a Puerto Rico!<\/strong><br>\u00a0<br>\u201cEl Cl\u00e1sico del Caribe es el Kentucky Derby de Am\u00e9rica Latina. La Ley 192-2004 asigna $500,000 pero esa cantidad se qued\u00f3 corta al crecimiento de la industria h\u00edpica. Por eso estaremos asignando este a\u00f1o $1 mill\u00f3n a este evento, para hacerlo viable en Puerto Rico. Gracias a esta asignaci\u00f3n de fondos seremos la sede del evento del 2-6 de diciembre 2026\u201d, anunci\u00f3 la gobernadora.<br>\u00a0<br>\u201cEl Cl\u00e1sico del Caribe en Puerto Rico es una oportunidad hist\u00f3rica para continuar y construir sobre el enorme triunfo de Irad y Jos\u00e9 Luis Ortiz y continuar promocionando a Puerto Rico como un destino tur\u00edstico. Eventos como este promueven m\u00e1s oportunidades a j\u00f3venes puertorrique\u00f1os. Ejemplo vivo como Irad y Jos\u00e9 Ortiz, que empezaron en estos eventos en el Hip\u00f3dromo Camarero y hoy conquistan el mundo. As\u00ed se crean campeones\u201d, a\u00f1adi\u00f3 Gonz\u00e1lez Col\u00f3n.<br>\u00a0<br>El Cl\u00e1sico del Caribe tiene un impacto econ\u00f3mico estimado por la metodolog\u00eda de Turismo en $3.3 millones. Se estiman m\u00e1s de 3,100 cuartos noche. Las delegaciones internacionales permanecen en la isla por 2 semanas, generando un gasto recurrente muy superior al turista promedio. El Hip\u00f3dromo Camarero est\u00e1 contribuyendo $1mill\u00f3n adicionales en recursos propios; incluyendo $276,000 para crear una cuarentena de caballos apropiada para Puerto Rico y las regulaciones federales.<br>\u00a0<br>La transmisi\u00f3n del evento a nueve pa\u00edses participantes posiciona la marca \u00abPuerto Rico\u00bb ante millones de espectadores, potenciando el turismo deportivo presente y futuro. Los pa\u00edses son: Panam\u00e1, Venezuela, M\u00e9xico, Rep\u00fablica Dominicana, Ecuador, Colombia, Jamaica, Trinidad &amp; Tobago y Puerto Rico.<\/p>","protected":false},"excerpt":{"rendered":"<p>La gobernadora Jenniffer Gonz\u00e1lez Col\u00f3n recibi\u00f3 en La Fortaleza a los ganadores de la primera y segunda posici\u00f3n del Kentucky Derby, Jos\u00e9 Luis Ortiz e Irad Ortiz Jr., para reconocer la gesta de estos hermanos puertorrique\u00f1os condecor\u00e1ndolos con la otorgaci\u00f3n de la Medalla de Gobernadora y la entrega de proclamas. Esta es la primera vez [&hellip;]<\/p>","protected":false},"author":100,"featured_media":999979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31,4],"tags":[153,5650,3875],"class_list":["post-999975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-gobierno","tag-gobernadora","tag-proclama","tag-recibimiento"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/999975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=999975"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/999975\/revisions"}],"predecessor-version":[{"id":999984,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/999975\/revisions\/999984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/999979"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=999975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=999975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=999975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}