{"id":999270,"date":"2026-05-08T06:54:10","date_gmt":"2026-05-08T10:54:10","guid":{"rendered":""},"modified":"2026-05-08T14:09:05","modified_gmt":"2026-05-08T18:09:05","slug":"tiroteo-deja-saldo-de-tres-muertos-en-bayamon","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/policiacas\/20260508\/tiroteo-deja-saldo-de-tres-muertos-en-bayamon\/","title":{"rendered":"Tiroteo deja saldo de tres muertos en Bayam\u00f3n"},"content":{"rendered":"<p>La Polic\u00eda inform\u00f3 el viernes que un tercer hombre muri\u00f3 por heridas de bala tras un tiroteo reportado la noche del jueves en la carretera PR-174, frente a una gasolinera Texaco en Bayam\u00f3n.<\/p>\n\n\n\n<p>Seg\u00fan informaron las autoridades, una llamada telef\u00f3nica alert\u00f3 sobre varias personas heridas de bala en las inmediaciones de la estaci\u00f3n ubicada frente a las instalaciones de Coca-Cola Puerto Rico Bottlers. La pesquisa preliminar apunta a que el tiroteo surgi\u00f3 en medio de una discusi\u00f3n entre tres hombres.<\/p>\n\n\n\n<p>La Polic\u00eda precis\u00f3 que la v\u00edctima y uno de los agresores murieron en la escena a causa de las heridas de bala. Un segundo agresor fue transportado a una instituci\u00f3n hospitalaria para recibir tratamiento m\u00e9dico, pero falleci\u00f3 m\u00e1s tarde.<\/p>\n\n\n\n<p>En horas de la tarde de hoy, en el Instituto de Ciencias Forenses, familiares identificaron a la v\u00edctima como Yadrian D\u00edaz Serrado, de 21 a\u00f1os, quien resid\u00eda en Bayam\u00f3n. Mientras que el agresor, quien muri\u00f3 en la escena, fue identificado como Jonathan Rivera Flores, de 39 a\u00f1os, del pueblo de Cidra, quien contaba con expediente criminal.<\/p><div class=\"notic-content-middle\" id=\"notic-1641640741\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>Al momento, el hombre que muri\u00f3 en la instituci\u00f3n m\u00e9dica no ha sido identificado.<\/p>\n\n\n\n<p>Se inform\u00f3 que el agente Jorge Mel\u00e9ndez, bajo la supervisi\u00f3n del sargento Luis Calder\u00f3n, adscrito al Cuerpo de Investigaciones Criminales (CIC) de Bayam\u00f3n, junto a la fiscal Liz L\u00f3pez tienen a cargo la investigaci\u00f3n.<\/p>\n\n\n\n<p>La Polic\u00eda exhort\u00f3 a quien tenga informaci\u00f3n que ayude en el esclarecimiento de casos a comunicarse al 787-343-2020, o escribir a trav\u00e9s de X en @PRPDNoticias o en Facebook en&nbsp;<a href=\"https:\/\/www.facebook.com\/prpdgov\">www.facebook.com\/prpdgov<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda inform\u00f3 el viernes que un tercer hombre muri\u00f3 por heridas de bala tras un tiroteo reportado la noche del jueves en la carretera PR-174, frente a una gasolinera Texaco en Bayam\u00f3n. Seg\u00fan informaron las autoridades, una llamada telef\u00f3nica alert\u00f3 sobre varias personas heridas de bala en las inmediaciones de la estaci\u00f3n ubicada frente [&hellip;]<\/p>","protected":false},"author":101,"featured_media":999271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[15],"tags":[1880,794],"class_list":["post-999270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiacas","tag-asesinatos","tag-bayamon-2"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/999270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=999270"}],"version-history":[{"count":5,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/999270\/revisions"}],"predecessor-version":[{"id":999377,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/999270\/revisions\/999377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/999271"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=999270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=999270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=999270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}