{"id":998835,"date":"2026-05-06T14:31:26","date_gmt":"2026-05-06T18:31:26","guid":{"rendered":""},"modified":"2026-05-06T14:34:33","modified_gmt":"2026-05-06T18:34:33","slug":"fiscalia-federal-presenta-cargos-contra-cinco-por-importar-cocaina-desde-venezuela","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260506\/fiscalia-federal-presenta-cargos-contra-cinco-por-importar-cocaina-desde-venezuela\/","title":{"rendered":"Fiscal\u00eda federal presenta cargos contra cinco por importar coca\u00edna desde Venezuela"},"content":{"rendered":"<p>Cinco individuos enfrentan cargos criminales a nivel federal tras ser acusados recientemente por intentar importar droga desde Venezuela<\/p>\n\n\n\n<p>Seg\u00fan la fiscal\u00eda federal, el 30 de abril un gran jurado autoriz\u00f3 una acusaci\u00f3n de cuatro cargos contra Jhon Dennis Guerrero Trotman, Jaime Jos\u00e9 Marval Guti\u00e9rrez, Jos\u00e9 Gregorio Pereira Orfila y H\u00e9ctor Gregorio Jim\u00e9nez Herrera por conspirar para importar coca\u00edna y conspirar para distribuir coca\u00edna proveniente de Venezuela. Seg\u00fan el gobierno, el mes pasado intentaron entrar al pa\u00eds al menos cinco kilos.<\/p>\n\n\n\n<p>El 26 de abril las autoridades ocuparon un cargamento de 48 paquetes con la droga para un total de 1,320 kilos.<\/p><div class=\"notic-content-middle\" id=\"notic-2227526230\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>El 29 de abril otro individuo, Douglas Antonio Fern\u00e1ndez Rodr\u00edguez fue acusado por conspiracion para importar coca\u00edna, tambi\u00e9n desde Venezuela. En su caso, se le acusa de tratar de entrar al pa\u00eds 709.1 kilos, que fueron ocupados.<\/p>\n\n\n\n<p>En otro caso separado, tambi\u00e9n el 29 de abril se presentaron cargos por narcotr\u00e1fico contra Jos\u00e9 Fernando Huggins Figueroa. Supuestamente el hombre intent\u00f3 importar 20 kilos de coca\u00edna.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cinco individuos enfrentan cargos criminales a nivel federal tras ser acusados recientemente por intentar importar droga desde Venezuela Seg\u00fan la fiscal\u00eda federal, el 30 de abril un gran jurado autoriz\u00f3 una acusaci\u00f3n de cuatro cargos contra Jhon Dennis Guerrero Trotman, Jaime Jos\u00e9 Marval Guti\u00e9rrez, Jos\u00e9 Gregorio Pereira Orfila y H\u00e9ctor Gregorio Jim\u00e9nez Herrera por conspirar [&hellip;]<\/p>","protected":false},"author":100,"featured_media":227778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3,2],"tags":[5624,3735],"class_list":["post-998835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","category-ultima-hora","tag-cocaina-2","tag-fiscalia-federal-2"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=998835"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998835\/revisions"}],"predecessor-version":[{"id":998836,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998835\/revisions\/998836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/227778"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=998835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=998835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=998835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}