{"id":998331,"date":"2026-05-05T13:23:31","date_gmt":"2026-05-05T17:23:31","guid":{"rendered":""},"modified":"2026-05-05T13:36:18","modified_gmt":"2026-05-05T17:36:18","slug":"ppd-denuncia-que-one-source-intento-establecer-un-esquema-similar-en-otro-hogar","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260505\/ppd-denuncia-que-one-source-intento-establecer-un-esquema-similar-en-otro-hogar\/","title":{"rendered":"PPD denuncia que One Source intent\u00f3 establecer un esquema similar en otro hogar"},"content":{"rendered":"<p>La delegaci\u00f3n del Partido Popular Democr\u00e1tico (PPD) en el Senado denunci\u00f3 que One Source Investigations radic\u00f3 en octubre de 2022 una demanda de cobro por la suma $120,000 por servicios prestados a un segundo hogar que provee asistencia a pacientes con discapacidades intelectuales.<\/p>\n\n\n\n<p>Seg\u00fan el documento sometido en el Tribunal de Primera Instancia en Bayam\u00f3n, el 17 de diciembre de 2021 ocurri\u00f3 una reuni\u00f3n entre el due\u00f1o del hogar con Jes\u00fas Nadal como presidente de One Source Investigations para discutir los detalles de un posible acuerdo. La oferta inicial era una contrataci\u00f3n de $45,000 mensuales, divididos en $40,000 para One Source Investigations y el restante para el hogar sustituto. Las facturas dirigidas a un hogar sustituto fueron por febrero, marzo y abril de 2022 por $40,000 cada uno. <\/p>\n\n\n\n<p>Asimismo, se detalla en el reclamo escrito que Nadal pretend\u00eda que el due\u00f1o del segundo hogar reconociera que One Source intervino para enmendar el contrato y aumentarlo a $50,000 mensuales, de los cuales $40,000 para la compa\u00f1\u00eda y $10,000 para el proveedor. El mismo paciente tambi\u00e9n estuvo en Hacienda Don Luis hasta diciembre de 2021, seg\u00fan se desprende del expediente del Departamento de Salud. Eliut Col\u00f3n, propietario de Hacienda Don Luis, reclam\u00f3 p\u00fablicamente que un acuerdo para recibir al paciente por $60,000 mensuales estuvo condicionado a la subcontrataci\u00f3n de One Source Investigations.<\/p>\n\n\n\n<p>\u201cCuando ese primer proveedor (Hacienda Don Luis) le pone un detente a Roig, se van con un segundo proveedor con un acuerdo muy similar de $50,000 por el participante a cambio de que $40,000 fueran dirigidos a la compa\u00f1\u00eda One Source. Este segundo proveedor tambi\u00e9n le puso un detente a los actos de corrupci\u00f3n de Roig al punto que One Source los demand\u00f3 por cobro de dinero\u201d, explic\u00f3 la senadora Marially Gonz\u00e1lez Huertas durante una conferencia de prensa en el Capitolio.<\/p><div class=\"notic-content-middle\" id=\"notic-4081823866\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>Seg\u00fan Luis Javier Hern\u00e1ndez Ortiz, al parecer las partes llegaron a un acuerdo fuera de corte para cerrar el pleito.<\/p>\n\n\n\n<p>\u201cCreo que hubo un tipo de negociaci\u00f3n y el Departamento de Salud le pag\u00f3 a la compa\u00f1\u00eda. Hubo un acuerdo con One Source\u201d, dijo Hern\u00e1ndez Ortiz. \u201cLo importante es que en esa demanda hay una alegaci\u00f3n de One Source donde admite que intervino en el contrato. Es importante que Justicia lo eval\u00fae porque confirma nuestra teor\u00eda\u201d, agrega.<\/p>\n\n\n\n<p>Los senadores insistieron que la secretaria de Justicia, Lourdes G\u00f3mez, reabra la pesquisa que fue archivada por la fiscal Melitza Osorio Santiago en octubre de 2025 y, al siguiente mes, confirmada de manera un\u00e1nime en el Senado para un ascenso.<\/p>","protected":false},"excerpt":{"rendered":"<p>La delegaci\u00f3n del Partido Popular Democr\u00e1tico (PPD) en el Senado denunci\u00f3 que One Source Investigations radic\u00f3 en octubre de 2022 una demanda de cobro por la suma $120,000 por servicios prestados a un segundo hogar que provee asistencia a pacientes con discapacidades intelectuales. Seg\u00fan el documento sometido en el Tribunal de Primera Instancia en Bayam\u00f3n, [&hellip;]<\/p>","protected":false},"author":93,"featured_media":998337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,5,3],"tags":[1133,250,206,263],"class_list":["post-998331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-legislatura","category-noticias","tag-familia","tag-legislatura","tag-salud","tag-senado"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=998331"}],"version-history":[{"count":8,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998331\/revisions"}],"predecessor-version":[{"id":998604,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998331\/revisions\/998604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/998337"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=998331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=998331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=998331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}