{"id":998198,"date":"2026-05-03T11:38:39","date_gmt":"2026-05-03T15:38:39","guid":{"rendered":"https:\/\/noticel.com\/?p=998198"},"modified":"2026-05-03T12:35:07","modified_gmt":"2026-05-03T16:35:07","slug":"asesinan-a-hombre-en-santurce-2","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260503\/asesinan-a-hombre-en-santurce-2\/","title":{"rendered":"Asesinan a hombre en Santurce"},"content":{"rendered":"<p>Un asesinato se report\u00f3 a las 2:22 de la madrugada del domingo en un estacionamiento en la intersecci\u00f3n de la calle Cerra y la calle Las Palmas, en Santurce.<\/p>\n\n\n\n<p>Seg\u00fan el reporte de la Polic\u00eda, una llamada a trav\u00e9s del Sistema de Emergencias 9-1-1, alert\u00f3 sobre m\u00faltiples disparos.<\/p>\n\n\n\n<p>De la informaci\u00f3n preliminar surge que, al llegar los agentes de la Polic\u00eda Municipal de San Juan, encontraron a el cad\u00e1ver de Vidal Antonio Fern\u00e1ndez Ram\u00edrez de 26 a\u00f1os\u00a0con varias heridas de bala en diferentes partes del cuerpo.<\/p>\n\n\n\n<p>El agente D\u00e1vila, adscrito a la Polic\u00eda Municipal de San Juan, y personal de la Divisi\u00f3n de Homicidios del Cuerpo de Investigaciones Criminales de San Juan investigan.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un asesinato se report\u00f3 a las 2:22 de la madrugada del domingo en un estacionamiento en la intersecci\u00f3n de la calle Cerra y la calle Las Palmas, en Santurce. Seg\u00fan el reporte de la Polic\u00eda, una llamada a trav\u00e9s del Sistema de Emergencias 9-1-1, alert\u00f3 sobre m\u00faltiples disparos. De la informaci\u00f3n preliminar surge que, al [&hellip;]<\/p>","protected":false},"author":101,"featured_media":617581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[3,15],"tags":[142,1497],"class_list":["post-998198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-policiacas","tag-asesinato","tag-santurce"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=998198"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998198\/revisions"}],"predecessor-version":[{"id":998202,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/998198\/revisions\/998202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/617581"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=998198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=998198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=998198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}