{"id":997685,"date":"2026-05-01T05:47:00","date_gmt":"2026-05-01T09:47:00","guid":{"rendered":""},"modified":"2026-05-01T07:50:49","modified_gmt":"2026-05-01T11:50:49","slug":"se-reduce-la-migracion-entre-puerto-rico-y-estados-unidos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260501\/se-reduce-la-migracion-entre-puerto-rico-y-estados-unidos\/","title":{"rendered":"Se reduce la migraci\u00f3n entre Puerto Rico y Estados Unidos"},"content":{"rendered":"<p>El movimiento migratorio entre Puerto Rico y Estados Unidos se ha reducido en los \u00faltimos a\u00f1os, pero siguen siendo m\u00e1s lo que se van que los que regresan a la Isla.<\/p>\n\n\n\n<p>Un informe actualizado sobre dicho movimiento migratorio confirma, adem\u00e1s, que el principal destino de los puertorrique\u00f1os es el \u00e1rea sureste de Estados Unidos, que comprende los estados de Texas, Oklahoma, Arkansas, Louisiana, Mississipi, Alabama, Tennessee, Kentucky, Georgia, Florida, Carolina del Norte, Carolina del Sur, Virginia, West Virginia y Maryland.<\/p>\n\n\n\n<p>El informe \u201cPerfil del migrante 2023\u20132024\u201d, en el que se presentan los hallazgos m\u00e1s recientes sobre los movimientos poblacionales entre Puerto Rico y Estados Unidos fue presentado por Alberto Vel\u00e1zquez Estrada, gerente senior de Proyectos Estad\u00edsticos del Instituto de Estad\u00edsticas de Puerto Rico<\/p>\n\n\n\n<p>El an\u00e1lisis se fundamenta en productos estad\u00edsticos como el Perfil del Migrante, que integran informaci\u00f3n de fuentes oficiales como la Encuesta sobre la Comunidad del U.S. Census Bureau, entre otras m\u00e9tricas de movilidad poblacional como el US Bureau of Transportation Statistics.<\/p>\n\n\n\n<p>\u201cLos \u00faltimos tres a\u00f1os de informaci\u00f3n de la Encuesta (2022-2024) han marcado un movimiento emigratorio neto relativamente menor, aun as\u00ed, se estim\u00f3 m\u00e1s personas movi\u00e9ndose hacia afuera de la jurisdicci\u00f3n\u201d, expres\u00f3 Vel\u00e1zquez Estrada.<\/p>\n\n\n\n<p>\u201cA modo de contexto frente a la pasada d\u00e9cada: del 2011-2014 la emigraci\u00f3n neta promedio represent\u00f3 un -1.5% anual de la poblaci\u00f3n total. Del 2021-2024 esta se tradujo a -0.6% anual de la poblaci\u00f3n total\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Seg\u00fan el informe, la regi\u00f3n noreste de Estados Unidos, que por d\u00e9cadas fue el principal destino de los boricuas, ha ido cambiando y bajando como destino de los emigrantes, aunque se mantiene en segundo lugar.<\/p><div class=\"notic-content-middle\" id=\"notic-2311247243\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>\u201cEl midwest se estar\u00e1 ubicando en los pr\u00f3ximos a\u00f1os como segunda \u00e1rea como destino de los boricuas. Mientras, el oeste sigue siendo la regi\u00f3n que menos boricuas tiene como destino\u201d, dijo Vel\u00e1zquez Estrada.<\/p>\n\n\n\n<p>En t\u00e9rminos de estados, Florida es el primero en la lista de los migrantes, seguido por Texas y Pensilvania en tercer lugar. Se calcula que en Florida hay 1.3 millones de boricuas.<\/p>\n\n\n\n<p>El promedio de edad de los emigrantes puertorrique\u00f1os es 45 a\u00f1os.<\/p>\n\n\n\n<p>Otros hallazgos que mencion\u00f3 son que, al comparar el a\u00f1o 2024 con el 2023 los emigrantes fueron menos j\u00f3venes, una ligera mayor\u00eda de mujeres sobre hombres, con una disminuci\u00f3n en el nivel de educaci\u00f3n alcanzado, con menor porcentaje fuera de la fuerza laboral y sin cambio sustancial en el ingreso.<\/p>\n\n\n\n<p>En cambio, los inmigrantes eran m\u00e1s j\u00f3venes, con mayor\u00eda de hombres, de mayor nivel de educaci\u00f3n alcanzada en t\u00e9rminos porcentuales, con menor proporci\u00f3n fuera de la fuerza laboral y con un ingreso marcadamente mayor.<\/p>\n\n\n\n<p>El \u00e1rea central tuvo entre 1,500 a 2,000 inmigrantes desde Estados Unidos, aproximadamente, la regi\u00f3n de la Isla que m\u00e1s inmigrantes registr\u00f3. Otras regiones que han recibido m\u00e1s inmigrantes son el sureste, el noroeste, municipios del \u00e1rea metro como San Juan, Bayam\u00f3n y Carolina y las islas municipio de Vieques y Culebra.<\/p>\n\n\n\n<p>Vel\u00e1zquez Estrada present\u00f3 datos sobre variables como edad, nivel educativo, ingresos y tendencias de movilidad. El experto destac\u00f3 que este tipo de an\u00e1lisis resulta clave para comprender el impacto de la migraci\u00f3n en \u00e1reas como el mercado laboral, la planificaci\u00f3n gubernamental y el desarrollo econ\u00f3mico, as\u00ed como para orientar la toma de decisiones basada en datos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--1024x682.jpg\" alt=\"\" class=\"wp-image-997690\" srcset=\"https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--1024x682.jpg 1024w, https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--300x200.jpg 300w, https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--768x512.jpg 768w, https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--1536x1023.jpg 1536w, https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--2048x1364.jpg 2048w, https:\/\/cdn.noticel.com\/2026\/04\/30144559\/25-04-10-AEROSTAR-PROYECTA-ALTO-VOLUMEN-DE-VIAJEROS-EN-SEMANA-SANTA-EJMM-0019--18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>El promedio de edad de los emigrantes puertorrique\u00f1os es 45 a\u00f1os. (Archivo\/NotiCel)<\/em><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>El movimiento migratorio entre Puerto Rico y Estados Unidos se ha reducido en los \u00faltimos a\u00f1os, pero siguen siendo m\u00e1s lo que se van que los que regresan a la Isla. Un informe actualizado sobre dicho movimiento migratorio confirma, adem\u00e1s, que el principal destino de los puertorrique\u00f1os es el \u00e1rea sureste de Estados Unidos, que [&hellip;]<\/p>","protected":false},"author":99,"featured_media":997689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,3],"tags":[363,2966,3610],"class_list":["post-997685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-noticias","tag-estadisticas","tag-instituto-de-estadisticas","tag-migracion-2"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/997685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=997685"}],"version-history":[{"count":4,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/997685\/revisions"}],"predecessor-version":[{"id":997817,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/997685\/revisions\/997817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/997689"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=997685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=997685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=997685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}