{"id":9952,"date":"2017-08-15T00:00:00","date_gmt":"2017-08-15T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/en-serio\/20170815\/de-la-nada-estrena-el-jingle-oficial-de-julia-keleher-video\/"},"modified":"2025-07-22T03:37:43","modified_gmt":"2025-07-22T03:37:43","slug":"de-la-nada-estrena-el-jingle-oficial-de-julia-keleher-video","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20170815\/de-la-nada-estrena-el-jingle-oficial-de-julia-keleher-video\/","title":{"rendered":"De La Nada estrena el jingle &#8216;oficial&#8217; de Julia Keleher (video)"},"content":{"rendered":"<p>El colectivo de s\u00e1tira gr\u00e1fica &#8216;De La Nada&#8217;, public\u00f3 en sus redes sociales un nuevo video donde crea un <em>jingle <\/em>de la secretaria del Departamento de Educaci\u00f3n (DE), Julia Keleher.<\/p>\n<p>En el video, inspirado en la serie de anime Sailor Moon, Keleher es mostrada como la superhero\u00edna que todo lo puede en el DE. Adem\u00e1s, se cuestionan los m\u00faltiples sombreros que esta tiene en la actual administraci\u00f3n del Partido Nuevo Progresista (PNP) y el sueldo que ostenta.<\/p>\n<p><strong>Mira el video a continuaci\u00f3n:<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El colectivo de s\u00e1tira gr\u00e1fica &#8216;De La Nada&#8217;, public\u00f3 en sus redes sociales un nuevo video donde crea un jingle de la secretaria del Departamento de Educaci\u00f3n (DE), Julia Keleher. En el video, inspirado en la serie de anime Sailor Moon, Keleher es mostrada como la superhero\u00edna que todo lo puede en el DE. Adem\u00e1s, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":551680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-9952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/9952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=9952"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/9952\/revisions"}],"predecessor-version":[{"id":551681,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/9952\/revisions\/551681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/551680"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=9952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=9952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=9952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}