{"id":991756,"date":"2026-03-31T14:37:22","date_gmt":"2026-03-31T18:37:22","guid":{"rendered":""},"modified":"2026-03-31T15:15:13","modified_gmt":"2026-03-31T19:15:13","slug":"salud-dice-que-mantiene-investigacion-activa-ante-situacion-de-hospital-wilma-vazquez","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260331\/salud-dice-que-mantiene-investigacion-activa-ante-situacion-de-hospital-wilma-vazquez\/","title":{"rendered":"Salud dice que mantiene investigaci\u00f3n activa ante situaci\u00f3n de Hospital Wilma V\u00e1zquez"},"content":{"rendered":"<p>El secretario de Salud, V\u00edctor Ramos Otero, expres\u00f3 hoy que, ante la manifestaci\u00f3n de empleados del Hospital Wilma V\u00e1zquez, el Departamento de Salud mantiene una investigaci\u00f3n activa liderada por la secretaria auxiliar para la Regulaci\u00f3n de Salud, Wanda Rodr\u00edguez.<\/p>\n\n\n\n<p>Esto debido a un patr\u00f3n de incumplimiento laboral con sus empleados por la alegada paga con cheques sin fondo y otras denuncias de sus empleados por los pasados tres meses. <\/p>\n\n\n\n<p>El titular de Salud explic\u00f3 que a mediado de este mes se remiti\u00f3 un requerimiento formal de informaci\u00f3n a la instituci\u00f3n hospitalaria, otorg\u00e1ndole un t\u00e9rmino de 30 d\u00edas para responder, el cual a\u00fan se encuentra vigente y no ha expirado, cuando se trajo varias situaciones similares a las de hoy y otras.<\/p>\n\n\n\n<p>Asimismo, Ramos Otero indic\u00f3 que, conforme a los registros del Departamento, no se han recibido querellas formales recientes relacionadas con la situaci\u00f3n. No obstante, enfatiz\u00f3 que el equipo de inspectores se mantiene en estado de alerta y en vigilancia constante para garantizar el cumplimiento con las disposiciones regulatorias y la seguridad de los pacientes.<\/p>\n\n\n\n<p>\u201cEl Departamento de Salud actuar\u00e1 con responsabilidad, rigor y dentro del marco de la ley. Nuestro compromiso es velar por la calidad de los servicios de salud y la protecci\u00f3n de todos los ciudadanos\u201d, concluy\u00f3 el secretario.<\/p>","protected":false},"excerpt":{"rendered":"<p>El secretario de Salud, V\u00edctor Ramos Otero, expres\u00f3 hoy que, ante la manifestaci\u00f3n de empleados del Hospital Wilma V\u00e1zquez, el Departamento de Salud mantiene una investigaci\u00f3n activa liderada por la secretaria auxiliar para la Regulaci\u00f3n de Salud, Wanda Rodr\u00edguez. Esto debido a un patr\u00f3n de incumplimiento laboral con sus empleados por la alegada paga con [&hellip;]<\/p>","protected":false},"author":100,"featured_media":991772,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3],"tags":[5099,206,352],"class_list":["post-991756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","tag-hospital-wilma-n-vazquez","tag-salud","tag-victor-ramos"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=991756"}],"version-history":[{"count":4,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991756\/revisions"}],"predecessor-version":[{"id":991787,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991756\/revisions\/991787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/991772"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=991756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=991756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=991756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}