{"id":991728,"date":"2026-03-31T14:54:13","date_gmt":"2026-03-31T18:54:13","guid":{"rendered":"https:\/\/noticel.com\/?p=991728"},"modified":"2026-03-31T14:54:24","modified_gmt":"2026-03-31T18:54:24","slug":"desbandan-a-narcoganga-que-prometia-muerte-al-virao","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260331\/desbandan-a-narcoganga-que-prometia-muerte-al-virao\/","title":{"rendered":"Desbandan a narcoganga que promet\u00eda \u201cmuerte al vira\u2019o\u201d"},"content":{"rendered":"<p>Tras un a\u00f1o de investigaci\u00f3n, pero con arrestos e incautaciones de drogas y armas desde 2018, las autoridades federales anunciaron el martes que acusaron a 52 miembros de la organizaci\u00f3n criminal conocida como La Familia Nunca Muere, incluyendo a dos cabecillas.<\/p>\n\n\n\n<p>Los cargos son por conspiraci\u00f3n para poseer con intenci\u00f3n de distribuir sustancias controladas, distribuci\u00f3n de drogas y violaciones a la ley de armas en San Juan, Morovis y Cata\u00f1o. Veintitres de los acusados ya estaban presos y otro n\u00famero igual fueron arrestados ahora, restando seis pr\u00f3fugos.<\/p>\n\n\n\n<p>La acusaci\u00f3n alega que, desde 2018 hasta el presente, la organizaci\u00f3n distribuy\u00f3 coca\u00edna, marihuana, hero\u00edna y fentanilo dentro de 1,000 pies de los residenciales p\u00fablicos Los Lirios, Jardines de Cata\u00f1o, Juana Matos, El Coqu\u00ed y Nemesio Rosario Canales, as\u00ed como en \u00e1reas cercanas, con el objetivo de obtener beneficio econ\u00f3mico y lucro. El documento tambi\u00e9n sostiene que miembros de la ganga participaron en tiroteos y asesinatos en lugares p\u00fablicos, utilizaron veh\u00edculos hurtados o robados mediante carjacking y se comunicaban por radios, tel\u00e9fonos celulares, mensajer\u00eda instant\u00e1nea y redes sociales.<\/p>\n\n\n\n<p>El jefe de la Oficina del Fiscal de los Estados Unidos para el Distrito de Puerto Rico, W. Stephen Muldrow, dijo que no dar\u00eda detalles sobre los asesinatos atribuidos a la ganga, pero confirm\u00f3 que varios acusados est\u00e1n involucrados con la balacera durante un cumplea\u00f1os en Cata\u00f1o en 2023 y en la que result\u00f3 muerto un ni\u00f1o de cuatro a\u00f1os.<\/p>\n\n\n\n<p>Espec\u00edficamente, el acusado Edwin \u201cBubu\u201d Rivera P\u00e9rez habr\u00eda sido el objetivo de aquella balacera de 2023. En junio de 2022, este tambi\u00e9n conduc\u00eda la guagua en la que muri\u00f3 asesinada su entonces pareja, la personalidad de redes sociales, Isadora \u201cPinky Curvy\u201d Nieves Cruz.<\/p>\n\n\n\n<p>En cuanto a actos de violencia, la fiscal\u00eda indic\u00f3 que este grupo se conoc\u00eda por disparar primero y preguntar despu\u00e9s, reaccionando a amenazas percibidas sin confirmar si, en efecto, eran amenazas reales. Esto conllev\u00f3 asesinatos en espacios p\u00fablicos, a plena luz del d\u00eda, y en presencia de menores y personas inocentes.<\/p>\n\n\n\n<p>Seg\u00fan la acusaci\u00f3n, los imputados ejerc\u00edan distintos roles dentro de la organizaci\u00f3n, entre ellos l\u00edderes, suplidores, due\u00f1os de puntos de droga, gatilleros, corredores, vendedores, vigilantes y facilitadores. A 40 de los acusados se les imputa posesi\u00f3n de armas de fuego en apoyo de un delito de narcotr\u00e1fico, mientras que a 21 de ellos tambi\u00e9n se les acusa por posesi\u00f3n de una ametralladora en apoyo de un delito de narcotr\u00e1fico. Todos enfrentan adem\u00e1s una alegaci\u00f3n de confiscaci\u00f3n de $12.8 millones, que es el estimado de lo que generaron vendiendo narc\u00f3ticos durante la conspiraci\u00f3n.<\/p>\n\n\n\n<p>Como en otros casos, parte de la evidencia que tienen los fiscales son mensajes de redes sociales en las que los acusados alardeaban de las armas que ten\u00edan o de la droga que vend\u00edan, como una forma de proclamar dominio en su territorio.<\/p><div class=\"notic-content-middle\" id=\"notic-2830839628\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>Muldrow afirm\u00f3 que, tambi\u00e9n como en otras ocasiones, en este caso ocurri\u00f3 que los miembros de la ganga ocuparon apartamentos vac\u00edos en los complejos de vivienda p\u00fablica para usarlos para los actos criminales por los que se le acusa. El representante m\u00e1ximo del ejecutivo federal en la isla explic\u00f3 que han pedido al gobierno local fiscalizaci\u00f3n sobre esos apartamentos desocupados y que el financiamiento federal de vivienda p\u00fablica se podr\u00eda afectar por la repetici\u00f3n de esta conducta.<\/p>\n\n\n\n<p>Adem\u00e1s de La Familia Nunca Muere, se hac\u00edan llamar Los Incorregibles y La Colectora (o La Cole). Los miembros que estaban en prisi\u00f3n segu\u00edan participando de las actividades de la ganga mediante llamadas de videoconferencia hechas con tel\u00e9fonos celulares de contrabando.<\/p>\n\n\n\n<p>Adem\u00e1s de Rivera P\u00e9rez, est\u00e1n acusados Tom\u00e1s Junior S\u00e1nchez Gonz\u00e1lez, alias Father, Boss, Patr\u00f3n y Gemelo; Junior Tom\u00e1s S\u00e1nchez Gonz\u00e1lez, alias Bere, Bereta y Gemelo; Jaime V\u00e1zquez Rom\u00e1n, alias T\u00edo To\u00edto; Carlos D. Valladares D\u00edaz, alias Dany, Lalo, Ojos Bellos y Ojos Lindos; Omar Mat\u00edas Mart\u00ednez, alias KTM; Duhamel J. Natal Gonz\u00e1lez, alias Banchi; Luis Joel Rivera Torres, alias Taly; N\u00e9stor N. Gonz\u00e1lez Mu\u00f1iz, alias Silencio y Mudo; Randy Padilla Fern\u00e1ndez, alias R; Tom\u00e1s Niochar S\u00e1nchez Feliciano, alias Nio; \u00c1ngel De Jes\u00fas V\u00e1squez, alias El Negro y D.O.; Jonathan Gonz\u00e1lez Agosto, alias Tat\u00e1n; Israel J. Gonz\u00e1lez Rosado, alias Kiko; Sa\u00fal Rodr\u00edguez Serrano, alias Patroncito; Jaybdiel L\u00f3pez Paz, alias Dreki Malo; Luis Antonio Rosa Hern\u00e1ndez, alias Menor de Fajardo; Luis Isander Medina V\u00e1zquez, alias Sugar, Flaco y Trenzas; Kevin M. Rijos Sep\u00falveda, alias Yeezy; Jorge S. Rodr\u00edguez Rivera, alias Gallero; John Michael Rentas Rivera, alias D\u00e1lmata; Gabrielle Eliud Delgado Garay, alias Kayak y KK; Pedro Antonio Barreto Mart\u00ednez, alias Pedrito, Mago y Maguito; Pedro A. Polanco Febus; Yadiel Daniel Rosario Castro, alias Papote; y Jeancarlos Reynoso Peralta, alias Domi y Gre\u00f1a.<\/p>\n\n\n\n<p>Tambi\u00e9n figuran Jordanish Manuel Torres Villegas, alias Mutombo; John Huertas Rodr\u00edguez, alias Casque; Giann Luis Rijos Sep\u00falveda, alias Yeesy, Yisi y Yeezysito; Freddy Maldonado Castillo, alias Sonrisa y Sonri; Carlos Rosario Reyes, alias Carlos Papi; Yahir Armando Ayala Rodr\u00edguez, alias Duende; Yecdiel Daniel Oliveras, alias Chagui; Josten Anthony Ramos, alias Justin Ramos y Prosper; Carlo Andr\u00e9 D\u00edaz Sep\u00falveda, alias Chavito; Adri\u00e1n Gabriel Ramos L\u00f3pez, alias ADN; Javier Col\u00f3n Oppenheimer, alias Javielito, Javi y TT de Trastalleres; Adam Yadiel D\u00edaz Santiago, alias El Menor; Joshua Yadie De Jes\u00fas De Jes\u00fas, alias Tokio y Yadiel; Jonathan Ram\u00f3n Gonz\u00e1lez P\u00e9rez, alias Tripi y Cripi; Fabi\u00e1n O. Mart\u00ednez Maldonado, alias Dreki Bueno y Draky Bueno; Noriel Iv\u00e1n Alvarado; Joseph Col\u00f3n Pag\u00e1n, alias Canito; Elliott Francis Correa Martorell, alias Ele; Adin Jafet Cruz Sastre, alias J; Paulina Santiago Vega; Yatniel Iv\u00e1n Ramos Borrero, alias Chama; Miguel S\u00e1nchez Reyes, alias Cabe; Ronny Arias Paulino, alias Karate; Elvin Josu\u00e9 Jim\u00e9nez De la Rosa, alias Bin; Jomar Rashid Torres Torres, alias Jomo y Yomo; y Juan Gianny Rodr\u00edguez Tosado, alias Guasy.<\/p>\n\n\n\n<p>Si son convictos por los cargos de drogas, los acusados enfrentan una pena m\u00ednima obligatoria de 10 a\u00f1os y hasta cadena perpetua. Si son convictos por los cargos de drogas y armas en el cargo cuatro, enfrentan una pena m\u00ednima obligatoria de 15 a\u00f1os y hasta cadena perpetua, mientras que los acusados imputados por posesi\u00f3n de ametralladoras en el cargo cinco enfrentan una pena obligatoria de 30 a\u00f1os de prisi\u00f3n, a cumplirse de manera consecutiva a cualquier sentencia por narcotr\u00e1fico.<\/p>\n\n\n\n<p>Muldrow enmarc\u00f3 el caso bajo la iniciativa de la Orden Ejecutiva 14159, que da al Departamento de Seguridad Nacional la encomienda de proteger al p\u00fablico estadounidense de la \u201cinvasi\u00f3n\u201d de cartes y organizaciones criminales.<\/p>\n\n\n\n<p>Los fiscales Alberto L\u00f3pez Rocafort, Teresa Zapata Valladares, Joseph Russell y Mar\u00eda L\u00f3pez Aponte tienen a su cargo el procesamiento criminal en este caso.<\/p>\n\n\n\n<p>En una de las im\u00e1genes que fiscal\u00eda proyect\u00f3 sobre las actividades del grupo para pedir al tribunal que los deje presos sin fianza se observa un grafiti en el que advirtieron que dar\u00edan \u201cmuerte al vira\u2019o\u201d, lo que se interpreta como muerte a los chotas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tras un a\u00f1o de investigaci\u00f3n, pero con arrestos e incautaciones de drogas y armas desde 2018, las autoridades federales anunciaron el martes que acusaron a 52 miembros de la organizaci\u00f3n criminal conocida como La Familia Nunca Muere, incluyendo a dos cabecillas. Los cargos son por conspiraci\u00f3n para poseer con intenci\u00f3n de distribuir sustancias controladas, distribuci\u00f3n [&hellip;]<\/p>","protected":false},"author":100,"featured_media":991732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,3],"tags":[2315,1339,793,4489],"class_list":["post-991728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-noticias","tag-acusaciones","tag-cargos-criminales","tag-ganga-criminal","tag-stephen-muldrow"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=991728"}],"version-history":[{"count":4,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991728\/revisions"}],"predecessor-version":[{"id":991769,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991728\/revisions\/991769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/991732"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=991728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=991728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=991728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}