{"id":991563,"date":"2026-03-30T16:37:51","date_gmt":"2026-03-30T20:37:51","guid":{"rendered":""},"modified":"2026-03-30T16:41:54","modified_gmt":"2026-03-30T20:41:54","slug":"causa-para-juicio-contra-hombre-que-mato-a-cuchillazos-a-su-hijo-infante","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/judicatura\/20260330\/causa-para-juicio-contra-hombre-que-mato-a-cuchillazos-a-su-hijo-infante\/","title":{"rendered":"Causa para juicio contra hombre que mat\u00f3 a cuchillazos a su hijo infante"},"content":{"rendered":"<p>Una jueza del Tribunal de Caguas encontr\u00f3 esta tarde causa para juicio contra Christian Serrano Rosario, el hombre imputado de asesinar a su hijo de cinco a\u00f1os en la v\u00edspera del D\u00eda de Reyes en Caguas.<\/p>\n\n\n\n<p>La jueza Mibari Rivera tom\u00f3 la determinaci\u00f3n tras escuchar el testimonio de tres testigos, report\u00f3 El Nuevo D\u00eda.<\/p>\n\n\n\n<p>Entre estos, la madre del infante. Adem\u00e1s, una investigadora forense<\/p>\n\n\n\n<p>La vista de lectura de acusaci\u00f3n ha sido se\u00f1alada para el 14 de abril.<\/p>\n\n\n\n<p>El fiscal Dennis Soto Fantauzzi present\u00f3 la prueba sobre el crimen cometi\u00f3 con un arma blanca. La defensa contin\u00faa levantando dudas sobre la capacidad mental del acusado.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una jueza del Tribunal de Caguas encontr\u00f3 esta tarde causa para juicio contra Christian Serrano Rosario, el hombre imputado de asesinar a su hijo de cinco a\u00f1os en la v\u00edspera del D\u00eda de Reyes en Caguas. La jueza Mibari Rivera tom\u00f3 la determinaci\u00f3n tras escuchar el testimonio de tres testigos, report\u00f3 El Nuevo D\u00eda. Entre [&hellip;]<\/p>","protected":false},"author":100,"featured_media":991566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[6],"tags":[142,381,4519,2156],"class_list":["post-991563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-judicatura","tag-asesinato","tag-caguas","tag-christian-serrano-rosario","tag-infante"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=991563"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991563\/revisions"}],"predecessor-version":[{"id":991567,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/991563\/revisions\/991567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/991566"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=991563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=991563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=991563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}