{"id":987721,"date":"2026-03-12T13:14:39","date_gmt":"2026-03-12T17:14:39","guid":{"rendered":""},"modified":"2026-03-12T13:27:52","modified_gmt":"2026-03-12T17:27:52","slug":"familia-de-roberto-viqueira-solicita-al-procurador-general-reconsideracion-de-fallo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/tribunales\/20260312\/familia-de-roberto-viqueira-solicita-al-procurador-general-reconsideracion-de-fallo\/","title":{"rendered":"Familia de Roberto Viqueira solicita al Procurador General reconsideraci\u00f3n de fallo"},"content":{"rendered":"<p>La viuda e hijos del bi\u00f3logo Roberto Viqueira presentado una solicitud formal al Procurador General y al Departamento de Justicia para que se reconsidere la posibilidad de revisar el fallo absolutorio emitido.<\/p>\n\n\n\n<p>La petici\u00f3n plantea que el caso merece un an\u00e1lisis adicional por parte de los tribunales apelativos ante las serias interrogantes jur\u00eddicas y de pol\u00edtica p\u00fablica que ha generado la determinaci\u00f3n del juez \u00c1ngel Llavona Figueroa, particularmente en torno a la interpretaci\u00f3n y aplicaci\u00f3n de la doctrina de leg\u00edtima defensa.<\/p>\n\n\n\n<p>Seg\u00fan el memorando presentado, el sistema de justicia contempla mecanismos para que decisiones judiciales puedan ser revisadas cuando existe una percepci\u00f3n razonable de que pudieron haberse cometido errores de derecho. La familia sostiene que solicitar dicha revisi\u00f3n no constituye un cuestionamiento al sistema judicial, sino precisamente el ejercicio de los procesos que garantizan su transparencia y evoluci\u00f3n.<\/p>\n\n\n\n<p>\u201cCuando una decisi\u00f3n judicial genera profundas dudas sobre la correcta aplicaci\u00f3n de la ley, el propio sistema provee los canales para que los tribunales superiores examinen la controversia\u201d, plantea el documento sometido a consideraci\u00f3n del Departamento de Justicia y del Procurador General.<\/p>\n\n\n\n<p>La familia de Viqueira expres\u00f3 que su solicitud responde a un leg\u00edtimo inter\u00e9s de justicia y respeto hacia la vida del cient\u00edfico, cuya trayectoria profesional estuvo marcada por su contribuci\u00f3n al estudio y protecci\u00f3n del ambiente.<\/p>\n\n\n\n<p>El documento tambi\u00e9n destaca que corresponde finalmente al Tribunal Supremo de Puerto Rico determinar si la normativa vigente debe reafirmarse o reconsiderarse, pero para que ese an\u00e1lisis pueda ocurrir es necesario que el asunto sea presentado ante el foro correspondiente.<\/p><div class=\"notic-content-middle\" id=\"notic-2381247331\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>Para la familia de Viqueira, esta gesti\u00f3n representa un paso necesario para procurar que el caso sea examinado con el m\u00e1ximo rigor jur\u00eddico posible.<\/p>\n\n\n\n<p>\u201cLa b\u00fasqueda de justicia no es un acto de confrontaci\u00f3n con las instituciones, sino una afirmaci\u00f3n de la confianza en que el sistema tiene la capacidad de revisarse y fortalecerse\u201d, se desprende de la solicitud.<\/p>\n\n\n\n<p>La familia reiter\u00f3 que su objetivo es que se eval\u00faen todas las herramientas legales disponibles para garantizar que el caso sea analizado a la luz de los m\u00e1s altos principios de justicia.<\/p>\n\n\n\n<p>Historias relacionadas:<\/p>\n\n\n\n<p><a href=\"https:\/\/noticel.com\/en\/noticias\/tribunales\/20260218\/justicia-no-apelara-absolucion-del-enfermero-acusado-de-matar-al-biologo-robert-viqueira\/\" title=\"\">Justicia no apelar\u00e1 absoluci\u00f3n del enfermero acusado de matar al bi\u00f3logo Robert Viqueira<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/noticel.com\/en\/noticias\/la-calle\/20260219\/familia-de-biologo-asesinado-no-contempla-mudarse-de-su-casa-en-yauco\/\" title=\"\">Familia de bi\u00f3logo asesinado no contempla mudarse de su casa en Yauco<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La viuda e hijos del bi\u00f3logo Roberto Viqueira presentado una solicitud formal al Procurador General y al Departamento de Justicia para que se reconsidere la posibilidad de revisar el fallo absolutorio emitido. La petici\u00f3n plantea que el caso merece un an\u00e1lisis adicional por parte de los tribunales apelativos ante las serias interrogantes jur\u00eddicas y de [&hellip;]<\/p>","protected":false},"author":100,"featured_media":987725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[13],"tags":[4119,4790,4090],"class_list":["post-987721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunales","tag-procurador-general","tag-reconsideracion","tag-robert-viqueira"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/987721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=987721"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/987721\/revisions"}],"predecessor-version":[{"id":987730,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/987721\/revisions\/987730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/987725"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=987721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=987721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=987721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}