{"id":984662,"date":"2026-02-26T13:03:21","date_gmt":"2026-02-26T17:03:21","guid":{"rendered":"https:\/\/noticel.com\/?p=984662"},"modified":"2026-02-26T13:14:51","modified_gmt":"2026-02-26T17:14:51","slug":"los-criollos-nombran-a-edwards-guzman-como-director-de-operaciones-y-dirigente","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260226\/los-criollos-nombran-a-edwards-guzman-como-director-de-operaciones-y-dirigente\/","title":{"rendered":"Los Criollos nombran a Edwards Guzm\u00e1n como director de operaciones y dirigente"},"content":{"rendered":"<p>Los Criollos de Caguas anunciaron el nombramiento del exjugador de Grandes Ligas Edwards Guzm\u00e1n como nuevo director de operaciones de b\u00e9isbol y dirigente de la franquicia para la temporada 2026-27 de \u00a0la Liga de B\u00e9isbol Profesional Roberto Clemente (LBPRC).<br><br>Guzm\u00e1n, quien tendr\u00e1 a su cargo la reestructuraci\u00f3n de la plantilla y la planificaci\u00f3n deportiva del equipo, tambi\u00e9n ser\u00e1 responsable del nombramiento del pr\u00f3ximo gerente general de los Criollos.<br><br>Como parte del acuerdo para relevar a Guzm\u00e1n de su compromiso contractual como dirigente de los Gigantes de Carolina, la organizaci\u00f3n de los Criollos cedi\u00f3 los derechos del guardabosque MJ Mel\u00e9ndez.<br><br>\u201cCon la llegada de Edwards Guzm\u00e1n iniciamos una nueva etapa en la organizaci\u00f3n. Su conocimiento del juego, liderazgo y compromiso con la excelencia nos brindan la confianza de que estamos dando un paso firme en la direcci\u00f3n correcta\u201d, dijo el presidente de los Criollos, Ra\u00fal Rodr\u00edguez Font.<br><br>Por su parte, el vicepresidente Arturo Ondina resalt\u00f3 la trayectoria del nuevo dirigente y ejecutivo.<br><br>\u201cEdwards Guzm\u00e1n ha tenido \u00e9xito en cada una de las posiciones que ha ocupado. Su experiencia como jugador, dirigente y ejecutivo lo convierten en la persona indicada para asumir esta gran responsabilidad\u201d, indic\u00f3 Ondina.<br><br>Guzm\u00e1n cuenta con experiencia previa como gerente general de los Criollos en las temporadas 2017-18, 2018-19 y 2019-20. Adem\u00e1s, fungi\u00f3 como director de operaciones. Por las pasadas cuatro temporadas se desempe\u00f1\u00f3 como dirigente de los Gigantes de Carolina, equipo al que gui\u00f3 al subcampeonato en 2022-23 y 2023-24, con dos premios consecutivos de Dirigente del A\u00f1o. Como jugador, Guzm\u00e1n jug\u00f3 en las Grandes Ligas durante tres temporadas con los Gigantes de San Francisco y los Expos de Montreal.<br><br>El nuevo director de operaciones de b\u00e9isbol estar\u00e1 a cargo de evaluar la plantilla y establecer la estructura deportiva del equipo, en coordinaci\u00f3n con la futura designaci\u00f3n del gerente general.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Los Criollos de Caguas anunciaron el nombramiento del exjugador de Grandes Ligas Edwards Guzm\u00e1n como nuevo director de operaciones de b\u00e9isbol y dirigente de la franquicia para la temporada 2026-27 de \u00a0la Liga de B\u00e9isbol Profesional Roberto Clemente (LBPRC). Guzm\u00e1n, quien tendr\u00e1 a su cargo la reestructuraci\u00f3n de la plantilla y la planificaci\u00f3n deportiva del [&hellip;]<\/p>","protected":false},"author":100,"featured_media":984666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[32,31],"tags":[2239,409,349],"class_list":["post-984662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes","tag-criollos-de-caguas","tag-lbprc","tag-liga-de-beisbol-profesional-roberto-clemente"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/984662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=984662"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/984662\/revisions"}],"predecessor-version":[{"id":984669,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/984662\/revisions\/984669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/984666"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=984662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=984662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=984662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}