{"id":97860,"date":"2012-08-27T00:40:00","date_gmt":"2012-08-27T04:40:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20120827\/morovis-le-tumbo-el-invicto-a-carolina\/"},"modified":"2025-07-15T08:24:35","modified_gmt":"2025-07-15T08:24:35","slug":"morovis-le-tumbo-el-invicto-a-carolina","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20120827\/morovis-le-tumbo-el-invicto-a-carolina\/","title":{"rendered":"Morovis le tumb\u00f3 el invicto a Carolina"},"content":{"rendered":"<p>La jugadora nacional Pamela Rosado anot\u00f3 19 puntos y reparti\u00f3 seis asistencias para conducir a las Monta\u00f1eras de Morovis (1-0) a una victoria por el m\u00ednimo 69-68 sobre las Gigantes de Carolina (2-1), en su primer compromiso en el campeonato 2012 del Baloncesto Superior Nacional Femenino (BSNF), celebrado en el Coliseo Guillermo Angulo de la Tierra de Gigantes.<\/p>\n<p>Carolina dominaba 66-62, tras canasta de Cindy Valent\u00edn, con 3:53 del \u00faltimo cuarto. Pero una cesta de Rosado y dos tiradas libres de Neisha Figueroa empat\u00f3 a 66 las hostilidades, con 2:35. Stephanie Pi\u00f1eiro rompi\u00f3 el empate desde la l\u00ednea de los suspiros y Rosado logr\u00f3 la ventaja definitiva 69-66, con 1:12.<\/p>\n<p>Las Gigantes tuvieron oportunidad de dejar sobre el tabloncillo a Morovis, con dos tiros libres de Valent\u00edn restando 36 segundos y luego de un robo de bal\u00f3n de Rodsan Rodr\u00edguez, con cinco segundos. Rodr\u00edguez adelant\u00f3 el bal\u00f3n con un pase a Angiely Morales, quien decidi\u00f3 no tomar el tiro y pasar la bola a manos de Valent\u00edn consumiendo el tiempo.<\/p>\n<p>El primer periodo cerr\u00f3 empate a 21 puntos, pero un bombazo de Figueroa y tirada libre de Angelina Williams despeg\u00f3 a las Monta\u00f1eras 25-21, con 8:55 del segundo segmento. M\u00e1s adelante, Rosado le otorg\u00f3 la mayor diferencia en el desaf\u00edo a Morovis, 47-36, con 2:10.<\/p>\n<p>Acto seguido, Carla Cortijo consigui\u00f3 una penetraci\u00f3n, donde cay\u00f3 de manera aparatosa de espalda en el tabloncillo. Cortijo tuvo que ser atendida por param\u00e9dicos, inmovilizada y llevada a un hospital del \u00e1rea en ambulancia debido a fuerte dolor de espalda.<\/p>\n<p>La mitad concluy\u00f3 47-44, a favor de las ganadoras.<\/p>\n<p>Carolina realiz\u00f3 una corrida 10-2 durante el tercer acto, para tomar la delantera 54-49, con 2:26. Luego de un intercambio de canastos, Katir\u00eda Rodr\u00edguez con un tiro brincado y Amanda Sep\u00falveda con un bombazo finaliz\u00f3 los primeros 30 minutos igualados a 56 tantos.<\/p>\n<p>Morovis tambi\u00e9n cont\u00f3 con 12 puntos de Williams y Figueroa con 11. Por las Gigantes, Valentin fue la mejor con 20 tantos, junto a 19 de Yolanda Jones con 12 rebotes.<\/p>\n<p>Mari Pl\u00e1cido acert\u00f3 un tiro restando dos d\u00e9cimas de segundo, otorg\u00e1ndole a las Piratas de Quebradillas (3-0) su tercer triunfo en la campa\u00f1a en igual n\u00famero de encuentros 83-81 frente a las Valencianas de Juncos (1-1), en choque escenificado en el coliseo Raymond Dalmau de la ciudad de corsarios.<\/p>\n<p>Juncos hab\u00eda logrado ventaja de tres, 81-78, tras cesta de Gatti Werema, con 21 segundos por jugarse en el partido. Las Valencianas cambiaron su defensa a zona y Melissa Lechlitner las hizo pagar con un bombazo, para empatar a 81 hasta el canasto de Pl\u00e1cido.<\/p>\n<p>Las visitantes lograron ganar el primer acto 18-11, pero vieron reducida la diferencia al m\u00ednimo 35-34 al concluir la primera mitad. Juncos logr\u00f3 despegarse en el tercer parcial 61-56, lo que no fue suficiente para garantizar la victoria.<\/p>","protected":false},"excerpt":{"rendered":"<p>La jugadora nacional Pamela Rosado anot\u00f3 19 puntos y reparti\u00f3 seis asistencias para conducir a las Monta\u00f1eras de Morovis (1-0) a una victoria por el m\u00ednimo 69-68 sobre las Gigantes de Carolina (2-1), en su primer compromiso en el campeonato 2012 del Baloncesto Superior Nacional Femenino (BSNF), celebrado en el Coliseo Guillermo Angulo de la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":318914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-97860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/97860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=97860"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/97860\/revisions"}],"predecessor-version":[{"id":318916,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/97860\/revisions\/318916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/318914"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=97860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=97860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=97860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}