{"id":9744,"date":"2020-01-30T00:00:00","date_gmt":"2020-01-30T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/la-calle\/top-stories\/20200130\/molinelli-pr-debe-tener-calma-tras-terremoto-entre-cuba-y-jamaica\/"},"modified":"2025-07-20T15:35:30","modified_gmt":"2025-07-20T15:35:30","slug":"molinelli-pr-debe-tener-calma-tras-terremoto-entre-cuba-y-jamaica","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20200130\/molinelli-pr-debe-tener-calma-tras-terremoto-entre-cuba-y-jamaica\/","title":{"rendered":"Molinelli: \u2018PR debe tener calma&#8217; tras terremoto entre Cuba y Jamaica"},"content":{"rendered":"<p><i>El sistema de placas tect\u00f3nicas es diferente<\/i><\/p>\n<p>El terremoto de magnitud 7.7 ocurrido ayer entre Cuba y Jamaica fue parte del movimiento de la Placa del Caribe, pero no significa que Puerto Rico sufrir\u00e1 un sismo igual, asegur\u00f3 hoy el doctor Jose Molinelli.<\/p>\n<p>El geomorf\u00f3logo dijo en entrevista radial (WKAQ) que los movimientos en esa zona son igual de normales que los de la zona de Puerto Rico, pero que en este caso fue el resultado del movimiento de la Placa del Norte hacia el oeste mientras que la del Caribe se movi\u00f3 hacia el este.<\/p>\n<p>&#8216;Son movimientos de lateral izquierdo. Son parte de los movimientos de la placa tect\u00f3nica del Caribe&#8217;, explic\u00f3 Molinelli. &#8216;Han ocurrido sismos muy fuertes en esa placa. En esa zona en particular hab\u00eda poca actividad s\u00edsmica registrada recientemente. Cuando hay zonas en silencio puede haber lo que se llama un silencio s\u00edsmico y son m\u00e1s propensas a que haya un terremoto mayor&#8217;, indic\u00f3.<\/p><div class=\"notic-content-middle\" id=\"notic-2542605615\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Lee m\u00e1s en: <a href=\"https:\/\/noticel.com\/en\/mundo\/terremoto-77-sacude-parte-de-cuba-y-jamaica\/1158213327\/\" target=\"_blank\">Terremoto 7.7 sacude parte de Cuba y Jamaica<\/a><\/p>\n<p>Pero el movimiento de esa zona de la Placa del Caribe ocurri\u00f3 en un sistema diferente, por lo que no es indicativo de que ocurrir\u00e1 uno similar en nuestra regi\u00f3n.<\/p>\n<p>&#8216;La respuesta es no. Son sistemas diferentes. Es parte del macrosistema &#8216;Placa del Caribe&#8217; pero no est\u00e1n conectados. La gente puede estar tranquila con eso. Me han llamado para preguntarme y la gente equivocadamente concluye que puede pasar aqu\u00ed. Desde el punto de vista cient\u00edfico no tiene que ver con el \u00e1rea de ac\u00e1&#8217;, afirm\u00f3 el cient\u00edfico.<\/p>\n<p>En cuanto al sismo entre Cuba y Jamaica dijo que ocurri\u00f3 lejos de \u00e1reas pobladas por lo que tuvo efectos menores. &#8216;A m\u00e1s de un centenar de kil\u00f3metros de tierra firme. Lo peor que se sinti\u00f3 de ese sismo fue equivalente o menor de lo que sinti\u00f3 en Guayanilla el 7 de enero&#8217;, manifest\u00f3 el experto.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"1158280355\" embed-content-groupid=\"593030471\" embed-content-id=\"1158280355\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2020\/01\/29\/18-06-27-Foro%20Radiografi%CC%81a%20de%20un%20Desastre%20NHM-5_1580299281235.jpg_39800100_ver1.0_640_360.jpg\" style=\"width:100%;\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>El sistema de placas tect\u00f3nicas es diferente El terremoto de magnitud 7.7 ocurrido ayer entre Cuba y Jamaica fue parte del movimiento de la Placa del Caribe, pero no significa que Puerto Rico sufrir\u00e1 un sismo igual, asegur\u00f3 hoy el doctor Jose Molinelli. El geomorf\u00f3logo dijo en entrevista radial (WKAQ) que los movimientos en esa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":538941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-9744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/9744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=9744"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/9744\/revisions"}],"predecessor-version":[{"id":538942,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/9744\/revisions\/538942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/538941"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=9744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=9744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=9744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}