{"id":97143,"date":"2013-05-01T00:54:00","date_gmt":"2013-05-01T04:54:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20130501\/nba-playoffs-saca-cara-iguodala-por-los-nuggets\/"},"modified":"2025-07-15T09:45:09","modified_gmt":"2025-07-15T09:45:09","slug":"nba-playoffs-saca-cara-iguodala-por-los-nuggets","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20130501\/nba-playoffs-saca-cara-iguodala-por-los-nuggets\/","title":{"rendered":"NBA &#8216;Playoffs&#8217;: Saca cara Iguodala por los Nuggets"},"content":{"rendered":"<p>El escolta Andre Iguodala encabez\u00f3 el ataque de los Nuggets en su victoria por 107-100 sobre los Warriors de Golden State, que mantuvo con vida a los de Denver en la serie al mejor de siete de la Conferencia Oeste.<\/p>\n<p>El quinto partido de la fase final la dominan los Warriors por 3-2. El sexto encuentro se producir\u00e1 este jueves en Oakland.<\/p>\n<p>Iguodala consigui\u00f3 un doble-doble de 25 puntos, 12 rebotes, incluidos nueve que fueron defensivos, siete asistencias, recuper\u00f3 dos balones y puso un tap\u00f3n.<\/p>\n<p>Junto a Iguodala, el base Ty Lawson dirigi\u00f3 el juego de los Nuggets e impidi\u00f3 que Stephen Curry fuese factor ganador de los Warriors al cortarles su ataque de transici\u00f3n.<\/p>\n<p>Lawson tambi\u00e9n aport\u00f3 cifras dobles al anotar 19 puntos, repartir 10 asistencias, capturar tres rebotes y recuperar dos balones.<\/p>\n<p>El ala-p\u00edvot Kenneth Faried domin\u00f3 bajo los aros y en la pintura y consigui\u00f3 13 puntos, 10 rebotes, recuper\u00f3 dos balones y puso un tap\u00f3n.<\/p>\n<p>Faried, que anul\u00f3 al p\u00edvot australiano Andrew Bogut, tambi\u00e9n fue el que puso la energ\u00eda y permiti\u00f3 a los Nuggets recuperar su mejor juego defensivo que le ayudaron a mantenerse dentro de la competici\u00f3n y tener la oportunidad de conseguir empatar la eliminatoria.<\/p>\n<p>&#8216;Era importante no s\u00f3lo conseguir la victoria sino tambi\u00e9n recuperar nuestra identidad como equipo y eso es lo que logramos&#8217;, declar\u00f3 el entrenador de los Nuggets, George Karl.<\/p>\n<p>El escolta-alero Wilson Chandler impuls\u00f3 el ataque de los Nuggets al conseguir 19 puntos, incluidos cinco triples.<\/p>\n<p>El veterano base Andre Miller anot\u00f3 11 puntos y fue el sexto hombre de los Nuggets que logr\u00f3 n\u00fameros de dos d\u00edgitos, adem\u00e1s de repartir cinco asistencias.<\/p>\n<p>Los Nuggets tambi\u00e9n tuvieron mejor control del bal\u00f3n en el quinto partido al perderlo 12 veces por 17 de los Warriors y ah\u00ed estuvo otra de las claves del triunfo del equipo de Denver, que rompieron racha de tres derrotas consecutivas, y en su campo del Pepsi Center, de Denver, no han perdido dos partidos seguidos desde el 8 al 9 de febrero del 2012.<\/p>\n<p>El alero novato Harrison Barnes lider\u00f3 el ataque de los Warriors al aportar 23 puntos y nueve rebotes, mientras que el veterano base Jarrett Jack logr\u00f3 20 tantos y fue el segundo m\u00e1ximo encestador de una lista de cuatro jugadores que lograron n\u00fameros de dos d\u00edgitos.<\/p>\n<p>El escolta Klay Thompson lleg\u00f3 a los 19 puntos y Curry no tuvo su mejor inspiraci\u00f3n ofensiva y logr\u00f3 15 tantos (8-17, 3-8, 0-0), captur\u00f3 seis rebotes, dio dos asistencias y puso un tap\u00f3n.<\/p>\n<p>Los Warriors tienen marca de 6-19 sin el ala-p\u00edvot David Lee, y 3-1 en la competici\u00f3n de la fase final, pero esta vez, el equipo si extra\u00f1\u00f3 la aportaci\u00f3n del l\u00edder de la liga en el apartado estad\u00edstico del doble-doble.<\/p>","protected":false},"excerpt":{"rendered":"<p>El escolta Andre Iguodala encabez\u00f3 el ataque de los Nuggets en su victoria por 107-100 sobre los Warriors de Golden State, que mantuvo con vida a los de Denver en la serie al mejor de siete de la Conferencia Oeste. El quinto partido de la fase final la dominan los Warriors por 3-2. El sexto [&hellip;]<\/p>","protected":false},"author":0,"featured_media":324385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-97143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/97143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=97143"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/97143\/revisions"}],"predecessor-version":[{"id":324386,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/97143\/revisions\/324386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/324385"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=97143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=97143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=97143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}