{"id":969495,"date":"2025-12-21T16:05:29","date_gmt":"2025-12-21T20:05:29","guid":{"rendered":"https:\/\/noticel.com\/?p=969495"},"modified":"2025-12-21T16:10:53","modified_gmt":"2025-12-21T20:10:53","slug":"aborto-libre-censura-nuevo-proyecto-de-ley-que-otorga-personalidad-juridica-al-feto","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20251221\/aborto-libre-censura-nuevo-proyecto-de-ley-que-otorga-personalidad-juridica-al-feto\/","title":{"rendered":"Aborto Libre censura nuevo proyecto de ley que otorga personalidad jur\u00eddica al feto"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>La organizaci\u00f3n Aborto Libre Puerto Rico conden\u00f3 esta tarde la decisi\u00f3n de la gobernadora Jenniffer Gonz\u00e1lez de convertir en ley el Proyecto del Senado 504, otorgando personalidad jur\u00eddica al cigoto, embri\u00f3n o feto.&nbsp;<\/p>\n\n\n\n<p>Esta ley, seg\u00fan denunci\u00f3 Aborto Libre Puerto Rico en declaraciones escritas, suspende la autonom\u00eda y emancipaci\u00f3n de las mujeres y personas gestantes, las somete a un r\u00e9gimen de tutela y permite que terceros intervengan en sus decisiones \u00edntimas y m\u00e9dicas.\u00a0<\/p>\n\n\n\n<p>\u201cUna vez m\u00e1s, la pol\u00edtica partidista sacrifica derechos fundamentales en favor de sectores conservadores y fundamentalistas, dejando a las mujeres desprotegidas\u201d, lee el escrito en que se acus\u00f3 a Gonz\u00e1lez de darle la espalda al reclamo de cientos de profesionales de la salud y el derecho, al igual que decenas de organizaciones de derechos humanos y derechos de las mujeres en Puerto Rico.\u00a0<\/p>\n\n\n\n<p>En las pasadas semanas, estos grupos hicieron declaraciones p\u00fablicas e intentaron de diversas maneras comunicarle a la gobernadora cu\u00e1n, peligroso, seg\u00fan indicaron, es este proyecto. El Proyecto del Senado 504 fue aprobado, denunciaron, de manera apresurada y sin consulta, trastocando el ordenamiento jur\u00eddico vigente y amenazando los est\u00e1ndares de cuidado y los protocolos cl\u00ednicos que rigen la pr\u00e1ctica m\u00e9dica, donde \u201cdebe prevalecer el principio \u00e9tico de la autonom\u00eda\u201d.<\/p><div class=\"notic-content-middle\" id=\"notic-3089908200\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>Esta ley, afirmaron, pone en riesgo la salud, la libertad y la autonom\u00eda de las mujeres y personas gestantes, reproduciendo efectos ya documentados en otras jurisdicciones, donde la personalidad fetal ha derivado en criminalizaci\u00f3n y graves da\u00f1os a sus vidas y derechos.<\/p>\n\n\n\n<p>\u201cAdem\u00e1s, el PS 504 suspende de manera expl\u00edcita los procesos de emancipaci\u00f3n al condicionar la capacidad de decisi\u00f3n de las mujeres al simple hecho de un embarazo, desplaz\u00e1ndolas como sujetas plenas de derechos y exponi\u00e9ndolas a la intervenci\u00f3n de terceros en decisiones sobre su cuerpo y su vida. Esta regresi\u00f3n atenta contra la igualdad, la autonom\u00eda personal y el reconocimiento de las mujeres como personas libres y capaces de decidir sobre sus propios cuerpos y su futuro\u201d, lee el escrito firmado por Rosa Segu\u00ed, Yanira Reyes Gil, Ruthie Arroyo y Alondra Hern\u00e1ndez Qui\u00f1ones.<\/p>\n\n\n\n<p>\u201cEste proyecto, ahora ley, no se aprob\u00f3 para resolver problema legal o de salud alguno. Por el contrario, este cambio en el C\u00f3digo Civil, provocar\u00e1 conflictos legales y m\u00e9dicos, innecesariamente. A pesar de que se hicieron advertencias sobre estos peligros por parte de personas expertas en derecho y salud, la gobernadora opt\u00f3 por ignorarlas. Esta acci\u00f3n solo puede entenderse como un c\u00e1lculo pol\u00edtico dirigido a congraciarse con sectores conservadores y fundamentalistas religiosos, aun cuando ello implique sacrificar derechos humanos fundamentales. En esta batalla pol\u00edtico partidista los derechos de las mujeres fueron sacrificados por unos cuantos votos\u201d, indicaron.<\/p>","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n Aborto Libre Puerto Rico conden\u00f3 esta tarde la decisi\u00f3n de la gobernadora Jenniffer Gonz\u00e1lez de convertir en ley el Proyecto del Senado 504, otorgando personalidad jur\u00eddica al cigoto, embri\u00f3n o feto.&nbsp; Esta ley, seg\u00fan denunci\u00f3 Aborto Libre Puerto Rico en declaraciones escritas, suspende la autonom\u00eda y emancipaci\u00f3n de las mujeres y personas gestantes, [&hellip;]<\/p>","protected":false},"author":100,"featured_media":292107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3],"tags":[3222,153,186],"class_list":["post-969495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","tag-aborto-libre","tag-gobernadora","tag-jenniffer-gonzalez"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/969495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=969495"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/969495\/revisions"}],"predecessor-version":[{"id":969496,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/969495\/revisions\/969496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/292107"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=969495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=969495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=969495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}