{"id":968485,"date":"2025-12-15T15:00:56","date_gmt":"2025-12-15T19:00:56","guid":{"rendered":"https:\/\/noticel.com\/?p=968485"},"modified":"2025-12-15T15:09:24","modified_gmt":"2025-12-15T19:09:24","slug":"identifican-a-las-victimas-de-un-doble-asesinato-en-toa-baja","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/policiacas\/20251215\/identifican-a-las-victimas-de-un-doble-asesinato-en-toa-baja\/","title":{"rendered":"Identifican a las v\u00edctimas de un doble asesinato en Toa Baja"},"content":{"rendered":"<p>La Polic\u00eda inform\u00f3 sobre la identificaci\u00f3n de las v\u00edctimas de un doble asesinato reportado la noche del domingo en la calle Dolores de la urbanizaci\u00f3n Villa Marisol en el sector Levittown en Toa Baja.<\/p>\n\n\n\n<p>Seg\u00fan informaron las autoridades, una llamada al Sistema de Emergencias 9-1-1 alert\u00f3 sobre disparos y, al llegar los agentes a la escena, encontraron un veh\u00edculo Toyota Corolla con los cuerpos de dos hombres con m\u00faltiples heridas de bala.<\/p>\n\n\n\n<p>La Polic\u00eda precis\u00f3 que los occisos fueron identificados como Joshua Alexis Garc\u00eda V\u00e9lez, de 23 a\u00f1os, y Diangelo Centeno Mart\u00ednez, de 22 a\u00f1os, ambos residentes de Guaynabo. En la escena se ocuparon varios casquillos de bala como parte de la investigaci\u00f3n.<\/p>\n\n\n\n<p>Seg\u00fan detalla el parte polic\u00edaco, la agente Ashley Trinidad, bajo la supervisi\u00f3n del sargento Jes\u00fas Alicea, ambos adscritos a la Divisi\u00f3n de Homicidios del Cuerpo de Investigaciones Criminales (CIC) de Bayam\u00f3n, junto a la fiscal Isabel Lafontaine, se hicieron cargo de la pesquisa.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda inform\u00f3 sobre la identificaci\u00f3n de las v\u00edctimas de un doble asesinato reportado la noche del domingo en la calle Dolores de la urbanizaci\u00f3n Villa Marisol en el sector Levittown en Toa Baja. Seg\u00fan informaron las autoridades, una llamada al Sistema de Emergencias 9-1-1 alert\u00f3 sobre disparos y, al llegar los agentes a la [&hellip;]<\/p>","protected":false},"author":100,"featured_media":968486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[15],"tags":[1511],"class_list":["post-968485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiacas","tag-toa-baja"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/968485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=968485"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/968485\/revisions"}],"predecessor-version":[{"id":968489,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/968485\/revisions\/968489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/968486"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=968485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=968485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=968485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}