{"id":96792,"date":"2017-03-01T20:28:00","date_gmt":"2017-03-02T00:28:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20170301\/enmiendan-ley-para-que-jefes-de-9-1-1-y-emergencias-medicas-tengan-vehiculo\/"},"modified":"2025-07-15T10:17:24","modified_gmt":"2025-07-15T10:17:24","slug":"enmiendan-ley-para-que-jefes-de-9-1-1-y-emergencias-medicas-tengan-vehiculo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20170301\/enmiendan-ley-para-que-jefes-de-9-1-1-y-emergencias-medicas-tengan-vehiculo\/","title":{"rendered":"Enmiendan ley para que jefes de 9-1-1 y Emergencias M\u00e9dicas tengan veh\u00edculo"},"content":{"rendered":"<p>La C\u00e1mara de Representantes aprob\u00f3 el miercoles legislaci\u00f3n para enmendar la &#8216;Ley Uniforme de Veh\u00edculos Oficiales del Gobierno de Puerto Rico&#8217;, a los fines de exceptuar de sus disposiciones a los directores ejecutivos del Cuerpo De Emergencias Medicas y al de la Junta de Gobierno del Servicio 9-1-1.<\/p>\n<p>El Proyecto de la C\u00e1mara 786, de la autor\u00eda del l\u00edder cameral y del representante Carlos Bianchi Angler\u00f3, tiene como objetivo que estos dos funcionarios tengan disponibles un veh\u00edculo las 24 horas del d\u00eda, debido a las funciones de alto inter\u00e9s p\u00fablico que ejercen, que los obligan a movilizarse a trav\u00e9s de toda la isla.<\/p>\n<p>En el caso del director ejecutivo del Cuerpo de Emergencias M\u00e9dicas, este tiene que realizar investigaciones para determinar la causa de origen de las emergencias, as\u00ed como preparar los informes correspondientes y asesorar en la confecci\u00f3n de planes de emergencia a quienes as\u00ed lo soliciten.<\/p>\n<p>Mientras, que el director ejecutivo de la Junta de Gobierno del Servicio 9-1-1 tiene a su cargo el establecimiento y coordinaci\u00f3n de los trabajos dentro de las agencias de Seguridad P\u00fablica para atender r\u00e1pida y eficazmente las llamadas de emergencia de la ciudadan\u00eda. Adem\u00e1s, facilita la integraci\u00f3n de los servicios municipales de emergencias compatibles con los servicios estatales.<\/p>\n<p>Por otra parte, se le dio paso a la Resoluci\u00f3n Concurrente de la C\u00e1mara 15, del representante Jos\u00e9 Aponte Hern\u00e1ndez, para exigir al Congreso de los Estados Unidos de Am\u00e9rica igualdad de fondos Medicaid para Puerto Rico para poder cumplir con los requisitos de la ley federal &#8216;Individuals with Disabilities Education Improvement Act&#8217; (IDEA) al proveer servicios a estudiantes con discapacidades.<\/p><div class=\"notic-content-middle\" id=\"notic-3008847997\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La Exposici\u00f3n de Motivos de la pieza indica que &#8216;la falta de paridad de fondos para el programa estatal de Medicaid pone a Puerto Rico en desventaja para poder cumplir con las condiciones federales del programa de educaci\u00f3n especial y conlleva lacerar el presupuesto de dicho programa asumiendo costos que corresponden al programa Medicaid&#8217;.<\/p>\n<p>Sostiene, que en los momentos en que la econom\u00eda de la isla enfrenta la crisis fiscal m\u00e1s grande de la historia, el incremento de los fondos bajo el referido programa, se hace imprescindible para contar con los recursos econ\u00f3micos y poder cumplir con las condiciones y los servicios requeridos por los ni\u00f1os con discapacidades.<\/p>\n<p>Tambi\u00e9n se aprob\u00f3 el Proyecto de la C\u00e1mara 284, del representante Jorge Navarro Su\u00e1rez, para enmendar la Ley que crea &#8216;Registro Contratistas&#8217;, adscrito a la Oficina de Construcci\u00f3n, del Departamento de Asuntos del Consumidor, a los fines de que la agencia mantenga un registro accesible en sus oficinas al p\u00fablico al p\u00fablico y que adem\u00e1s publique en su p\u00e1gina de internet la informaci\u00f3n relativa a querellas que se generen en contra de contratistas por raz\u00f3n de incumplimiento o trabajo que resulte defectuoso, siempre y cuando las determinaciones del Departamento sean finales y firmes.<\/p>\n<p>Igualmente se favorecieron dos resoluciones de investigaci\u00f3n, Resoluci\u00f3n de la C\u00e1mara 108 y Resoluci\u00f3n de la C\u00e1mara 169 de los representantes Pedro Santiago Guzm\u00e1n y Guillermo Miranda Rivera, para evaluar el cumplimiento y efectividad por parte del Departamento de Educaci\u00f3n en temas tales como la deserci\u00f3n escolar y la integraci\u00f3n de diversos recursos a la comunidad escolar.<\/p>","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Representantes aprob\u00f3 el miercoles legislaci\u00f3n para enmendar la &#8216;Ley Uniforme de Veh\u00edculos Oficiales del Gobierno de Puerto Rico&#8217;, a los fines de exceptuar de sus disposiciones a los directores ejecutivos del Cuerpo De Emergencias Medicas y al de la Junta de Gobierno del Servicio 9-1-1. El Proyecto de la C\u00e1mara 786, de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":326676,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-96792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=96792"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96792\/revisions"}],"predecessor-version":[{"id":326679,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96792\/revisions\/326679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/326676"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=96792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=96792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=96792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}