{"id":96481,"date":"2014-03-03T19:45:58","date_gmt":"2014-03-03T23:45:58","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/credito-de-pr\/economia\/20140303\/spt-y-ugt-senalan-a-los-culpables-de-la-crisis-economica\/"},"modified":"2025-07-15T10:44:22","modified_gmt":"2025-07-15T10:44:22","slug":"spt-y-ugt-senalan-a-los-culpables-de-la-crisis-economica","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140303\/spt-y-ugt-senalan-a-los-culpables-de-la-crisis-economica\/","title":{"rendered":"SPT y UGT se\u00f1alan a los culpables de la crisis econ\u00f3mica"},"content":{"rendered":"<p>El Sindicato Puertorrique\u00f1o de Trabajadores (SPT) y la Uni\u00f3n General de Trabajadores (UGT) se\u00f1alaron a los inversionistas de Wall Street, las casas de corretaje como UBS, los intermediarios y administradores de las emisiones de bonos, e incluso a la banca local, como los responsables de la actual crisis econ\u00f3mica.<\/p>\n<p>Para los trabajadores, Puerto Rico ha sido empujado a un ciclo vicioso donde se deteriora la econom\u00eda, los inversionistas de Wall Street otorgan pr\u00e9stamos a muy altos intereses para &#8216;solucionar los problemas&#8217; que generan un endeudamiento insostenible, requiriendo que el estado vuelva a tomar prestado para pagar la deuda. Al final los prestamistas y sus intermediarios hacen ganancias multimillonarias, mientras se contin\u00faa el c\u00edrculo vicioso que alentaron las agencias acreditadoras de tomar prestado m\u00e1s all\u00e1 de la capacidad de repago.<\/p>\n<p>Todo ello ha empeorado las condiciones para que el gobierno pueda implantar un plan de recuperaci\u00f3n.<\/p>\n<p>Seg\u00fan expresaran las uniones en comunicaci\u00f3n escrita, la banca inversionista de Wall Street se ceba con el pago de los intereses de la deuda de sobre $70 mil millones e impone condiciones usureras a los nuevos pr\u00e9stamos.<\/p>\n<p>Asimismo, culparon a los ejecutivos de UBS y otras casas de corretaje, que propusieron y estructuraron las transacciones que han arruinado los sistemas de retiro.<\/p>\n<p>La banca local tambi\u00e9n se llev\u00f3 su agua, ya que en medio de la m\u00e1s profunda crisis econ\u00f3mica declara que est\u00e1 en su momento m\u00e1s s\u00f3lido de los \u00faltimos diez a\u00f1os.<\/p>\n<p>Por otro lado, las organizaciones sindicales alertaron sobre la profundizaci\u00f3n del endeudamiento que traer\u00eda la millonaria emisi\u00f3n de bonos, indicando que las medidas para atajar la crisis no deben seguir abriendo la brecha de desigualdad socioecon\u00f3mica que se vive en el pa\u00eds.<\/p>\n<p>Tambi\u00e9n denunciaron el manejo irresponsable de los fondos p\u00fablicos por los gobiernos de turno, as\u00ed como su incapacidad para desarrollar un modelo econ\u00f3mico que aumente los ingresos gubernamentales y active el flujo de capital local. Incluso, reclamaron que se fijen responsabilidades a los que desde el gobierno no cumplieron con proteger los fondos p\u00fablicos del pueblo.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Sindicato Puertorrique\u00f1o de Trabajadores (SPT) y la Uni\u00f3n General de Trabajadores (UGT) se\u00f1alaron a los inversionistas de Wall Street, las casas de corretaje como UBS, los intermediarios y administradores de las emisiones de bonos, e incluso a la banca local, como los responsables de la actual crisis econ\u00f3mica. Para los trabajadores, Puerto Rico ha [&hellip;]<\/p>","protected":false},"author":0,"featured_media":328548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,2],"tags":[],"class_list":["post-96481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=96481"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96481\/revisions"}],"predecessor-version":[{"id":328550,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96481\/revisions\/328550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/328548"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=96481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=96481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=96481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}