{"id":96370,"date":"2018-06-21T13:55:17","date_gmt":"2018-06-21T17:55:17","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/deportes-cool\/20180621\/el-tico-que-supero-kilometros-y-fronteras-para-ir-a-rusia\/"},"modified":"2025-07-15T10:54:06","modified_gmt":"2025-07-15T10:54:06","slug":"el-tico-que-supero-kilometros-y-fronteras-para-ir-a-rusia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20180621\/el-tico-que-supero-kilometros-y-fronteras-para-ir-a-rusia\/","title":{"rendered":"El tico que super\u00f3 kil\u00f3metros y fronteras para ir a Rusia"},"content":{"rendered":"<p><i>En apoyo a la selecci\u00f3n de f\u00fatbol costarricense<\/i><\/p>\n<p>Hay pasiones que llevan muy lejos. La del tico Marco Luis Benavides en la selecci\u00f3n de Costa Rica le ha llevado a devorar 3,500 kil\u00f3metros en bicicleta durante 40 d\u00edas para llegar a San Petersburgo y animar a la &#8216;Sele&#8217; en el trascendental duelo de ma\u00f1ana contra Brasil.<\/p>\n<p>De cuerpo menudo, de puro ciclista, facciones cansadas pero el \u00e1nimo intacto para superar siete fronteras desde Londres a San Petersburgo a sus 58 a\u00f1os, este hincha &#8216;tico&#8217; conversa con EFE en la &#8216;Venecia del norte&#8217; rusa sobre c\u00f3mo fue su recorrido, a menos de 24 horas de un partido para el que, reconoce, no ha conseguido entrada.<\/p>\n<p>Con su inseparable bicicleta, que se llev\u00f3 de su Esparza (en la costa oeste de Costa Rica) a Londres en avi\u00f3n, emprendi\u00f3 el viaje cruzando el t\u00fanel del Canal de La Mancha a golpe de pedal, para un trayecto que no iba a ser sencillo por los problemas de los visados.<\/p>\n<p>&#8216;Iba a ir por Bielorrusia, pero no ten\u00eda visado, as\u00ed que fui por Holanda, Alemania, Polonia, Letonia, Lituania y Estonia&#8217;, explica Marco, m\u00e1s conocido como &#8216;Makey&#8217;.<\/p>\n<p>Un trayecto no exento de dificultades, ya que este esforzado hincha tico tuvo que pasar 15 d\u00edas en la frontera entre el pa\u00eds b\u00e1ltico y Rusia porque no ten\u00eda visado ni entrada, que le hubiera permitido conseguir el pase FAN ID con el que la FIFA y el estado ruso han permitido cruzar la frontera a los asistentes al Mundial.<\/p>\n<p>&#8216;Una argentina y un mexicano me regalaron el n\u00famero de una entrada para que pudiera sacar el FAN ID para entrar a Rusia. Estuve entre Estonia y Rusia unos 15 d\u00edas, pase situaciones complicadas, dormir en cementerios, cosas as\u00ed&#8217;, recuerda Marco.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"756542849\" embed-content-groupid=\"593030471\" embed-content-id=\"756542849\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2018\/06\/21\/Benavides%20no%20tiene%20entrada%20para%20el%20partido%20_1529603858787.jpg_12004231_ver1.0_640_360.jpg\" style=\"width:100%;\"\/><\/p>\n<p>No obstante, no es la primera aventura de este tipo para este exciclista, con cuatro decadas de carretera y manillar a sus espaldas, que incluso lleg\u00f3 a correr pruebas deportivas centroamericanas.<\/p>\n<p>&#8216;Soy un viejo lobo de mar, llevo 40 a\u00f1os corriendo en bicicleta. Hice la Vuelta a Costa Rica, Panam\u00e1, Nicaragua&#8230; Son muchos a\u00f1os de andar en bicicleta&#8217;, se\u00f1ala.<\/p><div class=\"notic-content-middle\" id=\"notic-1951139843\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>De hecho, al Mundial de Brasil 2014, en el que su Costa Rica fue la autentica sorpresa del torneo superando un &#8216;grupo de la muerte&#8217; con tres campeonas mundiales (Uruguay, Inglaterra e Italia), lleg\u00f3 pedaleando desde su Esparza natal.<\/p>\n<p>&#8216;Cuando llegue a Brasil, econ\u00f3micamente iba muy mal, pero la gente de Costa Rica me ayud\u00f3 mucho. Vi varios partidos gracias a la ayuda de la gente: Costa Rica contra Uruguay, contra Italia y un alem\u00e1n me regal\u00f3 un ticket para el Alemania-Ghana&#8217;, recuerda.<\/p>\n<p>A Marco se le humedecen los ojos cuando se acuerda del apoyo de quienes le ayudaron a completar su empresa, y reconoce que a menos de 24 horas de que Brasil y Costa Rica se jueguen su futuro en Rusia 2018, no tiene entrada para asistir al duelo del San Petersburg Stadium.<\/p>\n<p>&#8216;No tengo entrada para el partido contra Brasil, a ver si hay suerte y me la prestan&#8217;, manifiesta un Marco que, ante todo es &#8216;positivo&#8217; sobre las posibilidades de la escuadra de \u00d3scar &#8216;Macho&#8217; Ram\u00edrez para derrotar a la &#8216;canarinha&#8217;.<\/p>\n<p>&#8216;Pienso que s\u00ed va a ganar y va a pasar a octavos. Los &#8216;ticos&#8217; cuando hay que sacar la casta la sacamos, esa es la fe que tengo&#8217;, asegura este &#8216;tico&#8217; cuyo \u00eddolo es el arquero del Real Madrid Keylor Navas.<\/p>\n<p>Como el guardameta de la &#8216;Sele&#8217;, Marco &#8216;Makey&#8217; Benavides se mueve por la fe. La que le dice que ma\u00f1ana Costa Rica derrotar\u00e1 a la pentacampeona Brasil por primera vez en su historia en los Mundiales.<\/p>\n<p>Esa misma fe le inspira a intentar su aventura en los pr\u00f3ximos dos Mundiales: Catar 2022 y el recientemente elegido de 2026 que organizar\u00e1n Canad\u00e1, Estados Unidos y Mexico.<\/p>\n<p>&#8216;Si Dios lo permite y me presta salud, mi idea es ir al pr\u00f3ximo mundial de Catar y al de Mexico. Quiero implantar un record en bicicleta, uno de los pocos del mundo que haya ido a tantos Mundiales en bicicleta&#8217;, finaliza Marco Benavides, el &#8216;tico&#8217; que devor\u00f3 kil\u00f3metros y adversidades para llegar al Mundial de Rusia.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"756542860\" embed-content-groupid=\"593030471\" embed-content-id=\"756542860\" embed-content-imgalign=\"none\" embed-content-index=\"0\" embed-content-location=\"input_story-body\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2018\/06\/21\/Un%20trayecto%20no%20exento%20de%20dificultades%20para%20el%20hincha%20tico_1529603859001.jpg_12004233_ver1.0_640_360.jpg\" style=\"width:100%;\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>En apoyo a la selecci\u00f3n de f\u00fatbol costarricense Hay pasiones que llevan muy lejos. La del tico Marco Luis Benavides en la selecci\u00f3n de Costa Rica le ha llevado a devorar 3,500 kil\u00f3metros en bicicleta durante 40 d\u00edas para llegar a San Petersburgo y animar a la &#8216;Sele&#8217; en el trascendental duelo de ma\u00f1ana contra [&hellip;]<\/p>","protected":false},"author":0,"featured_media":329220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-96370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=96370"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96370\/revisions"}],"predecessor-version":[{"id":329222,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/96370\/revisions\/329222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/329220"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=96370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=96370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=96370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}