{"id":961609,"date":"2025-11-14T09:21:48","date_gmt":"2025-11-14T13:21:48","guid":{"rendered":"https:\/\/noticel.com\/?p=961609"},"modified":"2025-11-14T09:31:04","modified_gmt":"2025-11-14T13:31:04","slug":"plata-agonica-para-mariecarmen-rivera-en-la-final-del-isa-world-sup-paddleboard-championship","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20251114\/plata-agonica-para-mariecarmen-rivera-en-la-final-del-isa-world-sup-paddleboard-championship\/","title":{"rendered":"Plata ag\u00f3nica para Mariecarmen Rivera en la final del ISA World SUP &amp; Paddleboard Championship"},"content":{"rendered":"<p>La tricampeona mundial Mariecarmen Rivera volvi\u00f3 a demostrar su grandeza en el escenario internacional al conquistar la medalla de plata en la final de larga distancia del ISA World SUP &amp; Paddleboard Championship 2025, en una carrera que se decidi\u00f3 por una cent\u00e9sima de segundo y que mantuvo en vilo a todo Puerto Rico hasta la l\u00ednea de llegada.<\/p>\n\n\n\n<p>La final fue una verdadera batalla f\u00edsica y mental. En los \u00faltimos metros, ya sin tabla y corriendo hacia la meta en la arena, Rivera protagoniz\u00f3 un cierre electrizante que desat\u00f3 emoci\u00f3n en El Sunzal y dej\u00f3 en evidencia su esp\u00edritu combativo.<\/p>\n\n\n\n<p>La argentina Juliete Duhaume se llev\u00f3 el oro con 20:08, mientras que Mariecarmen cruz\u00f3 la meta en 20:09, dejando todo en el tramo final. El bronce fue para la espa\u00f1ola Duna Gordillo, con tiempo de 20:29.<\/p>\n\n\n\n<p>Antes de su dram\u00e1tico desenlace, Rivera hab\u00eda dominado las semifinales al ganar el Heat 2 con un s\u00f3lido tiempo de 15:05, clasificando a la final como una de las favoritas.<\/p>\n\n\n\n<p>Este resultado contin\u00faa la impresionante racha competitiva de la puertorrique\u00f1a. En octubre, Rivera hizo historia al convertirse en la primera atleta en ganar tres t\u00edtulos mundiales en una misma edici\u00f3n del ICF Stand Up Paddling World Championships, al conquistar las pruebas de Sprint, Technical Race y Long Distance, dejando un precedente hist\u00f3rico para Puerto Rico y para el SUP internacional. La presidenta del Comit\u00e9 Ol\u00edmpico de Puerto Rico, Sara Rosario V\u00e9lez, resalt\u00f3 la valent\u00eda y consistencia de Rivera. \u201cLo que hizo Mariecarmen hoy es una demostraci\u00f3n de entrega absoluta. Competir al m\u00e1s alto nivel, cerrar con ese coraz\u00f3n y quedar a un segundo del oro habla de su grandeza. Puerto Rico est\u00e1 orgulloso de su disciplina, su temple y todo lo que contin\u00faa aportando al deporte mundial\u201d, expres\u00f3 Rosario V\u00e9lez.<\/p>","protected":false},"excerpt":{"rendered":"<p>La boricua lleg\u00f3 segunda por una diferencia de una cent\u00e9sima de segundo. Foto suministrada.<\/p>","protected":false},"author":100,"featured_media":961610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[2438,2454,2674],"class_list":["post-961609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-copur","tag-mariecarmen-rivera","tag-medalla-de-plata"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/961609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=961609"}],"version-history":[{"count":3,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/961609\/revisions"}],"predecessor-version":[{"id":961615,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/961609\/revisions\/961615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/961610"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=961609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=961609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=961609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}