{"id":95500,"date":"2014-06-02T09:53:17","date_gmt":"2014-06-02T13:53:17","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20140602\/tailandia-planea-crear-sus-propios-servidores-para-controlar-mejor-internet\/"},"modified":"2025-07-15T12:11:44","modified_gmt":"2025-07-15T12:11:44","slug":"tailandia-planea-crear-sus-propios-servidores-para-controlar-mejor-internet","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20140602\/tailandia-planea-crear-sus-propios-servidores-para-controlar-mejor-internet\/","title":{"rendered":"Tailandia planea crear sus propios servidores para controlar mejor Internet"},"content":{"rendered":"<p>La junta militar de Tailandia planea crear sus propios servidores de Internet para controlar de forma m\u00e1s eficiente el contenido en las redes sociales y las p\u00e1ginas web, informaron hoy los medios locales.<\/p>\n<p>Surachai Srisarakam, secretario permanente del Ministerio de Tecnolog\u00eda e Informaci\u00f3n, afirm\u00f3 que el plan incluye la creaci\u00f3n de la Red Social de Tailandia, un servicio parecido a Facebook pero controlado por las autoridades locales.<\/p>\n<p>Seg\u00fan el plan, los proveedores de servicios de Internet (ISP) privados tendr\u00edan que contratar la conexi\u00f3n en el pa\u00eds a trav\u00e9s del ISP de propiedad estatal, lo que facilitar\u00eda la censura y el bloqueo de paginas web, seg\u00fan el diario &#8216;Matichon&#8217;.<\/p>\n<p>Surachai afirm\u00f3 que el proyecto, que puede estar terminado en dos meses, servir\u00eda para luchar contra delitos en la red y que ahorrar\u00eda a Tailandia el dinero que ahora paga a servidores extranjeros.<\/p>\n<p>La junta militar ha censurado cientos de p\u00e1ginas cr\u00edticas con el r\u00e9gimen en Internet, aunque redes sociales como Facebook, Twitter y Line no se han visto afectadas.<\/p>\n<p>El Ej\u00e9rcito se hizo con el poder el pasado 22 de mayo tras m\u00e1s de siete meses de protestas antigubernamentales en las que murieron 28 personas y m\u00e1s de 700 resultaron heridas.<\/p>\n<p>La junta militar ha asegurado que quisieron evitar una escalada de violencia entre manifestantes rivales y que su plan es celebrar elecciones en 2015, si consigue finalizar para entonces su plan de reformas del sistema, que considera corrompido.<\/p>\n<p>Tailandia ha padecido 19 pronunciamientos militares, de los que 12 culminaron en golpe de Estado, desde el fin de la monarqu\u00eda absolutista en 1932.<\/p>","protected":false},"excerpt":{"rendered":"<p>La junta militar de Tailandia planea crear sus propios servidores de Internet para controlar de forma m\u00e1s eficiente el contenido en las redes sociales y las p\u00e1ginas web, informaron hoy los medios locales. Surachai Srisarakam, secretario permanente del Ministerio de Tecnolog\u00eda e Informaci\u00f3n, afirm\u00f3 que el plan incluye la creaci\u00f3n de la Red Social de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":335009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-95500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/95500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=95500"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/95500\/revisions"}],"predecessor-version":[{"id":335010,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/95500\/revisions\/335010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/335009"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=95500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=95500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=95500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}