{"id":95067,"date":"2012-07-01T20:00:00","date_gmt":"2012-07-02T00:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20120701\/felicitacion-futbolera-de-sting-en-ibiza\/"},"modified":"2025-07-15T12:45:38","modified_gmt":"2025-07-15T12:45:38","slug":"felicitacion-futbolera-de-sting-en-ibiza","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20120701\/felicitacion-futbolera-de-sting-en-ibiza\/","title":{"rendered":"Felicitaci\u00f3n futbolera de Sting en Ibiza"},"content":{"rendered":"<p>Sant Antoni (Ibiza) &#8211; Uno a uno, Sting ha repasado hoy sus cl\u00e1sicos y los de su m\u00edtica Police en el esperado primer concierto estrella del Bacard\u00ed Ibiza123, haciendo vibrar a un p\u00fablico emocionado tras la victoria de Espa\u00f1a en la Eurocopa que se ha podido ver en directo en las pantallas gigantes del festival.<\/p>\n<p>&#8216;Viva Espa\u00f1a&#8217;, han sido las primeras palabras del cantante brit\u00e1nico al salir al escenario ubicado junto al famoso Caf\u00e9 del Mar, despu\u00e9s de haber accedido a posponer su concierto para contentar a los seguidores de la selecci\u00f3n espa\u00f1ola.<\/p>\n<p>Los asistentes a la que pretende ser la mayor cita musical del a\u00f1o en la isla han disfrutado de noventa minutos de partido y de otros noventa del concierto de una de las figuras m\u00e1s emblem\u00e1ticas del rock de las \u00faltimas d\u00e9cadas, que ha comenzado su actuaci\u00f3n, como si la fe futbolera describiera, con su tema &#8216;If I ever loose my faith in you&#8217;.<\/p>\n<p>&#8216;Enhorabuena Espa\u00f1a&#8217;, &#8216;campeones&#8217; y &#8216;felicidades&#8217; han sido algunas de las palabras de Sting dedicadas a la victoria espa\u00f1ola, y hasta ha hecho corear el &#8216;oe, oe, oe, oe&#8217; a los miles de asistentes a la cita musical de Sant Antoni de Pormany.<\/p>\n<p>El ingl\u00e9s no solo ha recordado sus cl\u00e1sicos en solitario, sino que ha repasado con su banda los \u00e9xitos de Police, provocando el delirio con &#8216;Every little thing she does is magic&#8217; como segundo tema de la noche.<\/p>\n<p>Con el p\u00fablico en el bolsillo, el ganador de diecis\u00e9is premios Grammy ha emocionado luego a las gradas con la balada &#8216;Englishman in New York&#8217; y hecho sacar los mecheros al ritmo de los acordes de &#8216;Fields of gold&#8217;.<\/p>\n<p>Acompa\u00f1ado de guitarra el\u00e9ctrica, bater\u00eda, teclados, coros y un multiinstrumentista viol\u00edn, guitarra y percusi\u00f3n, Sting no se ha olvidado de otros grandes temas de la banda ochentera que le debe la fama, como &#8216;Message in a bottle&#8217; y un &#8216;Roxanne&#8217; de siete minutos en el que ha hecho valer el virtuosismo de su voz.<\/p><div class=\"notic-content-middle\" id=\"notic-3110999142\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>El cantante y compositor ha salido hasta dos veces al escenario para interpretar sendos bises, que ha coronado con los sonidos \u00e1rabes de &#8216;Desert Rose&#8217; y &#8216;Every breath you take&#8217; hasta completar los 17 temas de su actuaci\u00f3n.<\/p>\n<p>Sus 60 a\u00f1os no han hecho mella en la voz clara e inconfundible de Sting, ni tampoco en su energ\u00eda vital, que ha desplegado en un escenario de lujo acompa\u00f1ado de una luna casi llena y con el mar Mediterr\u00e1neo de fondo.<\/p>\n<p>Con un sonido impecable y m\u00fasicos de lujo, esta ha sido la \u00fanica cita espa\u00f1ola de la gira veraniega del m\u00fasico brit\u00e1nico con la que conmemora sus 25 a\u00f1os de carrera, despu\u00e9s de que cancelara su concierto en Canarias por problemas de presupuesto.<\/p>\n<p>Al broche de la primera jornada del festival ibicenco, que quiere auparse como el fundador del &#8216;rocktronic&#8217;, la fusi\u00f3n entre el rock y la m\u00fasica electr\u00f3nica, ha seguido la sesi\u00f3n del popular David Guetta, que ha cogido un p\u00fablico caliente y \u00e1vido de bailar al ritmo de sus bases.<\/p>\n<p>Ma\u00f1ana, el experimento se har\u00e1 realidad de mano de su compatriota Elton John, que presentar\u00e1 en primicia un nuevo \u00e1lbum de m\u00fasica dance, &#8216;Turn around and say good morning to the light&#8217;, junto al d\u00fao australiano DJ Pnau, al que le seguir\u00e1 la actuaci\u00f3n de Fatboy Slim.<\/p>\n<p>El tercer y \u00faltimo d\u00eda tambi\u00e9n ser\u00e1 testigo del &#8216;rocktronic&#8217;, esta vez de la mano de Lenny Kravitz y Luciano, quienes compartir\u00e1n escenario para fusionar funk-rock y sonidos electr\u00f3nicos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sant Antoni (Ibiza) &#8211; Uno a uno, Sting ha repasado hoy sus cl\u00e1sicos y los de su m\u00edtica Police en el esperado primer concierto estrella del Bacard\u00ed Ibiza123, haciendo vibrar a un p\u00fablico emocionado tras la victoria de Espa\u00f1a en la Eurocopa que se ha podido ver en directo en las pantallas gigantes del festival. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":337707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-95067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/95067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=95067"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/95067\/revisions"}],"predecessor-version":[{"id":337709,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/95067\/revisions\/337709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/337707"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=95067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=95067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=95067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}