{"id":92711,"date":"2011-08-09T16:50:00","date_gmt":"2011-08-09T20:50:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20110809\/londres-arde-la-experiencia-de-un-boricua-video\/"},"modified":"2025-07-15T15:38:49","modified_gmt":"2025-07-15T15:38:49","slug":"londres-arde-la-experiencia-de-un-boricua-video","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20110809\/londres-arde-la-experiencia-de-un-boricua-video\/","title":{"rendered":"Londres arde!, la experiencia de un boricua (v\u00eddeo)"},"content":{"rendered":"<p>Ayer me fui a beber una cerveza con un amigo ingl\u00e9s en Bermondsey Street, Londres. Era una tarde serena con un encuentro rutinario de dos panas para contarse historias y chistes por un rato. En la calle, nadie. \u00c9l llevaba todo el d\u00eda trabajando en Richmond, a las afueras de la ciudad, y yo enclaustrado estudiando, as\u00ed que no nos imagin\u00e1bamos el infierno que caldeaba a nuestro alrededor. Eran las siete de la noche, en la v\u00edspera de una noche tenebrosa.<\/p>\n<p>Ya ca\u00eddo el sol en el apartamento junto a London Bridge, al centro-sur de la ciudad, comenc\u00e9 a escuchar sirenas polic\u00edacas y helic\u00f3pteros en la distancia. Entro a Twitter y #LondonRiots es la palabra m\u00e1s repetida en la ciudad de Londres. Cada segundo sale un nuevo tweet. Entre fotos de carros, casas y edificios en fuego, algunos atemorizados preguntaban si los revoltosos se hab\u00edan movido a sus vecindarios.<\/p><div class=\"notic-content-middle\" id=\"notic-2168587576\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Ya se escuchaban reportes de vandalismo y fuego en Oxford Circus (el Times Square), Chelsea (como el Condado y Miramar), Camden (antiguo vecindario de la fenecida Amy Winehouse), Clapham, Brixton, Ealing y South Bermondsey (cerca de m\u00ed). Alguien comparti\u00f3 un <a href=\"http:\/\/maps.google.co.uk\/maps\/ms?ie=UTF8&amp;oe=UTF8msa=0&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt; &lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt; &lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;&lt;&gt;msid=207192798388318292131.0004aa01af6748773e8f7%29\" target=\"_blank\" mapa=\"\" de=\"\" la=\"\" ciudad=\"\" con=\"\" los=\"\" lugares=\"\" donde=\"\" se=\"\" hab=\"\" reportado=\"\" disturbios=\"\" y=\"\" al=\"\" momento=\"\" escribir=\"\" esta=\"\" nota=\"\" cont=\"\" m=\"\" cuarenta=\"\" sitios=\"\" afectados=\"\" en=\"\" las=\"\" zonas=\"\" c=\"\" ciudad.=\"\" esto=\"\" no=\"\" incluye=\"\" afueras=\"\" ni=\"\" otras=\"\" ciudades=\"\" como=\"\" birmingham=\"\" liverpool=\"\" a=\"\" esparci=\"\" revuelta.=\"\" pmientras=\"\" tanto=\"\" otros=\"\" tuiteros=\"\" apoyo=\"\" o=\"\" cinismo=\"\" cantaban=\"\" famosa=\"\" tenebrosa=\"\" canci=\"\" cuna=\"\" bridge=\"\" is=\"\" falling=\"\" down=\"\" down...=\"\" muchos=\"\" que=\"\" estaban=\"\" el=\"\" meollo=\"\" publicaron=\"\" fotos=\"\" sus=\"\" haza=\"\" junto=\"\" soberbios=\"\" mensajes=\"\" desaf=\"\" autoridades.=\"\" todo=\"\" era=\"\" confusi=\"\" pqu=\"\" es=\"\" fue=\"\" mi=\"\" primera=\"\" reacci=\"\" ir=\"\" nada=\"\" pasaba=\"\" puente=\"\" londres=\"\" pero=\"\" resto=\"\" ard=\"\" llamas.=\"\" miles=\"\" polic=\"\" intentaban=\"\" contrarrestar=\"\" sublevaci=\"\" cuantos=\"\" revoltosos=\"\" qui=\"\" desde=\"\" s=\"\" pasado=\"\" llevan=\"\" aterrorizando=\"\" ciudadan=\"\" ptodo=\"\" por=\"\" sospechosa=\"\" muerte=\"\" mark=\"\" duggan=\"\" para=\"\" un=\"\" maleante=\"\" fundador=\"\" una=\"\" ganga=\"\" conocidos=\"\" padre=\"\" familia.=\"\" decenas=\"\" personas=\"\" congregaron=\"\" frente=\"\" comisar=\"\" tottenham=\"\" norte=\"\" lo=\"\" comenz=\"\" protesta=\"\" pac=\"\" convirti=\"\" pandemonium=\"\" di=\"\" paso=\"\" violencia=\"\" generalizada.=\"\" patrullas=\"\" apedreadas=\"\" edificios=\"\" enteros=\"\" incendiados=\"\" uno=\"\" dos=\"\" sino=\"\" propiedades=\"\" vandalizadas.=\"\" siente=\"\" si=\"\" fuera=\"\" pel=\"\" pimg=\"\" embed-content-articleid=\"664709430\" embed-content-groupid=\"593030475\" embed-content-id=\"664709430\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2011\/08\/09\/londres_arde_boricua_noticel_9500819_ver1.0_320_240.jpg\" pem=\"\" payer=\"\" lunes=\"\" mientras=\"\" terminaba=\"\" cerveza=\"\" amigo=\"\" nos=\"\" pregunt=\"\" d=\"\" sali=\"\" mayor=\"\" londinenses=\"\" ajenos=\"\" causa=\"\" vecinos=\"\" sectores=\"\" fueron=\"\" hasta=\"\" anoche=\"\" cre=\"\" manifestaciones=\"\" concluidas.=\"\" noche=\"\" prob=\"\" contrario=\"\" registr=\"\" aumento=\"\" delincuencia=\"\" pahora=\"\" ve=\"\" im=\"\" youtube=\"\" atacando=\"\" tiendas=\"\" prop=\"\" robarlas.=\"\" gente=\"\" corr=\"\" carros=\"\" llenos=\"\" televisores=\"\" tostadoras.=\"\" otro=\"\" v=\"\" muchacho=\"\" herido=\"\" sentado=\"\" acera=\"\" ser=\"\" robo=\"\" plena=\"\" luz=\"\" del=\"\" hay=\"\" saltando=\"\" ventanas=\"\" llamas=\"\" reportes=\"\" bandidos=\"\" entrando=\"\" hogares=\"\" robar.=\"\" cund=\"\" p=\"\" nadie=\"\" atrev=\"\" salir=\"\" calle.=\"\" pesar=\"\" fuese=\"\" raro=\"\" ver=\"\" barras=\"\" restaurantes=\"\" media=\"\" cosa=\"\" aconteci=\"\" anoche.=\"\" pocos=\"\" salieron=\"\" calle=\"\" defender=\"\" suficiente=\"\" vac=\"\" quienes=\"\" ten=\"\" intereses.=\"\" pya=\"\" trataba=\"\" contra=\"\" ya=\"\" vacil=\"\" reacciones=\"\" twitter=\"\" medios=\"\" eran=\"\" mixtas.=\"\" rogaban=\"\" cese=\"\" motines=\"\" saqueos=\"\" apoyaban.=\"\" qu=\"\" han=\"\" estado=\"\" preguntando=\"\" mis=\"\" amigos=\"\" aqu=\"\" pla=\"\" verdad=\"\" culminaron=\"\" estudiantiles=\"\" verano=\"\" sentido=\"\" malestar=\"\" social=\"\" manera=\"\" tan=\"\" tele=\"\" blogs=\"\" ha=\"\" quejando=\"\" pasados=\"\" meses=\"\" nunca=\"\" habl=\"\" alguna=\"\" manifestaci=\"\" multitudinaria=\"\" esperaba=\"\" palgunos=\"\" condenan=\"\" gobierno=\"\" recortar=\"\" gastos=\"\" educaci=\"\" servicios=\"\" sociales=\"\" sorpresa=\"\" reyerta=\"\" tomado=\"\" sugiere=\"\" otra=\"\" est=\"\" analizarse=\"\" pues=\"\" cierto=\"\" pa=\"\" pasando=\"\" crisis=\"\" econ=\"\" son=\"\" marginados=\"\" sufrido.=\"\" pmuchos=\"\" criticado=\"\" generalizada=\"\" cuyas=\"\" incluyen=\"\" trevor=\"\" reeves=\"\" due=\"\" muebler=\"\" llevaba=\"\" servicio=\"\" sobrevivi=\"\" guerras=\"\" incendios=\"\" canas=\"\" arrugas=\"\" esculpidas=\"\" preguntaba=\"\" voz=\"\" triste=\"\" desalentada=\"\" phoy=\"\" tranquilo.=\"\" bullicio=\"\" cotidiano=\"\" vida=\"\" normal=\"\" puede=\"\" escuchar=\"\" ventana=\"\" tambi=\"\" veo=\"\" cada=\"\" cinco=\"\" minutos=\"\" varios=\"\" helic=\"\" pasar=\"\" cielos.=\"\" ah=\"\" darle=\"\" van=\"\" estar=\"\" patrullando=\"\" calles=\"\" pr=\"\" horas.=\"\" peste=\"\" seguridad=\"\" logrado=\"\" cientos=\"\" salieran=\"\" ma=\"\" bolsas=\"\" escobas=\"\" quebrar=\"\" robar=\"\" enseres=\"\" limpiar=\"\" recoger=\"\" basura.=\"\" indignados=\"\" sucedido=\"\" salido=\"\" contra-protesta=\"\" voluntarios=\"\" comunitario=\"\" defensa=\"\" comunidades=\"\" destrucci=\"\" masiva.=\"\" tarde=\"\" transe=\"\" ven=\"\" prisa.=\"\" ayer=\"\" negocios=\"\" anunciado=\"\" cierre=\"\" temprano.=\"\" postrada=\"\" esquina=\"\" pedido=\"\" poblaci=\"\" su=\"\" cooperaci=\"\" qued=\"\" casas=\"\" propia=\"\" seguridad.=\"\" sabe=\"\" repetir=\"\" escenas=\"\" catalogadas=\"\" revuelta=\"\" violenta=\"\" memoria=\"\" reciente=\"\" vez=\"\" calmados=\"\" recuperaci=\"\" seguramente=\"\" r=\"\" sigui=\"\" pasadas=\"\" universitarias.=\"\" l=\"\" este=\"\" tendr=\"\" mucho=\"\" ponderar=\"\" solo=\"\" sobre=\"\" reclamos=\"\" dieron=\"\" g=\"\" circunstancias=\"\" permitido=\"\" desborde.=\"\" autor=\"\" estudiante=\"\" puertorrique=\"\" londres.=\"\" direcci=\"\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>Ayer me fui a beber una cerveza con un amigo ingl\u00e9s en Bermondsey Street, Londres. Era una tarde serena con un encuentro rutinario de dos panas para contarse historias y chistes por un rato. En la calle, nadie. \u00c9l llevaba todo el d\u00eda trabajando en Richmond, a las afueras de la ciudad, y yo enclaustrado [&hellip;]<\/p>","protected":false},"author":0,"featured_media":351446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-92711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=92711"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92711\/revisions"}],"predecessor-version":[{"id":351447,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92711\/revisions\/351447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/351446"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=92711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=92711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=92711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}