{"id":92661,"date":"2013-03-15T11:02:18","date_gmt":"2013-03-15T15:02:18","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20130315\/policia-argentina-rescata-jugador-del-river-que-fue-secuestrado\/"},"modified":"2025-07-15T15:43:53","modified_gmt":"2025-07-15T15:43:53","slug":"policia-argentina-rescata-jugador-del-river-que-fue-secuestrado","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20130315\/policia-argentina-rescata-jugador-del-river-que-fue-secuestrado\/","title":{"rendered":"Polic\u00eda argentina rescata jugador del River que fue secuestrado"},"content":{"rendered":"<p>El defensa del River Plate Jonathan Bottinelli fue liberado la noche del jueves por la polic\u00eda tras ser secuestrado por cuatro delincuentes en los alrededores de la capital argentina.<\/p>\n<p>Los ladrones intentaron llevarse a Bottinelli en su propia camioneta cuando aparcaba frente a la casa de un amigo, en la localidad bonaerense de El Palomar, quien le hab\u00eda invitado a cenar.<\/p>\n<p>Fuentes policiales indicaron que los delincuentes no pudieron poner en marcha el veh\u00edculo del futbolista, por lo que le amenazaron con armas de fuego, le subieron a otro coche, y se lo llevaron a toda velocidad.<\/p>\n<p>Dentro del coche le quitaron unos 300 d\u00f3lares que Bottinelli, un anillo de oro y sus tel\u00e9fonos m\u00f3viles.<\/p>\n<p>Un vecino, testigo del hecho, avis\u00f3 a la polic\u00eda, que puso en marcha una inmediata persecuci\u00f3n del coche en el que trasladaban a Bottinelli con destino desconocido, y lograron liberarlo, aunque no pudieron detener a los delincuentes.<\/p>\n<p>El padre del zaguero, Juan Calos Bottinelli, dijo a la prensa que &#8216;los ladrones quisieron llevarlo a su casa y recorrer cajeros autom\u00e1ticos para sacar dinero, pero \u00e9l se neg\u00f3. Fue ah\u00ed cuando recibi\u00f3 algunos golpes&#8217;.<\/p>\n<p>El exdefensa argentino del Zaragoza Fernando C\u00e1ceres fue v\u00edctima de un hecho similar hace tres a\u00f1os tambi\u00e9n en las cercan\u00edas de Buenos Aires, cuando unos ladrones quisieron robarle el coche y le dispararon con armas de fuego en la cabeza, hecho que le tuvo entre la vida y la muerte durante varios meses.<\/p>\n<p>El a\u00f1o pasado, los jugadores del River Plate Daniel &#8216;Keko&#8217; Villalva y Juan Cazares fueron asaltados por tres delincuentes armados cuando sal\u00edan de un entrenamiento.<\/p>\n<p>Estuvieron cautivos durante media hora y les robaron dinero, objetos de valor y el coche en el que viajaban, hasta que fueron liberados ilesos por la polic\u00eda.<\/p>","protected":false},"excerpt":{"rendered":"<p>El defensa del River Plate Jonathan Bottinelli fue liberado la noche del jueves por la polic\u00eda tras ser secuestrado por cuatro delincuentes en los alrededores de la capital argentina. Los ladrones intentaron llevarse a Bottinelli en su propia camioneta cuando aparcaba frente a la casa de un amigo, en la localidad bonaerense de El Palomar, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":351891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-92661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=92661"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92661\/revisions"}],"predecessor-version":[{"id":351893,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92661\/revisions\/351893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/351891"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=92661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=92661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=92661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}