{"id":92506,"date":"2012-08-16T07:29:00","date_gmt":"2012-08-16T11:29:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20120816\/madonna-la-reina-del-pop-cumple-54-anos\/"},"modified":"2025-07-15T15:55:24","modified_gmt":"2025-07-15T15:55:24","slug":"madonna-la-reina-del-pop-cumple-54-anos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20120816\/madonna-la-reina-del-pop-cumple-54-anos\/","title":{"rendered":"Madonna, la reina del pop cumple 54 a\u00f1os"},"content":{"rendered":"<p>Madrid &#8211; Lleva m\u00e1s de 30 a\u00f1os &#8216;reinando&#8217; en el panorama musical, otros tantos en el mundo del cine, y el \u00e9xito es una de las palabras que definen su carrera; Madonna suma hoy un a\u00f1o m\u00e1s a una vida en la que, a juzgar por sus relaciones sentimentales, en lo \u00fanico en lo que no ha tenido suerte ha sido en el amor.<\/p>\n<p>Naci\u00f3 en Bay City, Michigan (EEUU) en 1958, y dej\u00f3 de ser la ni\u00f1a de la casa tras perder a su madre por un c\u00e1ncer de mama, ya que su padre volvi\u00f3 a casarse y tuvo dos hijos m\u00e1s, Jennifer y Mario, lo que impuls\u00f3 una rebeld\u00eda que no perder\u00eda con los a\u00f1os.<\/p>\n<p>Sus inicios art\u00edsticos fueron las clases de piano que su padre le obligaba a recibir, y que ella consigui\u00f3 cambiar por las de baile usando como moneda de cambio sus buenas notas en la escuela, mostrando ya desde peque\u00f1a sus dotes para los negocios.<\/p>\n<p>Fue el core\u00f3grafo Christopher Flynn quien agudiz\u00f3 el instinto art\u00edstico de Madonna, y quien la inici\u00f3 en los sacrificios que exig\u00eda el dedicarse a ello profesionalmente, algo que en lugar de asustarla, le hizo lanzarse a buscar su sue\u00f1o.<\/p>\n<p>Se mud\u00f3 a Nueva York con una beca para aprender danza, y poco despu\u00e9s entr\u00f3 en el coro de Patrick Hern\u00e1ndez en Par\u00eds, pero fue su relaci\u00f3n sentimental con Dan Gilroy lo que le hizo empezar a tocar la bater\u00eda en el grupo &#8216;The Breakfast Club&#8217;.<\/p>\n<p>Conoci\u00f3 a Steve Bray en 1980, y se uni\u00f3 a su banda, &#8216;The Millionares&#8217;, lo que la convirti\u00f3 en una habitual de las noches neoyorquinas en las que empez\u00f3 a llamar la atenci\u00f3n con sus atrevidos &#8216;looks&#8217;.<\/p>\n<p>En 1983 public\u00f3 su primer disco en solitario, &#8216;Madonna&#8217;, que fue el inicio de una carrera musical en la que ha enlazado \u00e9xito tras \u00e9xito, aunque tambi\u00e9n pol\u00e9mica tras pol\u00e9mica.<\/p>\n<p>Solo un a\u00f1o m\u00e1s tarde debut\u00f3 en el cine con &#8216;Desperately Seeking Susan&#8217;, y sus apariciones en largometrajes se sucedieron, con mayor suerte en algunos, como &#8216;Evita&#8217; (1996), y peor en otros, como &#8216;Swept Away&#8217; (2002), en la que estuvo dirigida por su entonces marido Guy Ritchie.<\/p>\n<p>Su faceta cinematogr\u00e1fica se complet\u00f3 en 2008 con su estreno como directora con &#8216;Filth and Wisdom&#8217;, y en 2011 volvi\u00f3 a coger las riendas para dirigir la pel\u00edcula &#8216;W.E.&#8217;.<\/p>\n<p>Sus relaciones amorosas han sido varias, pero la lista oficial est\u00e1 compuesta solamente por algunos nombres.<\/p>\n<p>Se cas\u00f3 con Sean Penn en 1985, y su matrimonio dur\u00f3 cuatro a\u00f1os, tras el cual tuvo un breve romance con Warren Beatty, compa\u00f1ero de reparto en la pel\u00edcula &#8216;Dick Tracy&#8217;.<\/p>\n<p>En 1996 Madonna dio a luz a su primera hija, Lourdes Mar\u00eda, fruto de su relaci\u00f3n con su entrenador personal, el cubano Carlos Le\u00f3n.<\/p>\n<p>Hasta esa fecha, se le hab\u00eda relacionado con varios hombres conocidos, como el cantante Lenny Kravitz, el rapero Vanilla Ice o el deportista Dennis Rodman.<\/p>\n<p>Poco despu\u00e9s lleg\u00f3 a su vida el director de cine Guy Ritchie, el hombre que m\u00e1s dur\u00f3 a su lado en el trono, y con quien tuvo a su hijo Rocco en 2001 y adopt\u00f3 a David Banda Mwale, de Malaui, en 2008, tras una custodia temporal de dos a\u00f1os.<\/p>\n<p>Un a\u00f1o m\u00e1s tarde, ya separada de Ritchie, y tras una lucha en los tribunales, adopt\u00f3 a otra ni\u00f1a malau\u00ed, Chifundo James &#8216;Mercy&#8217;.<\/p>\n<p>Despu\u00e9s de su sonado divorcio, mantuvo una relaci\u00f3n con el modelo brasile\u00f1o Jes\u00fas Luz, de tan solo 22 a\u00f1os.<\/p>\n<p>Con fama de extravagante, grab\u00f3 uno de los v\u00eddeos m\u00e1s caros de la historia de la m\u00fasica, &#8216;Express yourself&#8217;, el mismo tema que, seg\u00fan sugiri\u00f3 la propia Madonna en una entrevista, Lady Gaga plagi\u00f3 con su sencillo &#8216;Born this way&#8217;.<\/p>\n<p>Su personalidad provocadora ha sido la se\u00f1a de identidad de la cantante durante su reinado en el pop, y ya en los 80 tuvo problemas con la iglesia italiana por el v\u00eddeo de su disco &#8216;Like a prayer&#8217;.<\/p>\n<p>Pero sus espect\u00e1culos irreverentes y pol\u00e9micos han sido una constante en su carrera musical, incluso despu\u00e9s de introducirse en la C\u00e1bala, una corriente de la m\u00edstica jud\u00eda, que tuvo gran influencia en su disco &#8216;Ray of light&#8217;.<\/p>\n<p>A lo largo de los a\u00f1os, sus habituales cambios de &#8216;look&#8217;, las escenas sexuales expl\u00edcitas en sus v\u00eddeoclips, como las del tema &#8216;Justify my love&#8217;, han suscitado muchas cr\u00edticas e incluso censura en algunos medios.<\/p>\n<p>La actriz, cantante, directora y empresaria cumple hoy 54 a\u00f1os inmersa en la gira mundial de presentaci\u00f3n de su \u00faltimo disco, &#8216;MDNA&#8217;, el duod\u00e9cimo de estudio de su carrera, que ya se ha convertido en un nuevo \u00e9xito de &#8216;la ambici\u00f3n rubia&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Madrid &#8211; Lleva m\u00e1s de 30 a\u00f1os &#8216;reinando&#8217; en el panorama musical, otros tantos en el mundo del cine, y el \u00e9xito es una de las palabras que definen su carrera; Madonna suma hoy un a\u00f1o m\u00e1s a una vida en la que, a juzgar por sus relaciones sentimentales, en lo \u00fanico en lo que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":352875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-92506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=92506"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92506\/revisions"}],"predecessor-version":[{"id":352877,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92506\/revisions\/352877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/352875"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=92506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=92506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=92506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}