{"id":92107,"date":"2014-07-29T06:20:40","date_gmt":"2014-07-29T10:20:40","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20140729\/oriental-otorga-financiamiento-de-1-4-millones-a-bettina\/"},"modified":"2025-07-15T16:23:15","modified_gmt":"2025-07-15T16:23:15","slug":"oriental-otorga-financiamiento-de-1-4-millones-a-bettina","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20140729\/oriental-otorga-financiamiento-de-1-4-millones-a-bettina\/","title":{"rendered":"Oriental otorga financiamiento de $1.4 millones a Bettina"},"content":{"rendered":"<p>La divisi\u00f3n de banca de empresas de Oriental otorg\u00f3 un prestamo por m\u00e1s de $1.4 millones a la empresa Bettina Cosmetics, Inc., compa\u00f1\u00eda puertorrique\u00f1a con m\u00e1s de 50 a\u00f1os de establecida en la Isla.<\/p>\n<p>El financiamiento servir\u00e1 para la expansi\u00f3n y adquisici\u00f3n de equipo para sus nuevas instalaciones de manufactura, localizadas en Dorado. Esta inversi\u00f3n contribuir\u00e1 a la creaci\u00f3n de empleos directos e indirectos en la zona.<\/p><div class=\"notic-content-middle\" id=\"notic-747124035\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Por medio de este pr\u00e9stamo ayudamos a aumentar significativamente la capacidad de producci\u00f3n de dicha compa\u00f1\u00eda al a\u00f1adir recursos para la expansi\u00f3n y exportaci\u00f3n de productos de una empresa netamente puertorrique\u00f1a&#8217;, dijo Elena Manrara, vicepresidenta s\u00e9nior de Banca de Empresas en Oriental. &#8216;Adem\u00e1s, estas mejoras a la infraestructura de Bettina Cosmetics, permiten que unas instalaciones que no estaban en uso en dicho municipio se remodelen y genere actividad econ\u00f3mica para la regi\u00f3n&#8217;, concluy\u00f3 Manrara.<\/p>\n<p>Para m\u00e1s noticias de econom\u00eda visite <a href=\"http:\/\/sincomillas.com\/\" target=\"_blank\">Sincomillas.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La divisi\u00f3n de banca de empresas de Oriental otorg\u00f3 un prestamo por m\u00e1s de $1.4 millones a la empresa Bettina Cosmetics, Inc., compa\u00f1\u00eda puertorrique\u00f1a con m\u00e1s de 50 a\u00f1os de establecida en la Isla. El financiamiento servir\u00e1 para la expansi\u00f3n y adquisici\u00f3n de equipo para sus nuevas instalaciones de manufactura, localizadas en Dorado. Esta inversi\u00f3n [&hellip;]<\/p>","protected":false},"author":0,"featured_media":355298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-92107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=92107"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92107\/revisions"}],"predecessor-version":[{"id":355300,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92107\/revisions\/355300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/355298"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=92107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=92107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=92107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}