{"id":92001,"date":"2016-03-30T18:49:00","date_gmt":"2016-03-30T22:49:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20160330\/el-capricho-del-paseo-puerta-de-tierra-puede-quedar-a-medias\/"},"modified":"2025-07-15T16:32:28","modified_gmt":"2025-07-15T16:32:28","slug":"el-capricho-del-paseo-puerta-de-tierra-puede-quedar-a-medias","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160330\/el-capricho-del-paseo-puerta-de-tierra-puede-quedar-a-medias\/","title":{"rendered":"El &#8216;capricho&#8217; del Paseo Puerta de Tierra puede quedar a medias"},"content":{"rendered":"<p>&#8216;La cr\u00f3nica de un desastre anunciado&#8217; y un &#8216;capricho&#8217; disfrazado de &#8216;proyecto emblem\u00e1tico&#8217;, fueron algunas de las descripciones que ocho organizaciones comunitarias y ambientales usaron para describir la construcci\u00f3n a medias del Paseo Puerta de Tierra hoy, miercoles, durante una conferencia de prensa con la cual advirtieron que el mismo pudiera quedar a mitad aunque su efecto ya es irreversible.<\/p>\n<p>&#8216;Las comunidades del Viejo San Juan y de Puerta de Tierra advirtieron desde que se les present\u00f3 este proyecto en mayo de 2014 los problemas de tr\u00e1nsito, de destrucci\u00f3n ambiental, de mala planificaci\u00f3n sin consulta a la comunidad y del uso indebido de $40 millones de d\u00f3lares \u2013en aquel momento- en tiempos de crisis econ\u00f3mica gubernamental&#8217;, indic\u00f3 la portavoz de la Asociaci\u00f3n de vecinos del Viejo San Juan (AVISAJ), Janice Petrovich.<\/p>\n<p>Organizaciones como el Consejo Vecinal de Puerta de Tierra, la Brigada de Puerta de Tierra, LOLA Costanera Inc., Coralations, Inc., GuardaMar Caribe, la Coalici\u00f3n Restauraci\u00f3n Ecosistemas Santurcinos (CRES), Arrecifes Pro Ciudad, Inc., y Vegabaje\u00f1os Impulsando Desarrollo Ambiental Sustentable (VIDAS), advirtieron que dada la situaci\u00f3n econ\u00f3mica del Pa\u00eds, el proyecto podr\u00eda quedarse a mitad a menos que el gobierno decida sacrificar prioridades como salud y seguridad para seguirle inyectando dinero al &#8216;malnacido capricho del gobernador Alejandro Garc\u00eda Padilla que lo ha denominado como su &#8216;proyecto emblem\u00e1tico&#8217;, cuando &#8216;queda demostrado que el derrumbe es lo emblem\u00e1tico de esta administraci\u00f3n que no escucha razones y se empe\u00f1a en caprichos&#8217;.<\/p>\n<p>&#8216;El costo social de este proyecto se extiende peligrosamente hasta Puerta de Tierra amenazando la integridad del sector con el desplazamiento de sus habitantes y la destrucci\u00f3n de este hist\u00f3rico sector&#8217;, a\u00f1adi\u00f3 la portavoz del Consejo Vecinal de Puerta de Tierra, comerciante y residente del sector, Lucy D\u00e1vila.<\/p><div class=\"notic-content-middle\" id=\"notic-2423205425\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La comunidad reiter\u00f3 la necesidad de paralizar el proyecto, redise\u00f1arlo a una escala humana y sensible con el ambiente f\u00edsico y social; revisar los estudios de suelos, si se hicieron; y reforestar el \u00e1rea para mitigar la erosi\u00f3n y proteger el patrimonio arqueol\u00f3gico.<\/p>\n<p>Ni las querellas presentadas y acogidas favorablemente ante la Agencia federal de Protecci\u00f3n Ambiental (EPA por sus siglas ingl\u00e9s) han tenido efecto sobre el gobierno.<\/p>\n<p>&#8216;Los \u00fanicos cambios a que accedi\u00f3 la licenciada Grace Santana, directora de AFI y hoy secretaria de la Gobernaci\u00f3n, fue eliminar la p\u00e9rgola que ir\u00eda sobre la Terraza al Mar y la construcci\u00f3n de la Puerta de Santiago, proyectada para la entrada al Viejo San Juan. Cambios cosm\u00e9ticos que no atend\u00edan la preocupaci\u00f3n de intervenir agresivamente el \u00fanico litoral libre de construcciones en la costa norte de la zona metropolitana&#8217;, detallaron.<\/p>\n<p>&#8216;Hoy vemos que nuestras advertencias se confirman: la erosi\u00f3n y el deslizamiento de terreno en el \u00e1rea -que a su vez afecta los ecosistemas marinos del lugar- son quiz\u00e1s irreversibles. Sin embargo el proyecto, el capricho, contin\u00faa adelante afectando no s\u00f3lo el ambiente f\u00edsico, sino la calidad de vida de los residentes de Puerta de Tierra que sufren los efectos de la mala planificaci\u00f3n ejecutada en Antigua v\u00eda del tren que ya ha causado serios accidentes de tr\u00e1nsito&#8217;, a\u00f1adi\u00f3 Petrovich.<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8216;La cr\u00f3nica de un desastre anunciado&#8217; y un &#8216;capricho&#8217; disfrazado de &#8216;proyecto emblem\u00e1tico&#8217;, fueron algunas de las descripciones que ocho organizaciones comunitarias y ambientales usaron para describir la construcci\u00f3n a medias del Paseo Puerta de Tierra hoy, miercoles, durante una conferencia de prensa con la cual advirtieron que el mismo pudiera quedar a mitad aunque [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-92001","post","type-post","status-publish","format-standard","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=92001"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92001\/revisions"}],"predecessor-version":[{"id":356137,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/92001\/revisions\/356137"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=92001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=92001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=92001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}