{"id":91327,"date":"2014-07-22T17:03:35","date_gmt":"2014-07-22T21:03:35","guid":{"rendered":"http:\/\/www.noticel.com\/auspiciado\/suplemento\/20140722\/supermercados-econo-dona-110000-a-organizaciones-sin-fines-de-lucro\/"},"modified":"2025-07-15T17:28:40","modified_gmt":"2025-07-15T17:28:40","slug":"supermercados-econo-dona-110000-a-organizaciones-sin-fines-de-lucro","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/auspiciado\/20140722\/supermercados-econo-dona-110000-a-organizaciones-sin-fines-de-lucro\/","title":{"rendered":"Supermercados Econo dona $110,000 a organizaciones sin fines de lucro"},"content":{"rendered":"<p>Supermercados ECONO celebr\u00f3 su tradicional Torneo de Golf &#8216;Presidential Cup&#8217; como parte de las actividades del Encuentro Familiar 2014, en el Wyndham Grand R\u00edo Mar Beach Resort. Gracias a la participaci\u00f3n y aportaci\u00f3n de suplidores, socios y auspiciadores, ECONO logr\u00f3 recaudar $110,000 para ayudar a cinco entidades beneficas que llevan a cabo una labor extraordinaria en la comunidad, como parte de su plataforma de responsabilidad social corporativa, <strong><em>Gestos Positivos P\u00e1salos P\u00e1&#8217;Lante.<\/em><\/strong><\/p>\n<p>Las entidades ben\u00e9ficas seleccionadas fueron:<\/p>\n<p>\u2022 Fundaci\u00f3n Make a Wish- Utilizar\u00e1n este donativo para cumplir el sue\u00f1o de 5 ni\u00f1os cuyas vidas han sido marcadas por enfermedades terminales.<\/p>\n<p>\u2022 La Fondita de Jes\u00fas &#8211; Con esta aportaci\u00f3n, rehabilitar\u00e1n el \u00e1rea de Servicios Biopsicosociales, conocida como &#8216;La Puerta al Cambio&#8217;, permitiendo as\u00ed ofrecer mejores servicios a personas sin hogar, asegurando una mejor salud y condiciones de vida.<\/p>\n<p>\u2022 DEA Survivors Benefit Fund&#8217; \u2013 Utilizar\u00e1 los fondos, para continuar pagando los estudios y ayudando a familiares e hijos de oficiales ca\u00eddos en el deber.<\/p><div class=\"notic-content-middle\" id=\"notic-118149100\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u2022 Liga Puertorrique\u00f1a Contra el C\u00e1ncer \u2013 Este donativo ser\u00e1 destinado al Centro de Im\u00e1genes, para adquirir maquinaria necesaria para ofrecer mejores servicios a los pacientes.<\/p>\n<p>\u2022 CAP \u2013 El donativo ser\u00e1 destinado a la remodelaci\u00f3n del cuarto de tratamiento de acuerdo a los est\u00e1ndares de salud p\u00fablica.<\/p>\n<p>&#8216;Estamos muy emocionados de poder apoyar a estas entidades, que d\u00eda tras d\u00eda, en conjunto, trabajan por una mejor calidad de vida para los puertorrique\u00f1os y en separado, canalizan todos sus esfuerzos y medios a atender alguna causa apremiante. El Torneo de Golf, &#8216;Presidential Cup&#8217; de Supermercados ECONO, reafirma el compromiso social de nuestra Empresa&#8217;, concluy\u00f3 Juan R. Barreto, hijo, Presidente de la Junta de Directores de Supermercados ECONO.<\/p>\n<p>Los donativos a estas entidades fueron entregados durante la premiaci\u00f3n del Torneo, como parte de las actividades del Encuentro Familiar 2014.<\/p>","protected":false},"excerpt":{"rendered":"<p>Supermercados ECONO celebr\u00f3 su tradicional Torneo de Golf &#8216;Presidential Cup&#8217; como parte de las actividades del Encuentro Familiar 2014, en el Wyndham Grand R\u00edo Mar Beach Resort. Gracias a la participaci\u00f3n y aportaci\u00f3n de suplidores, socios y auspiciadores, ECONO logr\u00f3 recaudar $110,000 para ayudar a cinco entidades beneficas que llevan a cabo una labor extraordinaria [&hellip;]<\/p>","protected":false},"author":0,"featured_media":360716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[81],"tags":[],"class_list":["post-91327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auspiciado"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=91327"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91327\/revisions"}],"predecessor-version":[{"id":360717,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91327\/revisions\/360717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/360716"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=91327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=91327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=91327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}