{"id":91258,"date":"2016-04-18T14:48:00","date_gmt":"2016-04-18T18:48:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20160418\/grandes-de-la-salsa-lloran-la-muerte-de-quintana\/"},"modified":"2025-07-15T17:37:44","modified_gmt":"2025-07-15T17:37:44","slug":"grandes-de-la-salsa-lloran-la-muerte-de-quintana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20160418\/grandes-de-la-salsa-lloran-la-muerte-de-quintana\/","title":{"rendered":"Grandes de la salsa lloran la muerte de Quintana"},"content":{"rendered":"<p>La muerte del cantante y compositor Ismael Quintana, uno de los miembros originales de la legendaria orquesta de Las Estrellas de la Fania, supone una perdida importante para el mundo de la salsa, que hoy llora el fallecimiento de una de sus voces m\u00e1s reconocidas.<\/p>\n<p>&#8216;Ismael fue un hombre recto, tranquilo, hablaba bien pausado y era bien agradable. Siempre fue la misma persona&#8217;, dijo hoy a Efe el trompetista y cantante boricua Jerry Medina, quien tambi\u00e9n particip\u00f3 en las Estrellas de la Fania, aunque nunca coincidi\u00f3 con Quintana en la agrupaci\u00f3n.<\/p>\n<p>Donde s\u00ed coincidieron fue en la orquesta del pianista Eddie Palmieri, con quien el fenecido cantante grab\u00f3 algunos de sus m\u00e1s reconocidos temas, como &#8216;V\u00e1monos pal&#8217; monte&#8217;, &#8216;Puerto Rico&#8217;, &#8216;Mu\u00f1eca&#8217;, &#8216;La blusita color\u00e1&#8217;, &#8216;La malanga&#8217;, &#8216;Bilongo&#8217;, &#8216;Adoraci\u00f3n&#8217; y &#8216;Mi debilidad&#8217;.<\/p>\n<p>&#8216;Hay binomios que se dan y explotan, y \u00e9se fue el de Ismael con Eddie, que explot\u00f3&#8217;, resalt\u00f3 Medina sobre el junte de orquesta entre Quintana y Palmieri, conocido como &#8216;El sol de la m\u00fasica latina&#8217;, en la orquesta La Perfecta.<\/p>\n<p>Otros destacados duetos musicales en el g\u00e9nero de la salsa han sido el de Rafael Cortijo con Ismael Rivera, H\u00e9ctor Lavoe con Willie Col\u00f3n, Col\u00f3n con Rub\u00e9n Blades, Larry Harlow con Ismael Miranda y Ray Barreto con Adalberto Santiago.<\/p>\n<p>Quintana, conocido como &#8216;El Pat&#8217;, falleci\u00f3 el pasado s\u00e1bado por la noche a sus 78 a\u00f1os por un infarto cardiaco en el estado de Colorado (EE.UU.), seg\u00fan confirm\u00f3 a Efe el historiador musical Hiram Guadalupe.<\/p>\n<p>Su muerte se dio a conocer el domingo, el mismo d\u00eda en que se cumpl\u00eda el segundo aniversario del fallecimiento del legendario cantante puertorrique\u00f1o Cheo Feliciano, con quien comparti\u00f3 el escenario con las Estrellas de la Fania.<\/p>\n<p>Esa legendaria orquesta ve morir as\u00ed a otro de sus integrantes, como ya ocurri\u00f3 con Lavoe, Barreto, Celia Cruz, Pete &#8216;El Conde&#8217; Rodr\u00edguez y Yomo Toro.<\/p>\n<p>En vida quedan sin embargo muchas otras figuras de aquella orquesta neoyorquina, entre ellos su primer director musical y fundador, el dominicano Johnny Pacheco, as\u00ed como Roberto Roena, Bobby Valent\u00edn, Nicky Marrero, Papo Lucca, Eddie Montalvo, Ruben Blades, Larry Harlow, Willie Col\u00f3n, Adalberto Santiago e Ismael Miranda.<\/p>\n<p>&#8216;La voz de Quintana la puedo describir como aterciopelada&#8217;, dijo hoy a Efe Jos\u00e9 Lugo, conocido pianista y director musical de la orquesta Guas\u00e1bara Combo que nunca coincidi\u00f3 en el escenario con el m\u00fasico, natural de la localidad sure\u00f1a de Ponce.<\/p>\n<p>&#8216;Cada vez quedan menos cantantes de la talla de Ismael Quintana. Al igual que Cheo, pasar\u00e1n cien a\u00f1os para tener otra vez igual&#8217;, destac\u00f3 Lugo del tambi\u00e9n percusionista.<\/p>\n<p>El m\u00fasico cubano y residente en Puerto Rico Juan Jos\u00e9 Hern\u00e1ndez explic\u00f3 hoy a Efe que escuch\u00f3 por primera vez la m\u00fasica de Quintana en su pa\u00eds natal y desde entonces sigui\u00f3 haci\u00e9ndolo, hasta el punto de que influy\u00f3 en su forma de cantar y componer.<\/p>\n<p>&#8216;La discograf\u00eda de Ismael form\u00f3 parte de mi aprendizaje como cantante, sobre todo al llegar a Puerto Rico. Quintana ser\u00e1 eterno junto a otros como Cheo, Maelo y Lavoe&#8217;, afirm\u00f3 el tambi\u00e9n cantante y compositor de artistas como Gilberto Santa Rosa, Ismael Miranda y El Gran Combo de Puerto Rico.<\/p>\n<p>Muchos otros grandes de la m\u00fasica como Eddie Palmieri y Rub\u00e9n Blades lamentaban tambi\u00e9n la muerte de Quintana, quien particip\u00f3 con las Estrellas de Fania en los emblem\u00e1ticos conciertos del antiguo Yankee Stadium en Nueva York en 1973 y del estadio Statu Hai en Zaire, \u00c1frica.<\/p>\n<p>&#8216;Fue un gran amigo de toda mi vida, un cantante incre\u00edble y un verdadero caballero dentro y fuera del escenario. Juntos hicimos historia con la orquesta original La Perfecta. Ismael siempre vivir\u00e1 en nuestros corazones, y le enviamos a sus familiares nuestras mes sinceras condolencias&#8217;, escribi\u00f3 Palmieri en un comunicado.<\/p>\n<p>Blades se refiri\u00f3 a Quintana como un &#8216;profesional sin tacha, decente y ejemplo para todos&#8217;.<\/p>\n<p>&#8216;Mi memoria de Ismael Quintana es la de una persona correcta, un verdadero caballero en todo sentido y alguien que desarroll\u00f3 un estilo que lo destaca y que lo sit\u00faa en el sal\u00f3n de los cl\u00e1sicos de la salsa&#8217;, dijo tambi\u00e9n en un comunicado.<\/p>\n<p>&#8216;El Pat&#8217; ser\u00e1 velado este pr\u00f3ximo jueves y viernes en la Funeraria Jackie Oliver en su natal Ponce, municipio al sur de Puerto Rico, para luego ser enterrado el s\u00e1bado en el cementerio La Piedad, donde tambi\u00e9n yacen los restos de Cheo Feliciano.<\/p>","protected":false},"excerpt":{"rendered":"<p>La muerte del cantante y compositor Ismael Quintana, uno de los miembros originales de la legendaria orquesta de Las Estrellas de la Fania, supone una perdida importante para el mundo de la salsa, que hoy llora el fallecimiento de una de sus voces m\u00e1s reconocidas. &#8216;Ismael fue un hombre recto, tranquilo, hablaba bien pausado y [&hellip;]<\/p>","protected":false},"author":0,"featured_media":361328,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-91258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=91258"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91258\/revisions"}],"predecessor-version":[{"id":361330,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91258\/revisions\/361330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/361328"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=91258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=91258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=91258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}