{"id":91119,"date":"2012-12-05T14:10:28","date_gmt":"2012-12-05T18:10:28","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/gobierno\/politica\/20121205\/andreu-fuentes-critica-acuerdo-de-cooperacion-con-federales\/"},"modified":"2025-07-15T17:48:33","modified_gmt":"2025-07-15T17:48:33","slug":"andreu-fuentes-critica-acuerdo-de-cooperacion-con-federales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20121205\/andreu-fuentes-critica-acuerdo-de-cooperacion-con-federales\/","title":{"rendered":"Andreu Fuentes critica acuerdo de cooperaci\u00f3n con federales"},"content":{"rendered":"<p>El licenciado Jose Andreu Fuentes, miembro del Comite de Transici\u00f3n del gobierno entrante, critic\u00f3 a la administraci\u00f3n saliente de Luis Fortu\u00f1o por menospreciar el sistema de justicia local al delegar en las autoridades estadounidenses el procesamiento judicial de casos que han recibido mucha cobertura medi\u00e1tica, como el asesinato reciente del publicista Jose Enrique G\u00f3mez.<\/p>\n<p>Andreu Fuentes destac\u00f3 que es dif\u00edcil medir la efectividad del acuerdo si se toma en cuenta que los casos que llegan ante los magistrados y jueces federales son investigados por agentes de la Polic\u00eda puertorrique\u00f1a.<\/p>\n<p>&#8216;En virtud de este acuerdo de cooperaci\u00f3n, esos casos son investigados por agentes de la Polic\u00eda de Puerto Rico y por agentes del NIE, en otras palabras, los que est\u00e1n investigando esos casos es el gobierno estatal. De la misma manera que usted lo puede llevar al foro federal, usted lo puede procesar en el foro estatal&#8217;, destac\u00f3 Andreu Fuentes en una rueda de prensa en el intermedio de almuerzo de la transici\u00f3n gubernamental.<\/p>\n<p>Andreu Fuentes utiliz\u00f3 el caso del publicista para establecer que se pudo haber procesado localmente.<\/p>\n<p>&#8216;En el caso de ayer, yo no veo (la necesidad), si usted tiene una persona que ha confesado que el crimen, si usted tiene ya todas las personas arrestadas, (y) aparentemente todos de una u otra manera han confesado, cu\u00e1l es la necesidad de que ese caso se vaya al foro federal?, cuando nosotros tenemos los fiscales en Puerto Rico, tenemos los jueces en Puerto Rico y tenemos la capacidad para procesar a esas personas&#8217;, destac\u00f3.<\/p><div class=\"notic-content-middle\" id=\"notic-2239331211\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Y record\u00f3 que en el foro federal no existe el delito de asesinato.<\/p>\n<p>&#8216;Esas personas no est\u00e1n acusadas de asesinato en el caso federal. Est\u00e1n acusadas del \u2018carjacking&#8217;, que es donde ellos tienen jurisdicci\u00f3n y, obviamente, salen culpables como hubo un asesinato en el carjacking pues la pena puede llegar a ser una pena de cadena perpetua o de pena de muerte. No hay nada en ese caso que impida que esas personas est\u00e9n hoy en una c\u00e1rcel de Puerto Rico procesadas dentro del sistema nuestro&#8217;, indic\u00f3.<\/p>\n<p>&#8216;Yo creo que por ese tipo de acuerdo el sistema judicial puertorrique\u00f1o pierde credibilidad cuando no deber\u00eda ser as\u00ed&#8217;, sostuvo Andreu Fuentes, quien opin\u00f3 que el cr\u00e9dito y m\u00e9rito de procesar esos casos se lo debe llevar el sistema judicial local.<\/p>\n<p>A su juicio, el acuerdo entre Fortu\u00f1o y la jefa de la fiscal\u00eda federal, Rosa Emilia Rodr\u00edguez, ha desmotivado a los componentes de seguridad p\u00fablica, principalmente en el Departamento de Justicia.<\/p>\n<p>&#8216;Una de las cosas importantes es que se mantengan a nuestros componentes del sistema de justicia criminal con la motivaci\u00f3n suficiente para seguir trabajando. En la medida en que las cosas se desv\u00edan all\u00e1 (al foro federal), pues yo estoy seguro que habr\u00e1 una serie de fiscales aqu\u00ed que hubieran querido procesar ese caso y eso crea un problema&#8217;, sentenci\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>El licenciado Jose Andreu Fuentes, miembro del Comite de Transici\u00f3n del gobierno entrante, critic\u00f3 a la administraci\u00f3n saliente de Luis Fortu\u00f1o por menospreciar el sistema de justicia local al delegar en las autoridades estadounidenses el procesamiento judicial de casos que han recibido mucha cobertura medi\u00e1tica, como el asesinato reciente del publicista Jose Enrique G\u00f3mez. Andreu [&hellip;]<\/p>","protected":false},"author":0,"featured_media":362184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,7,2],"tags":[],"class_list":["post-91119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=91119"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91119\/revisions"}],"predecessor-version":[{"id":362186,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/91119\/revisions\/362186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/362184"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=91119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=91119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=91119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}