{"id":90379,"date":"2016-09-15T14:50:00","date_gmt":"2016-09-15T18:50:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/politica\/20160915\/david-bernier-no-votara-por-jaime-perello-y-perello-le-lanza-otra\/"},"modified":"2025-07-15T18:56:58","modified_gmt":"2025-07-15T18:56:58","slug":"david-bernier-no-votara-por-jaime-perello-y-perello-le-lanza-otra","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160915\/david-bernier-no-votara-por-jaime-perello-y-perello-le-lanza-otra\/","title":{"rendered":"David Bernier no votar\u00e1 por Jaime Perell\u00f3&#8230; y Perell\u00f3 le lanza otra"},"content":{"rendered":"<p>&#8216;Yo no voy a votar por Jaime Perell\u00f3. Y exhorto a los electores que, como nunca antes en la historia electoral de Puerto Rico, sean rigurosos a la hora de emitir su voto&#8217;.<\/p>\n<p>Estas fueron las palabras del aspirante a la gobernaci\u00f3n por el Partido Popular Democr\u00e1tico (PPD) a primeras horas de esta tarde, en las que el l\u00edder pidi\u00f3 al electorado que desempe\u00f1e un fuerte ejercicio de responsabilidad democr\u00e1tica de cara las pr\u00f3ximas elecciones. &#8216;Miren la papeleta de los dos partidos. A todos los que se han dejado en la papeleta alPNP que le han faltado al pa\u00eds, (que) no lo respalden. Y, en caso del PPD, que hagan lo propio. Que busquen a otro en ese rengl\u00f3n que sea del PPD&#8217;.<\/p>\n<p>Estas palabras vuelven a subrayar la profunda divisi\u00f3n existente en las filas de populares, pero Bernier afirm\u00f3 su determinaci\u00f3n de continuar con firmeza en la toma de decisiones dif\u00edciles que impliquen a su colegiatura, siempre y cuando sean pertinentes.<\/p>\n<p>Pero, el desaparecido Perell\u00f3 regres\u00f3 a las redes sociales para contrariar al Presidente de la Pava y exhortar al voto \u00edntegro.<\/p>\n<p>Los populares votamos \u00edntegro como nos ense\u00f1\u00f3 Mu\u00f1oz. Yo votar\u00e9 1 sola cruz bajo la pava en las 3 papeletas. JP<\/p>\n<p>\u2014 Jaime Perell\u00f3 (@jrperello)<\/p>\n<p><a href=\"https:\/\/twitter.com\/jrperello\/status\/776517574532161540\">September 15, 2016<\/a><\/p>\n<p>Respecto al cuestionamiento emitido por distintas voces del Partido Nuevo Progresista (PNP), en las que se destaca la inactividad del l\u00edder popular al no haber procedido a la desafiliaci\u00f3n de la ex senadora, Mari Tere Gonz\u00e1lez, tras haberse acogido a su derecho constitucional a no auto incriminarse en el testimonio efectuado con motivo de su posible implicaci\u00f3n en el esquema de corrupci\u00f3n gubernamental sostenido por el ex recaudador y empresario Anaudi Hern\u00e1ndez, David Bernier sostuvo que &#8216;lo que hay es una opini\u00f3n sobre lo que pudiera ocurrir&#8217;, y que, en el instante en que se pruebe que la ex senadora popular incurri\u00f3 en delito, se le aplicar\u00e1 el reglamento del partido.<\/p><div class=\"notic-content-middle\" id=\"notic-3389192616\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Sin embargo, Bernier destac\u00f3 que, m\u00e1s all\u00e1 de esas medidas fijadas por el reglamento, &#8216;yo estoy estableciendo una vara m\u00e1s alta, que es un planteamiento moral&#8217;. Respecto a las voces que han manifestado su debilidad en t\u00e9rminos de liderazgo, el candidato a la gobernaci\u00f3n rememor\u00f3 acciones llevadas a cabo en el pasado: &#8216;no me ha titubeado la mano. Yo le ped\u00ed la renuncia al alcalde de R\u00edo Grande. Yo le ped\u00ed la renuncia al alcalde de Guayanilla. Yo saqu\u00e9 casi a media docena, por faltas menores, de la papeleta del PPD. Hice lo propio con Mari Tere Gonz\u00e1lez, con Jaime Perell\u00f3, y con todo el que tenga que hacerlo. Y el PNP? Cu\u00e1ndo ustedes le van a reclamar que cumpla su reglamento?&#8217;.<\/p>\n<p>El ex secretario de Estado asegur\u00f3 que hizo todo cuanto estuvo en su mano para expulsar a Jaime Perell\u00f3 de la papeleta popular, asegurando que no se hallaron evidencias suficientes que pudieran permitir la toma de decisiones, ni tan siquiera bajo los reglamentos estipulados por el propio partido: &#8216;lo evaluamos, hicimos el an\u00e1lisis legal y yo te aseguro que, si las tuviera (evidencias), hubiera actuado. De inmediato y firme&#8217;.<\/p>\n<p>Frente a esta situaci\u00f3n de incapacidad, exhort\u00f3 a los votantes que se abstengan de apoyar la candidatura del ex presidente de la C\u00e1mara de Representantes.<\/p>\n<p>Incidiendo en la divisi\u00f3n del partido, se mostr\u00f3 en desacuerdo con la decisi\u00f3n del actual presidente en funciones de la C\u00e1mara Baja,Roberto Rivera Ruiz de Porras, quien afirm\u00f3 no tener la intenci\u00f3n de investigar \u00e9ticamente a Perell\u00f3. &#8216;El presidente debe ser riguroso y debe investigar a Jaime&#8217;, confirm\u00f3 Bernier, al tiempo que afirm\u00f3 que &#8216;con la duda es suficiente para que lo investiguen&#8217;. Cerrando este asunto, asegur\u00f3 que proceder\u00e1 a la evaluaci\u00f3n de la situaci\u00f3n y, en caso de hallar evidencias, no tendr\u00e1 ning\u00fan problema en presentar \u00e9l mismo la querella.<\/p>\n<p>M\u00e1s temprano el exsenador popular Eudaldo B\u00e1ez Galibdijo a NotiCel que se debe pedir abiertamente al electorado que vote en contra aPerell\u00f3.<\/p>\n<p>De acuerdo al abogado, el presidente del PPD no tiene otro camino si quiere ser consistente con las razones esbozadas para solicitar la renuncia de Perell\u00f3 a la presidencia de la c\u00e1mara y posteriormente su salida de la papeleta de esa colectividad.<\/p>\n<p>&#8216;Debe pedir p\u00fablicamente en su campa\u00f1a un voto en contra y explicar por qu\u00e9. Esto es el factor, el elemento moral. Es que, de otra forma, yo no puedo ver c\u00f3mo \u00e9l (Bernier) pueda pedir un voto \u00edntegro. Podr\u00e1 pedirlo en otra papeleta; pero en la papeleta de los candidatos a representantes por acumulaci\u00f3n\u2026 Si lo hace es ir en contra de la petici\u00f3n que ha hecho&#8217;, afirm\u00f3 B\u00e1ez Galib.<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8216;Yo no voy a votar por Jaime Perell\u00f3. Y exhorto a los electores que, como nunca antes en la historia electoral de Puerto Rico, sean rigurosos a la hora de emitir su voto&#8217;. Estas fueron las palabras del aspirante a la gobernaci\u00f3n por el Partido Popular Democr\u00e1tico (PPD) a primeras horas de esta tarde, en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":367604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-90379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/90379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=90379"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/90379\/revisions"}],"predecessor-version":[{"id":367606,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/90379\/revisions\/367606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/367604"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=90379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=90379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=90379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}