{"id":90283,"date":"2014-03-21T14:24:32","date_gmt":"2014-03-21T18:24:32","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20140321\/ordenan-la-detencion-de-la-cantante-anita-baker\/"},"modified":"2025-07-15T19:03:08","modified_gmt":"2025-07-15T19:03:08","slug":"ordenan-la-detencion-de-la-cantante-anita-baker","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140321\/ordenan-la-detencion-de-la-cantante-anita-baker\/","title":{"rendered":"Ordenan la detenci\u00f3n de la cantante Anita Baker"},"content":{"rendered":"<p>Una jueza de Michigan (EE.UU.) orden\u00f3 la detenci\u00f3n por desacato de la cantautora Anita Baker, galardonada ocho veces en los premios Grammy, informaron hoy los medios locales.<\/p>\n<p>A Baker se la acusa de impago a una empresa de decoraci\u00f3n que realiz\u00f3 trabajos de carpinter\u00eda y pintura en su casa de Grosse Pointe, junto a lago Saint Clair, en la frontera entre Estados Unidos y Canad\u00e1, por un valor de m\u00e1s de 15,000 d\u00f3lares.<\/p>\n<p>La magistrada Annette Berry emiti\u00f3 este mi\u00e9rcoles una orden de arresto para la cantante, que se conoci\u00f3 hoy, por no acudir al tribunal hace seis meses, cuando fue requerida su presencia.<\/p>\n<p>Baker, que se destac\u00f3 en la d\u00e9cada de los 80 con canciones soul-pop como &#8216;Sweet Love&#8217;, &#8216;Caught Up In the Rapture&#8217; y &#8216;Giving You the Best That I Got&#8217;, se ha enfrentado a varias denuncias por no abonar facturas y por no pagar sus impuestos en los \u00faltimos a\u00f1os.<\/p>\n<p>Adem\u00e1s, en 2008, su ahora exmarido, del que se estaba divorciando, la demand\u00f3 por retrasarse en la firma de los documentos de la separaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una jueza de Michigan (EE.UU.) orden\u00f3 la detenci\u00f3n por desacato de la cantautora Anita Baker, galardonada ocho veces en los premios Grammy, informaron hoy los medios locales. A Baker se la acusa de impago a una empresa de decoraci\u00f3n que realiz\u00f3 trabajos de carpinter\u00eda y pintura en su casa de Grosse Pointe, junto a lago [&hellip;]<\/p>","protected":false},"author":0,"featured_media":368111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-90283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/90283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=90283"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/90283\/revisions"}],"predecessor-version":[{"id":368113,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/90283\/revisions\/368113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/368111"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=90283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=90283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=90283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}