{"id":89275,"date":"2013-12-05T13:16:51","date_gmt":"2013-12-05T17:16:51","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20131205\/oficial-el-concierto-de-tempo-en-el-choliseo\/"},"modified":"2025-07-15T20:32:45","modified_gmt":"2025-07-15T20:32:45","slug":"oficial-el-concierto-de-tempo-en-el-choliseo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20131205\/oficial-el-concierto-de-tempo-en-el-choliseo\/","title":{"rendered":"Oficial el concierto de Tempo en el Choliseo"},"content":{"rendered":"<p>El equipo de producci\u00f3n de David S\u00e1nchez Badillo, mejor conocido como Tempo, anunci\u00f3 el jueves oficialmente el concierto del reggaetonero que ser\u00e1 el 17 de mayo pr\u00f3ximo en el Coliseo de Puerto Rico. Tempo, retomar\u00e1 su espacio con un espect\u00e1culo de primera, llamado &#8216;Freedom&#8217; y que producir\u00e1 No Limit Entertainment.<\/p>\n<p>&#8216;No puedo esperar a que sea el 17 de mayo. Esto ser\u00e1 un concierto para la historia lleno de sorpresas&#8217;, asegur\u00f3 el productor Paco L\u00f3pez.<\/p>\n<p>Los boletos para el concierto estar\u00e1n a la venta en Ticketpop y en la boleter\u00eda del Coliseo desde este viernes, 6 de diciembre a partir de las 10:00 de la ma\u00f1ana.<\/p><div class=\"notic-content-middle\" id=\"notic-1250318744\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/07\/01063353\/CST_Suma-Pasa-La-Llave_300x600-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La presentaci\u00f3n ser\u00e1 el inicio de una nueva etapa del cantante, quien recientemente sali\u00f3 de una prisi\u00f3n federal por un caso de drogas y armas por el que debe completar 500 horas de labor comunitaria y 10 a\u00f1os de libertad supervisada como parte de su condena de 14 a\u00f1os. Originalmente la sentencia era de 24 a\u00f1os.<\/p>\n<p>La producci\u00f3n asegur\u00f3 que Tempo ya cuenta con un sinn\u00famero de ofertas para llevar sus presentaciones alrededor del mundo.<\/p>\n<p>Adem\u00e1s, se dio a conocer que el artista ya tiene presencia en las redes sociales. Sus fans ya pueden seguir sus cuentas oficiales en Twitter, Facebook, Instagram bajo el nombre de usuario yosoytempo.<\/p>","protected":false},"excerpt":{"rendered":"<p>El equipo de producci\u00f3n de David S\u00e1nchez Badillo, mejor conocido como Tempo, anunci\u00f3 el jueves oficialmente el concierto del reggaetonero que ser\u00e1 el 17 de mayo pr\u00f3ximo en el Coliseo de Puerto Rico. Tempo, retomar\u00e1 su espacio con un espect\u00e1culo de primera, llamado &#8216;Freedom&#8217; y que producir\u00e1 No Limit Entertainment. &#8216;No puedo esperar a que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":374971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-89275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/89275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=89275"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/89275\/revisions"}],"predecessor-version":[{"id":374973,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/89275\/revisions\/374973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/374971"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=89275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=89275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=89275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}