{"id":88949,"date":"2016-07-19T22:33:00","date_gmt":"2016-07-20T02:33:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20160719\/uber-necesita-reglas-pero-distintas-a-las-de-los-taxistas\/"},"modified":"2025-07-15T21:03:49","modified_gmt":"2025-07-15T21:03:49","slug":"uber-necesita-reglas-pero-distintas-a-las-de-los-taxistas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20160719\/uber-necesita-reglas-pero-distintas-a-las-de-los-taxistas\/","title":{"rendered":"Uber necesita reglas, pero distintas a las de los taxistas"},"content":{"rendered":"<p>La empresa Uber &#8216;amerita un marco regulatorio diferente&#8217; al de la Federaci\u00f3n de Taxistas de Puerto Rico (FTPR) por tratarse de &#8216;un producto nuevo e innovador&#8217; que ofrece servicios de transporte a traves de una aplicaci\u00f3n m\u00f3vil, opin\u00f3 en un documento la organizaci\u00f3n Foundation of Puerto Rico.<\/p>\n<p>En un <a href=\"https:\/\/www.dropbox.com\/s\/y8rf23m44oaj0um\/Econom\u00edaColaborativa.pdf?dl\" target=\"_blank\">documento<\/a> de 24 p\u00e1ginas esta fundaci\u00f3n indica que, a pesar de que algunos taxistas &#8216;reclaman que estar\u00e1n en una desventaja competitiva al tener dos marcos regulatorios cobijando el mercado de transportaci\u00f3n&#8217;, la soluci\u00f3n a dichas denuncias &#8216;no puede ser castigar la innovaci\u00f3n aplic\u00e1ndole la regulaci\u00f3n existente a las empresas de red de transporte&#8217;.<\/p>\n<p>El an\u00e1lisis insta a una acci\u00f3n inmediata &#8216;que no incluya regular, por ejemplo, el color de los veh\u00edculos como en el caso de taxistas&#8217;, pero que se considere el ejemplo de la ciudad de Seattle, &#8216;donde la legislatura municipal regul\u00f3 a la entrada de Uber limitando el n\u00famero de autom\u00f3viles y horas en la carretera&#8217;.<\/p>\n<p>Mientras a\u00fan se dilucida en los tribunales de Puerto Rico las agencias que tienen jurisdicci\u00f3n para regular las operaciones de Uber, la Fundaci\u00f3n record\u00f3 el caso de Londres, donde estudios de varios economistas detallaron que &#8216;la ineficiencia causada por los requisitos restrictivos para obtener una licencia de regulaci\u00f3n en la ciudad&#8217; incorpor\u00f3 &#8217;10 millones&#8217; de d\u00f3lares en p\u00e9rdida anual de este servicio.<\/p>\n<p>&#8216;En 1986 hab\u00eda unos 19,000 taxis, mientras que en el 2015 la cantidad de taxis era de 22,500&#8217;, lo que seg\u00fan el an\u00e1lisis, representa un incremento de &#8216;18%&#8217; en el ofrecimiento de transporte. Sin embargo, la poblaci\u00f3n en Londres en ese mismo periodo aument\u00f3 &#8216;en un 32%&#8217;.<\/p>\n<p>&#8216;Quiz\u00e1s alguien pudiera argumentar que un aumento en poblaci\u00f3n no necesariamente lleva a un aumento proporcional en la demanda de servicios de transporte. Sin embargo con la entrada de esta empresa s\u00ed podemos analizar el efecto que tiene una expansi\u00f3n de la oferta en el mercado. Desde su inserci\u00f3n en Londres en el 2012, se han sumado unos 25,000 conductores a su plataforma y esto se debe a la f\u00e1cil regulaci\u00f3n que cost\u00f3 un tiempo incorporar&#8217;, lee el informe de la organizaci\u00f3n.<\/p>\n<p>En Puerto Rico, a pesar de no contar con un marco regulatorio para Uber, los requisitos para obtener una licencia &#8216;son muy exigentes&#8217;, apunta el documento.<\/p><div class=\"notic-content-middle\" id=\"notic-1666104744\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Adem\u00e1s de exigir el tipo de veh\u00edculo a operar, el reglamento exige la aprobaci\u00f3n de los siguientes ex\u00e1menes: Mejoramiento de Conductores, Informaci\u00f3n Tur\u00edstica e Hist\u00f3rica de Puerto Rico, Ingl\u00e9s conversacional, Relaciones Humanas y cursos de educaci\u00f3n continua cada dos a\u00f1os para conocer las \u00c1reas de Transporte Tur\u00edstico&#8217;, se\u00f1ala.<\/p>\n<p>No obstante, el presidente de la FTPR, Juan de Le\u00f3n, reaccion\u00f3 a estos consejos de regulaci\u00f3n estableciendo que &#8216;el color de los carros no es un issue para nosotros. Aqu\u00ed lo importante es que primero, se quiere aprobar una regulaci\u00f3n que no dice que \u2018ning\u00fan municipio u otra entidad gubernamental podr\u00e1 imponer impuestos sobre o requerir licencias&#8217;. Oye, no van a pagar a Hacienda, ni las patentes. Te garantizo que a la semana pr\u00f3xima de aprobarse, nosotros vamos a pedir que se emitan medidas de resoluci\u00f3n con estas mismas concesiones&#8217;.<\/p>\n<p>Por otro lado, a pesar de las recomendaciones a favor de Uber, Foundation of Puerto Rico, tambi\u00e9n se sit\u00faa en la misma l\u00ednea del presidente de la Federaci\u00f3n, plateando una invitaci\u00f3n a la prudencia.<\/p>\n<p>&#8216;Intivamos a ser prudentes con los reglamentos, ya que estos pueden afectar el desarrollo de este mercado\u2026 y recomendamos tambi\u00e9n que se atemperen los requisitos regulatorios para todos, no solo a las empresas de la econom\u00eda colaborativa&#8217;, cierra el documento.<\/p>\n<p>Lea tambi\u00e9n<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/noticia\/192780\/impugnado-en-el-apelativo-el-permiso-provisional-del-dtop-a-uber-documentos.html\/\" target=\"_blank\">Impugnado en el Apelativo el permiso provisional del DTOP a Uber (documentos)<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/noticia\/192535\/guino-de-uber-en-puerto-rico-a-la-economia-del-compartir.html\/\" target=\"_blank\">Gui\u00f1o de Uber en Puerto Rico a la &#8216;econom\u00eda del compartir&#8217;<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La empresa Uber &#8216;amerita un marco regulatorio diferente&#8217; al de la Federaci\u00f3n de Taxistas de Puerto Rico (FTPR) por tratarse de &#8216;un producto nuevo e innovador&#8217; que ofrece servicios de transporte a traves de una aplicaci\u00f3n m\u00f3vil, opin\u00f3 en un documento la organizaci\u00f3n Foundation of Puerto Rico. En un documento de 24 p\u00e1ginas esta fundaci\u00f3n [&hellip;]<\/p>","protected":false},"author":0,"featured_media":377405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-88949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=88949"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88949\/revisions"}],"predecessor-version":[{"id":377407,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88949\/revisions\/377407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/377405"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=88949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=88949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=88949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}