{"id":88948,"date":"2014-10-13T18:53:08","date_gmt":"2014-10-13T22:53:08","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20141013\/enfermeras-de-ee-uu-no-se-sienten-preparadas-para-el-ebola\/"},"modified":"2025-07-15T21:03:52","modified_gmt":"2025-07-15T21:03:52","slug":"enfermeras-de-ee-uu-no-se-sienten-preparadas-para-el-ebola","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20141013\/enfermeras-de-ee-uu-no-se-sienten-preparadas-para-el-ebola\/","title":{"rendered":"Enfermeras de EE.UU. no se sienten preparadas para el \u00e9bola"},"content":{"rendered":"<p>Al menos tres de cada cuatro enfermeras en Estados Unidos no se sienten preparadas para tratar adecuadamente con pacientes de ebola, seg\u00fan los resultados de un sondeo divulgado el lunes.<\/p>\n<p>El sondeo, realizado a 2,000 enfermeras pertenecientes a National Nurses United, la mayor asociaci\u00f3n de profesionales del sector en el pa\u00eds, revela que un 85 % de las entrevistadas afirman no haber recibido en sus hospitales suficiente informaci\u00f3n para identificar e interactuar con pacientes con s\u00edntomas de padecer \u00e9bola.<\/p>\n<p>El primer caso de contagio dentro de EE.UU. ha sido precisamente el de una enfermera de 26 a\u00f1os, Nina Pham, que atendi\u00f3 en el hospital presbiteriano de Dallas, Texas a Thomas Eric Duncan, el primer enfermo de \u00e9bola diagnosticado en el pa\u00eds y que falleci\u00f3 el pasado mi\u00e9rcoles.<\/p>\n<p>La encuesta, que se puede ver en la p\u00e1gina web de la asociaci\u00f3n, muestra, adem\u00e1s, que un 75 % de las enfermeras sostienen que sus hospitales no les han comunicado la existencia de una pol\u00edtica espec\u00edfica con respecto a &#8216;potenciales admisiones&#8217; de pacientes infectados por el virus.<\/p><div class=\"notic-content-middle\" id=\"notic-4113396549\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Asimismo, un 36 % se\u00f1ala que en sus hospitales no hay suficientes batas de las requeridas para entrar en contacto con pacientes de \u00e9bola.<\/p>\n<p>Tras confirmarse el contagio este domingo, Pham sigue aislada y est\u00e1 &#8216;cl\u00ednicamente estable&#8217;, dijo hoy el director de los Centros de Control de Prevenci\u00f3n y Enfermedades (CDC) de EE.UU., Thomas Frieden, en una conferencia de prensa.Frieden tambi\u00e9n afirm\u00f3 que a ra\u00edz de este contagio Estados Unidos debe &#8216;repensar&#8217; el modo en el que &#8216;aborda&#8217; el control del \u00e9bola en su propio territorio, ya que la infecci\u00f3n de Pham es &#8216;inaceptable&#8217;.<\/p>\n<p>Las autoridades sanitarias contin\u00faan hoy investigando qu\u00e9 pudo pasar para que la enfermera se infectara.Durante su contacto con Duncan, la mujer llevaba el traje de protecci\u00f3n requerido, con bata, guantes y m\u00e1scara, pero &#8216;en alg\u00fan momento hubo un fallo en el protocolo&#8217; de seguridad, seg\u00fan sostuvo ayer Frieden.Tambi\u00e9n ayer, Obama orden\u00f3 que se realice &#8216;lo m\u00e1s pronto posible&#8217; una investigaci\u00f3n del &#8216;aparente&#8217; fallo en los protocolos de control de infecciones del hospital afectado.<\/p>","protected":false},"excerpt":{"rendered":"<p>Al menos tres de cada cuatro enfermeras en Estados Unidos no se sienten preparadas para tratar adecuadamente con pacientes de ebola, seg\u00fan los resultados de un sondeo divulgado el lunes. El sondeo, realizado a 2,000 enfermeras pertenecientes a National Nurses United, la mayor asociaci\u00f3n de profesionales del sector en el pa\u00eds, revela que un 85 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":377409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-88948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=88948"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88948\/revisions"}],"predecessor-version":[{"id":377412,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88948\/revisions\/377412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/377409"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=88948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=88948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=88948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}