{"id":88213,"date":"2015-05-18T16:18:31","date_gmt":"2015-05-18T20:18:31","guid":{"rendered":"http:\/\/www.noticel.com\/beisbol\/deportes\/mlb\/20150518\/dan-jennings-es-el-nuevo-manejador-de-los-marlins\/"},"modified":"2025-07-15T22:04:45","modified_gmt":"2025-07-15T22:04:45","slug":"dan-jennings-es-el-nuevo-manejador-de-los-marlins","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20150518\/dan-jennings-es-el-nuevo-manejador-de-los-marlins\/","title":{"rendered":"Dan Jennings es el nuevo manejador de los Marlins"},"content":{"rendered":"<p>Los Marlins de Miami ya tienen a su nuevo manejador, se trata del gerente general Dan Jennings que fue elegido para suceder a Mike Redmond, que ayer fue cesado del cargo.<\/p>\n<p>Jennings fue presentado hoy por la ma\u00f1ana en una conferencia de prensa, menos de 24 horas despu\u00e9s del despido de Redmond tras una derrota 6-0 ante Atlanta, que barri\u00f3 una serie de tres partidos y dej\u00f3 la marca de la novena de Miami en 16-22.<\/p>\n<p>&#8216;No hemos estado jugando como podemos hacerlo&#8217;, sostuvo el presidente de las operaciones de b\u00e9isbol, Michael Hill, despu\u00e9s de esa derrota. &#8216;Esperemos que una nueva voz motive a nuestros muchachos&#8217;.<\/p>\n<p>Tambi\u00e9n fue despedido el ayudante de Redmond, Rob Leary, al considerar que tampoco hizo su trabajo.<\/p>\n<p>Jennings estaba en su segundo a\u00f1o como gerente general. Trabaja con los Marlins en la parte administrativa desde el 2002 y su experiencia como piloto se limita a un breve per\u00edodo en el que dirigi\u00f3 a un equipo de una escuela secundaria en Mobile, Alabama, en la d\u00e9cada de 1980.<\/p>\n<p>Se prob\u00f3 como lanzador con la organizaci\u00f3n de los Yanquis de Nueva York y despu\u00e9s hizo de observador antes de ser contratado por los Marlins.<\/p>\n<p>Los cambios han sido orquestados por el due\u00f1o de los Marlins, Jeffrey Loria, famoso por su impaciencia con los pilotos.<\/p><div class=\"notic-content-middle\" id=\"notic-1316309758\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.facebook.com\/magnapremiumlager\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"106-2026-21_Magna Verano Display v.02\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Jennings es el quinto piloto que tienen los Marlins en las \u00faltimas seis temporadas.<\/p>\n<p>Su selecci\u00f3n le evita al equipo tener que pagar un nuevo sueldo. Redmond ten\u00eda contrato hasta el 2017 y los Marlins todav\u00eda le est\u00e1n pagando al venezolano Ozzie Guill\u00e9n, a quien le quedaban tres a\u00f1os de contrato cuando fue despedido en el 2012.<\/p>\n<p>Los Marlins aspiraban a cosas grandes esta temporada, en que se reforzaron con el toletero de origen puertorrique\u00f1o Giancarlo Stanton, a quien le dieron un contrato sin precedentes de 325 millones de d\u00f3lares.<\/p>\n<p>Pero su bullpen ha sido un desastre y los bates no est\u00e1n respondiendo, con excepci\u00f3n de Stanton, quien encabeza la liga en carreras impulsadas, y Dee Gordon.<\/p>\n<p>Los Marlins ganaron apenas nueve de sus \u00faltimos 13 juegos y est\u00e1n cuartos en la divisi\u00f3n Este de la Liga Nacional, algo que impacient\u00f3 de nuevo a Loria.<\/p>\n<p>Sin embargo, el movimiento no se entiende, dado que el equipo pod\u00eda haber incluido a Jennings en el trabajo de Redmond y buscar soluciones conjuntas con el profesional al que tienen que pagarle salario hasta el 2017 aunque no est\u00e9 con ellos dentro de la organizaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los Marlins de Miami ya tienen a su nuevo manejador, se trata del gerente general Dan Jennings que fue elegido para suceder a Mike Redmond, que ayer fue cesado del cargo. Jennings fue presentado hoy por la ma\u00f1ana en una conferencia de prensa, menos de 24 horas despu\u00e9s del despido de Redmond tras una derrota [&hellip;]<\/p>","protected":false},"author":0,"featured_media":381946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[32,31],"tags":[],"class_list":["post-88213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=88213"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88213\/revisions"}],"predecessor-version":[{"id":381948,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88213\/revisions\/381948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/381946"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=88213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=88213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=88213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}