{"id":88160,"date":"2014-09-01T14:00:06","date_gmt":"2014-09-01T18:00:06","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20140901\/el-tango-electronico-de-bajofondo-vuelve-a-puerto-rico\/"},"modified":"2025-07-15T22:08:31","modified_gmt":"2025-07-15T22:08:31","slug":"el-tango-electronico-de-bajofondo-vuelve-a-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140901\/el-tango-electronico-de-bajofondo-vuelve-a-puerto-rico\/","title":{"rendered":"El tango electr\u00f3nico de Bajofondo vuelve a Puerto Rico"},"content":{"rendered":"<p>La agrupaci\u00f3n de tango electr\u00f3nico Bajofondo vuelve a Puerto Rico para ofrecer dos conciertos a comienzos de noviembre, en los que repasar\u00e1 con el p\u00fablico de la isla los temas de su \u00faltima producci\u00f3n, &#8216;Presente&#8217; (2013), as\u00ed como de los dos anteriores, &#8216;Tango Club&#8217; (2002) y &#8216;Mar Dulce&#8217; (2007).<\/p>\n<p>Seg\u00fan detallaron los organizadores de ambos conciertos en un comunicado de prensa, la primera de esas presentaciones tendr\u00e1 lugar el jueves 6 de noviembre en el Paseo Litoral deMayag\u00fcez.<\/p>\n<p>Al d\u00eda siguiente los m\u00fasicos de Bajofondo, argentinos y uruguayos que ya visitaron la isla caribe\u00f1a hace poco m\u00e1s de un a\u00f1o, actuar\u00e1n en el Coliseo de Puerto Rico Jos\u00e9 Miguel Agrelot, en San Juan.<\/p>\n<p>&#8216;Puerto Rico siempre es parte importante de nuestras giras y guardamos un gran recuerdo del \u00e1nimo de la audiencia boricua. Estamos contentos de poder compartir nuestra m\u00fasica con los puertorrique\u00f1os&#8217;, dijo su integrante Gustavo Santaolalla.<\/p>\n<p>Seg\u00fan explic\u00f3, ambos conciertos &#8216;tendr\u00e1n la fusi\u00f3n de g\u00e9neros, pero manteniendo como base el tango, la m\u00fasica electr\u00f3nica y un aire de m\u00fasica cl\u00e1sica&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-3973081079\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.facebook.com\/magnapremiumlager\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"106-2026-21_Magna Verano Display v.02\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>&#8216;Nuestra m\u00fasica tambi\u00e9n se complementa con elementos de rock, jazz, blues y otros ritmos folcl\u00f3ricos latinoamericanos para bailar&#8217;, record\u00f3 el compositor y m\u00fasico argentino, ganador de dos premios \u00d3scar por las bandas sonoras de las pel\u00edculas &#8216;Brokeback Mountain&#8217; (2005) y &#8216;Babel&#8217; (2006), as\u00ed como de catorce Grammy.<\/p>\n<p>Las entradas para ver a esta banda, creada en 2002 y que antes de llegar a Puerto Rico est\u00e1 previsto que se presente tambi\u00e9n en otros pa\u00edses como Italia, Espa\u00f1a, Marruecos y M\u00e9xico, ya est\u00e1n a la venta a trav\u00e9s de los sistemas electr\u00f3nicos Ticketpop y Ticket Center.<\/p>\n<p>Adem\u00e1s de por Santaolalla, Bajofondo est\u00e1 integrada tambi\u00e9n por Juan Campod\u00f3nico, Luciano Supervielle, Ver\u00f3nica Loza, Mart\u00edn Ferres, Javier Casalla, Adri\u00e1n Sosa y Gabriel Casacuberta.<\/p>\n<p>Su \u00faltimo trabajo, &#8216;Presente&#8217;, es casi un disco doble con 21 temas, ideado como un manifiesto art\u00edstico de Bajofondo, donde los cortes van hilvanados con un hilo conductor sonoro y no argumental que trata de evocar &#8216;un viaje emocional y musical&#8217; cargado de influencias, seg\u00fan describi\u00f3 Santaolalla en una entrevista con el Efe la \u00faltima vez que visit\u00f3 la isla, en abril de 2013.<\/p>","protected":false},"excerpt":{"rendered":"<p>La agrupaci\u00f3n de tango electr\u00f3nico Bajofondo vuelve a Puerto Rico para ofrecer dos conciertos a comienzos de noviembre, en los que repasar\u00e1 con el p\u00fablico de la isla los temas de su \u00faltima producci\u00f3n, &#8216;Presente&#8217; (2013), as\u00ed como de los dos anteriores, &#8216;Tango Club&#8217; (2002) y &#8216;Mar Dulce&#8217; (2007). Seg\u00fan detallaron los organizadores de ambos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":382294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-88160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=88160"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88160\/revisions"}],"predecessor-version":[{"id":382297,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88160\/revisions\/382297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/382294"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=88160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=88160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=88160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}