{"id":88015,"date":"2011-05-21T16:02:00","date_gmt":"2011-05-21T20:02:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20110521\/gozoso-final-para-el-pep-y-su-barsa\/"},"modified":"2025-07-15T22:18:38","modified_gmt":"2025-07-15T22:18:38","slug":"gozoso-final-para-el-pep-y-su-barsa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20110521\/gozoso-final-para-el-pep-y-su-barsa\/","title":{"rendered":"Gozoso final para el Pep y su Barsa"},"content":{"rendered":"<p>El t\u00e9cnico del Barcelona FC, Pep Guardiola, no pudo esconder su regocijo al hablar esta tarde con la prensa espa\u00f1ola.<\/p>\n<p>Si usted es fan\u00e1tico del Barsa, grite &#8216;Weeeeepaaaaaa!&#8217;. Eso fue lo que le falt\u00f3 decir esta tarde a Pep Guardiola, dirigente del Barcelona, que tras vencer al M\u00e1laga completaron una de las temporadas m\u00e1s hist\u00f3ricas del f\u00fatbol espa\u00f1ol.<\/p>\n<p>El entrenador del Barcelona coment\u00f3 largo y tendido esta tarde, tras el 1-3 logrado por su equipo ante el M\u00e1laga en el partido de la \u00faltima jornada de La Liga, que le parece que los 96 puntos que han sumado en el campeonato son &#8216;una barbaridad&#8217;.<\/p>\n<p>El t\u00e9cnico catal\u00e1n tambi\u00e9n destac\u00f3 &#8216;el r\u00e9cord de victorias fuera de casa&#8217; y apunt\u00f3 que por todo ello hab\u00eda que &#8216;felicitar al equipo&#8217; blaugrana.<\/p>\n<p>Se refiri\u00f3 a la Final de la Liga de Campeones de Europa que disputar\u00e1n el pr\u00f3ximo s\u00e1bado en Londres ante el Manchester United.<\/p>\n<p>&#8216;El mundo nos va a mirar e intentaremos dignificar con nuestro juego al futbol espa\u00f1ol&#8217;, expres\u00f3 a la Agencia EFE.<\/p>\n<p>Guardiola coment\u00f3 sobre su \u00faltimo rival que &#8216;ha hecho un final de temporada excelente&#8217; y por ello quiso felicitar al equipo andaluz y al meta Francesc Arnau, quien se despidi\u00f3 como futbolista profesional.<\/p>\n<p>&#8216;Ahora ves al M\u00e1laga y ves que Pellegrini ha dejado su marca. Seguro que el a\u00f1o que viene va a ser un equipo muy competitivo&#8217;, puntualiz\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>El t\u00e9cnico del Barcelona FC, Pep Guardiola, no pudo esconder su regocijo al hablar esta tarde con la prensa espa\u00f1ola. Si usted es fan\u00e1tico del Barsa, grite &#8216;Weeeeepaaaaaa!&#8217;. Eso fue lo que le falt\u00f3 decir esta tarde a Pep Guardiola, dirigente del Barcelona, que tras vencer al M\u00e1laga completaron una de las temporadas m\u00e1s hist\u00f3ricas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":383126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-88015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=88015"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88015\/revisions"}],"predecessor-version":[{"id":383129,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/88015\/revisions\/383129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/383126"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=88015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=88015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=88015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}