{"id":87888,"date":"2014-02-07T16:20:50","date_gmt":"2014-02-07T20:20:50","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20140207\/la-fria-historia-de-los-juegos-olimpicos-invernales\/"},"modified":"2025-07-15T22:26:54","modified_gmt":"2025-07-15T22:26:54","slug":"la-fria-historia-de-los-juegos-olimpicos-invernales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20140207\/la-fria-historia-de-los-juegos-olimpicos-invernales\/","title":{"rendered":"La fr\u00eda historia de los Juegos Ol\u00edmpicos Invernales"},"content":{"rendered":"<p>La ciudad rusa de Sochi, que sucede a la canadiense de Vancouver, es la sede de los XXII Juegos Ol\u00edmpicos de Invierno de la historia, cuya primera edici\u00f3n tuvo lugar en 1924 en la localidad francesa de Chamonix.<\/p>\n<p>Con anterioridad, en el calendario de los Juegos de Londres 1908 se hab\u00eda incluido el patinaje art\u00edstico, al igual que en los de Amberes 1920, en los que tambi\u00e9n hubo hockey hielo, aunque los primeros Juegos de Invierno &#8216;de verdad&#8217; no se celebraron hasta 1924 y recibieron ese tratamiento de forma retroactiva, concebidos inicialmente como la Semana Internacional del Deporte (invernal).<\/p>\n<p>Las competiciones fueron un \u00e9xito y los escandinavos, que con anterioridad se opon\u00edan a las tesis -sobre todo alemanas- de crear unos Juegos de Invierno, accedieron a que \u00e9stos se disputaran, con una periodicidad de cuatro a\u00f1os, despu\u00e9s de ganar 28 de las 43 medallas repartidas. El patinador estadounidense Charles Jewtrew -oro en los 500 metros- fue el primer campe\u00f3n ol\u00edmpico de invierno y Noruega acab\u00f3 primera en el medallero.<\/p>\n<p>Lo volvi\u00f3 a encabezar en los que alberg\u00f3 en 1928 la estaci\u00f3n suiza de St. Moritz, en unos Juegos en los que el patinador de velocidad finland\u00e9s A. Clas Thunberg, que hab\u00eda capturado seis medallas cuatro a\u00f1os antes -tres de oro-, se anot\u00f3 dos nuevos t\u00edtulos ol\u00edmpicos y la noruega Sonja Henie caus\u00f3 sensaci\u00f3n al ganar el patinaje art\u00edstico a los 15 a\u00f1os.<\/p>\n<p>En su tercera edici\u00f3n, los Juegos de Invierno hicieron el primer cambio de continente y en el 32 la sede fue Lake Placid. Abri\u00f3 los Juegos Franklin Delano Roosevelt, gobernador del estado de Nueva York y m\u00e1s tarde presidente de los Estados Unidos, que encabezaron un medallero final que se decidi\u00f3 con pol\u00e9mica, al cambiar toda una serie de reglas en el patinaje de velocidad sin haber avisado de ello al resto. El estadounidense Eddie Eagan gan\u00f3 en el &#8216;bob&#8217; a cuatro y se convirti\u00f3 en el primer y hasta el momento el \u00fanico campe\u00f3n ol\u00edmpico de invierno y de verano, ya que en Amberes&#8217;20 (B\u00e9lgica) hab\u00eda ganado oro en boxeo.<\/p>\n<p>Los del 36 fueron los Juegos de Adolfo Hitler, que uni\u00f3 Garmisch y Partenkirchen situando una estaci\u00f3n de ferrocarril entre ambas localidades b\u00e1varas. Sonja Heine fue estrella ante su p\u00fablico al lograr su tercer oro consecutivo en patinaje art\u00edstico en la \u00faltima cita ol\u00edmpica antes de la II Guerra Mundial.<\/p>\n<p>Tras la misma, St. Moritz fue de nuevo sede en 1948, en una edici\u00f3n en la que las sanciones internacionales excluyeron a Jap\u00f3n y a Alemania.<\/p>\n<p>En 1952 los Juegos llegaron a Noruega, cuna del esqu\u00ed moderno. La llama ol\u00edmpica se encendi\u00f3 en la casa de Sondre Nordheim, el primer esquiador famoso, y fue transportada por 94 esquiadores hasta Oslo. Canad\u00e1 gan\u00f3 su quinto t\u00edtulo ol\u00edmpico en hockey y el pa\u00eds anfitri\u00f3n volvi\u00f3 a ganar el medallero, por tercera vez seguida.<\/p>\n<p>Cortina D&#8217;Ampezzo, en los Dolomitas italianos, alberg\u00f3 la edici\u00f3n de 1956, en la que particip\u00f3 por primera vez la URSS, que, con siete oros, tres platas y seis bronces, fue la primera en la clasificaci\u00f3n de trofeos, que se volver\u00eda a anotar en los siguientes dos Juegos.<\/p>\n<p>El austr\u00edaco Toni Sailer, que hizo pleno en esqu\u00ed alpino al ganar las tres pruebas -ahora se disputan cinco- fue el h\u00e9roe de los primera cita ol\u00edmpica invernal televisada, que le catapult\u00f3 al mundo del cine. &#8216;El rayo de Kitz&#8217; (&#8216;Der Blitz aus Kitz&#8217;), como se conoc\u00eda al esquiador de Kitzb\u00fchel, gan\u00f3 descenso, gigante y eslalon.<\/p>\n<p>En 1960 Squaw Valley, en California, supuso la segunda salida de Europa y la segunda que los EE.UU. se hicieron cargo de los mismos. Walt Disney presidi\u00f3 el comit\u00e9 organizador de las ceremonias inaugural y de cierre y Estados Unidos gan\u00f3 el hockey hielo.<\/p>\n<p>Cuatro a\u00f1os despu\u00e9s, Innsbruck sufri\u00f3 la escasez de nevadas y el ej\u00e9rcito austr\u00edaco &#8216;tom\u00f3&#8217; las monta\u00f1as para acondicionarlas con nieve tra\u00edda de otras estaciones. Las hermanas francesas Christine y Marielle Goitschel cruzaron primer y segundo puesto en el eslalon -que gan\u00f3 la primera- y en el gigante del esqu\u00ed alpino.<\/p>\n<p>En Grenoble&#8217;68 (Francia), Noruega interrumpi\u00f3 el dominio de la Uni\u00f3n Sovi\u00e9tica en el medallero y Jean-Claude Killy repiti\u00f3 ante su p\u00fablico la gesta de Sailer, doce a\u00f1os despu\u00e9s. El italiano Franco Nones (en la prueba de 30 kil\u00f3metros) fue el primer campe\u00f3n ol\u00edmpico de esqu\u00ed de fondo no escandinavo.<\/p>\n<p>Asia se estren\u00f3 en 1972 y en los Juegos de Sapporo (Jap\u00f3n), de los que fue excluido &#8216;por profesional&#8217; uno de los mejores esquiadores de la historia, el austr\u00edaco Karl Schranz, Espa\u00f1a sorprendi\u00f3 con el oro en eslalon de Paco Fern\u00e1ndez Ochoa, \u00fanico campe\u00f3n ol\u00edmpico invernal espa\u00f1ol.<\/p>\n<p>La URSS encabez\u00f3 de nuevo el medallero en Innsbruck&#8217;76 (Austria) y en Lake Placid&#8217;80 (Estados Unidos). En la capital del Tirol -que sustituy\u00f3 a Denver (Colorado, EEUU), designada por el COI, pero cuya poblaci\u00f3n se opuso a la organizaci\u00f3n de los Juegos- Franz Klammer brill\u00f3 ganando el descenso del Bergisel ante su p\u00fablico.<\/p>\n<p>Lake Placid, que, tras serlo en 1932, volvi\u00f3 a ser sede en 1980, fue testigo de los cinco oros en patinaje de velocidad que Eric Heiden gan\u00f3 para Estados Unidos y del sorprendente t\u00edtulo en hockey hielo del equipo local, que gan\u00f3 en la final a la Uni\u00f3n Sovi\u00e9tica.<\/p>\n<p>Sarajevo, la capital bosnia, entonces en Yugoslavia, organiz\u00f3 en el 84 la primera cita invernal en un pa\u00eds socialista. El estadounidense Bill Johnson gan\u00f3 el descenso y sus compatriotas los gemelos Phil y Steve Mahre fueron los dos mejores en el eslalon. La extinta RDA domin\u00f3 el medallero, ocho a\u00f1os antes de que la pista de bobsleigh se convirtiera en una posici\u00f3n artillera de las guerrillas serbias y las pistas de eslalon en una instalaci\u00f3n militar.<\/p>\n<p>En Calgary, Canad\u00e1 alberg\u00f3 por primera vez unos Juegos invernales en 1988 -en el 76 Montreal hab\u00eda sido sede de los de verano-. La germana oriental Katarina Witt defendi\u00f3 su t\u00edtulo en patinaje art\u00edstico. El italiano Alberto Tomba gan\u00f3 el eslalon y el gigante, la suiza Vreni Schneider le emul\u00f3 en las pruebas femeninas y el finland\u00e9s Matti Nykaenen gan\u00f3 tres oros en las pruebas de saltos de esqu\u00ed. La Uni\u00e7on Sovi\u00e9tica domin\u00f3 de nuevo el medallero.<\/p>\n<p>En Albertville&#8217;92 (Francia) Espa\u00f1a gan\u00f3 la que hasta ahora es su segunda medalla ol\u00edmpica invernal, la de Blanca Fern\u00e1ndez Ochoa, hermana de &#8216;Paquito&#8217;, en el eslalon. Tomba se convirti\u00f3 en el primer esquiador alpino en defender t\u00edtulo -el de gigante- y Alemania fue la que m\u00e1s medallas de oro gan\u00f3.<\/p>\n<p>Noruega -que hab\u00eda organizado los de Oslo&#8217;50- volvi\u00f3 a celebrar los Juegos en 1994, en Lillehammer, donde se rompi\u00f3 la cadencia de cuatro a\u00f1os, para separar la cita veraniega de la invernal.<\/p>\n<p>Fueron los Juegos de la pol\u00e9mica entre las patinadoras art\u00edsticas estadounidenses Nancy Kerrigan y Tonya Harding -que hab\u00eda ordenado a unos &#8216;matones&#8217; la agresi\u00f3n de aquella-, que se resolvi\u00f3 con plata para la &#8216;buena&#8217; y un triste octavo para la &#8216;mala&#8217;.<\/p>\n<p>El fondista noruego Bjorn Daehlie, que la hab\u00eda iniciado dos a\u00f1os antes, prosigui\u00f3 con su colecci\u00f3n de trofeos que culminar\u00eda cuatro a\u00f1os m\u00e1s tarde en la segunda cita invernal que alberg\u00f3 Jap\u00f3n: la de Nagano&#8217;98, donde el austr\u00edaco Hermann Maier se convirti\u00f3 en &#8216;Herminator&#8217;, al ganar dos oros -supergigante y gigante- despu\u00e9s de haber sufrido un espectacular accidente -&#8216;la ca\u00edda del siglo&#8217;- en el descenso, disputado en Hakuba.<\/p>\n<p>La alemana Katja Seizinger se convirti\u00f3 en la primera mujer que defend\u00eda con \u00e9xito un t\u00edtulo de descenso y su compatriota Georg Hackl, en luge, se convirti\u00f3 en el sexto deportista de toda la historia en lograr tres t\u00edtulos consecutivos en la misma disciplina.<\/p>\n<p>Daehlie, al ganar tres oros y un bronce, alcanz\u00f3 la gloria ol\u00edmpica absoluta en Nagano, donde alcanz\u00f3 su plusmarca hist\u00f3rica de t\u00edtulos (ocho en total) y medallas (doce).<\/p>\n<p>Su compatriota el biatleta Ole Einar Bjoerndalen (que lleva once) fue el rey de los Juegos que alberg\u00f3 la localidad estadounidense de Salt Lake City, en Utah, donde gan\u00f3 todas las pruebas en la que compiti\u00f3, colg\u00e1ndose al pecho cuatro oros, que a\u00f1adi\u00f3 a otro que hab\u00eda obtenido cuatro a\u00f1os antes en Nagano.<\/p>\n<p>Si Bjoerndalen fue rey, la reina fue la croata Janica Kostelic, ganadora de tres oros y una plata. Y el noruego Kjetil Andre Aamodt se convirti\u00f3 en el esquiador alpino m\u00e1s laureado de la historia ol\u00edmpica, con siete, al ganar en Salt Lake dos oros m\u00e1s. Plusmarca que ampli\u00f3 cuatro a\u00f1os despu\u00e9s en el Piamonte italiano.<\/p>\n<p>La sensaci\u00f3n fue el suizo Simon Ammann, que asombr\u00f3 al ganar dos oros en el salto de trampol\u00edn de 90 y de 120 con tan s\u00f3lo 20 a\u00f1os.<\/p>\n<p>El protagonista negativo fue el espa\u00f1ol de origen alem\u00e1n Johann Muehlegg, que fue despose\u00eddo por dopaje de las tres medallas de oro que lleg\u00f3 a colgarse en esqu\u00ed de fondo.<\/p>\n<p>Los pen\u00faltimos Juegos, vig\u00e9simos, tuvieron sede en Tur\u00edn y los triunfadores fueron el biatleta alem\u00e1n Michael Greis y el patinador en pista corta surcoreano Hyun-Soo Ahn, con tres oros cada uno.<\/p>\n<p>Con dos t\u00edtulos se fueron de Italia la fondista estonia Kristina Smigun y la austriaca Michaela Dorfmeister, que puso la guinda a su carrera con los oros de descenso y supergigante en esqu\u00ed alpino, deporte en el que la espa\u00f1ola Mar\u00eda Jos\u00e9 Rienda, que en los pasados Juegos de Vancouver fue ol\u00edmpica por quinta vez -igualando la plusmarca invernal del fondista c\u00e1ntabro Juan Jesus Guti\u00e9rrez- part\u00eda como favorita en el gigante, en el que se tuvo que conformar con el decimotercer puesto.<\/p>\n<p>El austriaco Benjamin Raich, se convirti\u00f3 en el primer hombre, despu\u00e9s de Tomba, en ganar gigante y eslalon; mientras que Aamodt hizo historia, al ganar por tercera vez -despu\u00e9s de Albertville&#8217;92 y Salt Lake&#8217;02- el t\u00edtulo de supergigante y convertirse en el esquiador alpino m\u00e1s laureado del olimpismo -cuatro oros, dos platas y dos bronces- y, asimismo, en el plusmarquista de esqu\u00ed alpino de medallas en Mundiales y Juegos, con veinte.<\/p>\n<p>Los Juegos de Vancouver comenzaron marcados por la tragedia, ya que horas antes de su inauguraci\u00f3n se produjo el fallecimiento del georgiano Nodar Kumaritashvili durante un entrenamiento de luge; y finalizaron con la anfitriona, Canad\u00e1, al frente del medallero.<\/p>\n<p>Triunfaron dos mujeres, la fondista noruega Marit Bjoergen, que captur\u00f3 tres oros, una plata y un bronce, y la patinadora de velocidad en pista corta Wang Meng logr\u00f3 tres oros en Vancouver, que se sumados al oro, la plata y el bronce que hab\u00eda conseguido cuatro a\u00f1os atr\u00e1s en Tur\u00edn la convirtieron en la m\u00e1s laureada del olimpismo invernal chino.<\/p>\n<p>Meng fue expulsada de su selecci\u00f3n en 2011 tras golpear a su entrenadora Wang Chunlu en estado de embriaguez. Volvi\u00f3 a competir 13 meses despu\u00e9s de ser sancionada y en 2013 brill\u00f3 en los mundiales de Debrecen (Hungr\u00eda), pero se fractur\u00f3 un tobillo el pasado 16 de enero y ser\u00e1 una de las m\u00e1s sonadas ausencias en Sochi.<\/p>\n<p>En esqu\u00ed alpino, el estadounidense Bode Miller -doble ganador de la Copa del Mundo y cu\u00e1druple mundial- captur\u00f3 en Whistler Mountain el \u00fanico t\u00edtulo que le faltaba, el ol\u00edmpico, en la supercombinada, a lo que a\u00f1adi\u00f3 una plata en el superG y un bronce en el descenso.<\/p>","protected":false},"excerpt":{"rendered":"<p>La ciudad rusa de Sochi, que sucede a la canadiense de Vancouver, es la sede de los XXII Juegos Ol\u00edmpicos de Invierno de la historia, cuya primera edici\u00f3n tuvo lugar en 1924 en la localidad francesa de Chamonix. Con anterioridad, en el calendario de los Juegos de Londres 1908 se hab\u00eda incluido el patinaje art\u00edstico, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":383733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-87888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=87888"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87888\/revisions"}],"predecessor-version":[{"id":383734,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87888\/revisions\/383734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/383733"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=87888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=87888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=87888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}