{"id":87480,"date":"2015-08-22T11:53:00","date_gmt":"2015-08-22T15:53:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20150822\/las-10-cincuentonas-mas-elegantes-del-patio-galeria-2\/"},"modified":"2025-07-15T22:56:50","modified_gmt":"2025-07-15T22:56:50","slug":"las-10-cincuentonas-mas-elegantes-del-patio-galeria-2","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20150822\/las-10-cincuentonas-mas-elegantes-del-patio-galeria-2\/","title":{"rendered":"Las 10 cincuentonas m\u00e1s elegantes del patio (galer\u00eda)"},"content":{"rendered":"<p>Las mujeres puertorrique\u00f1as siempre se han destacado por ser fan\u00e1ticas del buen vestir y de mantener una apariencia f\u00edsica impecable<\/p>\n<p>Esta es una costumbre que no desaparece con el pasar del tiempo, por el contrario, mientras pasan los a\u00f1os m\u00e1s cuidan de su imagen. Aqu\u00ed te presentamos 10 mujeres reconocidas de la far\u00e1ndula local, que pasan de los 50 a\u00f1os y se destacan por su elegancia.<\/p>\n<p><strong>Dagmar<\/strong><\/p>\n<p>Ella es una figura muy querida en la televisi\u00f3n por la alegr\u00eda y simpat\u00eda que transmite y, al parecer, esa alegr\u00eda le ha ayudado a que los a\u00f1os no la toquen. La animadora y cantante, adem\u00e1s, goza del cari\u00f1o incondicional del p\u00fablico. Dagmarcumpli\u00f3 60 en marzo pero sigue siendo &#8216;lind\u00edsma&#8217;.<\/p>\n<p><strong>Cordelia Gonz\u00e1lez<\/strong><\/p>\n<p>La veterana actriz se destaca por su elegancia en todo momento. Cordelia es una de esas mujeres que roba miradas donde quiera que se presenta, gracias a su personalidad y porte.<\/p>\n<p><strong>Von Marie M\u00e9ndez<\/strong><\/p>\n<p>Cuando la guapa actriz va por la calle sorprende a quienes la segu\u00edan d\u00eda a d\u00eda en las telenovelas, ya que luce casi id\u00e9ntica a aquellos tiempos en los que fue una de las m\u00e1s aclamadas protagonistas. Sin duda, Von Marie M\u00e9ndez es otra de las cincuentonas que no conoce lo que es el paso del tiempo.<\/p>\n<p><strong>Sully D\u00edaz<\/strong><\/p>\n<p>La respetada actriz y protagonista de telenovelas en la era de gloria<\/p>\n<p><strong>Giselle Blondet<\/strong><\/p><div class=\"notic-content-middle\" id=\"notic-3725811533\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Nos preguntamos si Giselle encontr\u00f3 la receta de la eterna juventud y no la quiere compartir con nadie. La actriz y animadora s\u00ed escribi\u00f3 en un libro su experiencia como cincuentona para motivar a todas esas mujeres que temen llegar a esa edad. Eso est\u00e1 perfecto. Ahora esperamos por la receta de la eterna juventud.<\/p>\n<p><strong>Cyd Marie Fleming<\/strong><\/p>\n<p>Siempre que estuvo ante las c\u00e1maras se destac\u00f3 por su gran elegancia. Y la realidad es que, aunque ya no est\u00e9 en la pantalla, Cyd Marie sigue siendo una de las mujeres mayores de 50 a\u00f1os m\u00e1s elegantes de la Isla.<\/p>\n<p><strong>Carmen Jovet<\/strong><\/p>\n<p>&#8216;La Mujer Noticia&#8217;, adem\u00e1s de ser muy respetada en el pa\u00eds, es sin duda una de las figuras femeninas m\u00e1s elegantes de la pantalla puertorrique\u00f1a. Aunque la veterana periodista pas\u00f3 de los 50 hace m\u00e1s de una d\u00e9cada, la incluimos en esta lista ya quesiempremantiene una imagen intachable.<\/p>\n<p><strong>Myraida Chaves<\/strong><\/p>\n<p>Elegancia, porte y carisma definen a esta presentadora puertorrique\u00f1a que parece no verse afectada con el caminar del reloj.<\/p>\n<p><strong>Alba Nydia D\u00edaz<\/strong><\/p>\n<p>La actriz y presentadora de televisi\u00f3n siempre ha mantenido su elegancia como carta de presentaci\u00f3n. Alba Nydia siempre fue muy admirada por su talento para la actuaci\u00f3n en la \u00e9poca de gloria de las telenovelas del patio. Ac\u00e1 en secreto, Alba Nydia ya cumpli\u00f3 60 pero, qui\u00e9n dir\u00eda?<\/p>\n<p><strong>Deborah Carthy Deu<\/strong><\/p>\n<p>Aunque a\u00fan est\u00e1 al filo de los cincuenta \u2013tiene 49\u2013, la exreina de belleza siempre ha volteado miradas por ese glamur que no la suelta.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"610392179\" embed-content-groupid=\"593030471\" embed-content-id=\"610392180\" embed-content-index=\"0\" embed-content-type=\"GALLERY\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2015\/08\/22\/f2db511261938e799c8f58a97eb18c3f_8150194_ver1.0_320_240.jpg\"\/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Las mujeres puertorrique\u00f1as siempre se han destacado por ser fan\u00e1ticas del buen vestir y de mantener una apariencia f\u00edsica impecable Esta es una costumbre que no desaparece con el pasar del tiempo, por el contrario, mientras pasan los a\u00f1os m\u00e1s cuidan de su imagen. Aqu\u00ed te presentamos 10 mujeres reconocidas de la far\u00e1ndula local, que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":385886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-87480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=87480"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87480\/revisions"}],"predecessor-version":[{"id":385913,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87480\/revisions\/385913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/385886"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=87480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=87480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=87480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}