{"id":87469,"date":"2012-06-04T08:12:00","date_gmt":"2012-06-04T12:12:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20120604\/favoritos-indiscutibles-los-beatles-en-reino-unido\/"},"modified":"2025-07-15T22:57:32","modified_gmt":"2025-07-15T22:57:32","slug":"favoritos-indiscutibles-los-beatles-en-reino-unido","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20120604\/favoritos-indiscutibles-los-beatles-en-reino-unido\/","title":{"rendered":"Favoritos indiscutibles Los Beatles en Reino Unido"},"content":{"rendered":"<p>Londres &#8211; Los Beatles son el grupo que han colocado m\u00e1s canciones como n\u00famero uno en ventas en el Reino Unido durante los 60 a\u00f1os del reinado de Isabel II, seg\u00fan divulg\u00f3 hoy la empresa que elabora las listas, la Official Charts Company.<\/p>\n<p>Pese a que solo estuvieron en activo ocho a\u00f1os y se separaron hace cuatro d\u00e9cadas, el grupo de Liverpool situ\u00f3 17 de sus temas en el n\u00famero uno en ventas, mientras uno de sus componentes, Paul McCartney, lo hizo en once ocasiones despu\u00e9s de la separaci\u00f3n de los &#8216;fab four&#8217;.<\/p>\n<p>Los Beatles, cuyo primer hit fue &#8216;Love Me Do&#8217; en 1962, han vendido en estas seis d\u00e9cadas 21,9 millones de copias de sus sencillos.<\/p>\n<p>Les siguen en este listado Elvis Presley, con 21,6 millones de copias vendidas de sus &#8216;singles&#8217;, y Cliff Richard (14 n\u00fameros uno y 21,5 millones de copias), quien junto a Paul McCartney actuar\u00e1 esta noche en un concierto en homenaje al Jubileo de Diamantes de la reina Isabel.<\/p><div class=\"notic-content-middle\" id=\"notic-3693013690\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Desde que la Official Charts Company comenz\u00f3 a elaborar este listado en 1952, el a\u00f1o de la llegada al trono de la actual soberana brit\u00e1nica, cinco artistas o bandas han logrado superar las ventas de m\u00e1s de 15 millones de ejemplares de sus sencillos en el Reino Unido.<\/p>\n<p>Adem\u00e1s de los Beatles, Elvis y Cliff Richards, Madonna (17,6 millones) y Michael Jackson (15,3 millones) completan el quinteto.<\/p>\n<p>Por su parte, Rihanna se coloc\u00f3 en d\u00e9cimo lugar del r\u00e1nking con 10,4 millones de copias vendidas de sus &#8216;singles&#8217;, por delante de los Rolling Stones, que pese a tener ya en 1963 su primer n\u00famero uno solo alcanzan el puesto 13 debido a que desde 1981 no han encabezado nunca las listas de ventas en el Reino Unido.<\/p>","protected":false},"excerpt":{"rendered":"<p>Londres &#8211; Los Beatles son el grupo que han colocado m\u00e1s canciones como n\u00famero uno en ventas en el Reino Unido durante los 60 a\u00f1os del reinado de Isabel II, seg\u00fan divulg\u00f3 hoy la empresa que elabora las listas, la Official Charts Company. Pese a que solo estuvieron en activo ocho a\u00f1os y se separaron [&hellip;]<\/p>","protected":false},"author":0,"featured_media":385966,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-87469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=87469"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87469\/revisions"}],"predecessor-version":[{"id":385968,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87469\/revisions\/385968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/385966"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=87469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=87469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=87469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}