{"id":87181,"date":"2014-03-02T19:17:08","date_gmt":"2014-03-02T23:17:08","guid":{"rendered":"http:\/\/www.noticel.com\/cuidate\/vida\/20140302\/hospital-hima-san-pablo-oncologico-obtiene-prestigiosa-acreditacion\/"},"modified":"2025-07-15T23:21:02","modified_gmt":"2025-07-15T23:21:02","slug":"hospital-hima-san-pablo-oncologico-obtiene-prestigiosa-acreditacion","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140302\/hospital-hima-san-pablo-oncologico-obtiene-prestigiosa-acreditacion\/","title":{"rendered":"Hospital HIMA San Pablo Oncol\u00f3gico obtiene prestigiosa acreditaci\u00f3n"},"content":{"rendered":"<p>La &#8216;Comisi\u00f3n sobre el C\u00e1ncer&#8217; (por sus siglas CoC) del Colegio Americano de Cirujanos (ACS) ha concedido tres a\u00f1os de acreditaci\u00f3n con elogios al programa de c\u00e1ncer del Hospital HIMA San Pablo Oncol\u00f3gico, anunci\u00f3 la entidad en un comunicado de prensa.<\/p>\n<p>Para obtener la acreditaci\u00f3n CoC voluntaria, un programa contra el c\u00e1ncer debe cumplir o superar los 34 CoC est\u00e1ndares de calidad, mantener niveles de excelencia en la prestaci\u00f3n de atenci\u00f3n integral centrada en el paciente y se evaluar\u00e1 cada tres a\u00f1os a traves de un proceso de inspecci\u00f3n. Tres a\u00f1os de acreditaci\u00f3n con elogios s\u00f3lo se concede a una instituci\u00f3n que excede los est\u00e1ndares en el momento de su inspecci\u00f3n trienal.<\/p>\n<p>Debido a que es un centro de c\u00e1ncer CoC-acreditado el Hospital HIMA San Pablo Oncol\u00f3gico adopta un enfoque multidisciplinario para el tratamiento del c\u00e1ncer como un complejo grupo de enfermedades que requiere la consulta entre los cirujanos, onc\u00f3logos m\u00e9dicos, radio-onc\u00f3logos, radi\u00f3logos de diagn\u00f3stico, pat\u00f3logos y otros especialistas en c\u00e1ncer. Resultando de esta asociaci\u00f3n multidisciplinaria en la mejor y m\u00e1s alta calidad de atenci\u00f3n al paciente.<\/p>\n<p>&#8216;Commission on Cancer nos otorgo la calificaci\u00f3n m\u00e1s alta que puede obtener un Centro de Cancer: 3 Year with Commendation. Cumpliendo con los todos los est\u00e1ndares, esto significa que nuestro Hospital Oncologico HIMA San Pablo cumple con todos los est\u00e1ndares al momento de la evaluaci\u00f3n, adem\u00e1s recibi\u00f3 siete elogios ubic\u00e1ndolo a nivel oro, la categor\u00eda m\u00e1xima posible&#8217;, declar\u00f3 el Dr. Edgardo Rodr\u00edguez Monje, director m\u00e9dico Hospital HIMA San Pablo Oncol\u00f3gico.<\/p><div class=\"notic-content-middle\" id=\"notic-968232594\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El Programa de Acreditaci\u00f3n de CoC del Colegio Americano de Cirujanos proporciona el marco para mejorar la calidad de atenci\u00f3n al paciente a trav\u00e9s de diversos programas relacionados con el c\u00e1ncer; que se concentran en el espectro de la atenci\u00f3n del c\u00e1ncer que incluye: la prevenci\u00f3n, el diagn\u00f3stico precoz, la estatificaci\u00f3n del c\u00e1ncer, el tratamiento \u00f3ptimo, la rehabilitaci\u00f3n, seguimiento de por vida para la enfermedad recurrente, y la atenci\u00f3n al final de su vida \u00fatil. Cuando los pacientes reciben atenci\u00f3n en un centro acreditado por la CoC, tambi\u00e9n tienen acceso a la informaci\u00f3n sobre los ensayos cl\u00ednicos y nuevos tratamientos, el consejo gen\u00e9tico, y los servicios centrados en el paciente, incluido el apoyo psicosocial, un proceso de navegaci\u00f3n de pacientes, as\u00ed como un plan de cuidados que documenta la atenci\u00f3n que cada paciente recibe y busca mejorar la calidad de vida de los sobrevivientes de c\u00e1ncer.<\/p>\n<p>Al igual que todas las instituciones acreditadas por la CoC, el Hospital HIMA San Pablo Oncol\u00f3gico mantiene un registro de c\u00e1ncer y aporta datos a la Base de Datos Nacional del C\u00e1ncer (NCDB), un programa conjunto de la Sociedad del C\u00e1ncer y Americana (ACS). Esta base de datos que contienen los resultados oncol\u00f3gicos a nivel nacional, es el mayor registro de la enfermedad cl\u00ednica en el mundo. Los datos sobre todos los tipos de c\u00e1ncer son rastreados y analizados a trav\u00e9s de la NCDB y se utilizan para explorar las tendencias en el tratamiento del c\u00e1ncer. Los centros de c\u00e1ncer acreditados CoC, por su parte, tienen acceso a la informaci\u00f3n derivada de este tipo de an\u00e1lisis de datos, que se utiliza para crear informes nacionales, regionales y estatales de referencia. Estos informes ayudan a las instalaciones acreditadas con sus esfuerzos de mejoras de la calidad de prestaci\u00f3n de sus servicios.<\/p>\n<p>ACS estima que m\u00e1s de 1,6 millones de casos de c\u00e1ncer ser\u00e1n diagnosticados en 2013. Actualmente hay m\u00e1s de 1,500 programas de c\u00e1ncer acreditados por la CoC en los EE.UU. y Puerto Rico, lo que representa 30 por ciento de todos los hospitales. Las instalaciones acreditadas por CoC diagnostican y \/ o tratan m\u00e1s del 70 por ciento de todos los pacientes con c\u00e1ncer reci\u00e9n diagnosticados. Cuando los pacientes con c\u00e1ncer optan por buscar atenci\u00f3n m\u00e9dica en un centro de c\u00e1ncer acreditado por la CoC, est\u00e1n ganando acceso a una atenci\u00f3n integral y a un centro state of the art cerca de su hogar. El CoC proporciona al p\u00fablico informaci\u00f3n sobre los recursos, servicios y experiencia en el tratamiento del c\u00e1ncer para cada programa de c\u00e1ncer acreditado por la CoC trav\u00e9s del localizador en:<a href=\"http:\/\/www.facs.org\/cancerprogram\/index.html.\" target=\"_blank\"> http:\/\/www.facs.org\/cancerprogram\/index.html. <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La &#8216;Comisi\u00f3n sobre el C\u00e1ncer&#8217; (por sus siglas CoC) del Colegio Americano de Cirujanos (ACS) ha concedido tres a\u00f1os de acreditaci\u00f3n con elogios al programa de c\u00e1ncer del Hospital HIMA San Pablo Oncol\u00f3gico, anunci\u00f3 la entidad en un comunicado de prensa. Para obtener la acreditaci\u00f3n CoC voluntaria, un programa contra el c\u00e1ncer debe cumplir o [&hellip;]<\/p>","protected":false},"author":0,"featured_media":387592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-87181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=87181"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87181\/revisions"}],"predecessor-version":[{"id":387594,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87181\/revisions\/387594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/387592"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=87181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=87181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=87181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}