{"id":87114,"date":"2016-06-01T12:08:00","date_gmt":"2016-06-01T16:08:00","guid":{"rendered":"http:\/\/www.noticel.com\/cuidate\/vida\/20160601\/tu-cerebro-tambien-necesita-ejercicios\/"},"modified":"2025-07-15T23:26:14","modified_gmt":"2025-07-15T23:26:14","slug":"tu-cerebro-tambien-necesita-ejercicios","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20160601\/tu-cerebro-tambien-necesita-ejercicios\/","title":{"rendered":"Tu cerebro tambi\u00e9n necesita ejercicios"},"content":{"rendered":"<p>Usualmente relacionamos el ejercicio f\u00edsico con mantener en forma el cuerpo. Nos ejercitamos para mantener un peso y condici\u00f3n f\u00edsica saludable, para bajar unas libritas, o para tonificar nuestros m\u00fasculos y lucir una buena figura.<\/p>\n<p>Pero, sab\u00edas que el ejercicio f\u00edsico es bueno para tu cerebro? Despu\u00e9s de todo, el cerebro es un m\u00fasculo que tambi\u00e9n necesita estimularse. La investigaci\u00f3n cient\u00edfica apunta que realizar ejercicios redunda en beneficios para los procesos cognitivos y puede fortalecer nuestro sistema para evitar enfermedades neurodegenerativas como el Alzh\u00e9imer.<\/p>\n<p>Aunque existen ejercicios dirigidos a mejorar la capacidad del cerebro, el portal unobrain.com recomienda hacer ejercicios f\u00edsicos por sus efectos en el aumento de producci\u00f3n de neuronas y conexiones, fen\u00f3meno que se conoce como neurog\u00e9nesis; lo que aumenta la capacidad cerebral.<\/p>\n<p>De acuerdo a un estudio realizado por la Universidad de Illinois y el Instituto Beckman de Tecnolog\u00eda y Ciencia Avanzadas, en Estados Unidos, las personas que hacen ejercicio moderado de forma regular, disponen de un mayor volumen cerebral.<\/p>\n<p><strong>Caminar<\/strong><\/p>\n<p>Una simple caminata aumenta el nivel de endorfinas; oxigenaci\u00f3n del cerebro y libera tensiones. Estudios aseguran que practicar ejercicios ayuda en los procesos cognitivos por la oxigenaci\u00f3n que produce. Caminar a paso r\u00e1pido y de ejercer alg\u00fan tipo de fuerza y resistencia moderada hace que el h\u00edgado produzca un tipo de hormona que facilita la comunicaci\u00f3n entre las c\u00e9lulas cerebrales.<\/p><div class=\"notic-content-middle\" id=\"notic-3388497147\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p><strong>Bailar<\/strong><\/p>\n<p>Dar unos pasitos de baile ayuda a crear conciencia de d\u00f3nde est\u00e1n situadas las partes de nuestro cuerpo. Bailar facilita la coordinaci\u00f3n al activar unos receptores localizados en nuestros m\u00fasculos llamados &#8216;husos neuromusculares&#8217; que, a su vez, se comunican con el cerebro.<\/p>\n<p><strong>Ejercicios en el agua<\/strong><\/p>\n<p>No solo te vas a entretener ya que requiere coordinaci\u00f3n y resistencia. No tienes que nadar, solo mu\u00e9vete. Puedes hacer elevaciones de piernas, rotaciones en el agua, trabajar con pelotas y tablas o incluso imitar los movimientos del pedaleo en una bicicleta. Si adem\u00e1s lo acompa\u00f1as de buena m\u00fasica y agradable compa\u00f1\u00eda en la piscina, todo ello revertir\u00e1 positivamente en tu salud f\u00edsica, emocional y cerebral, recomienda el portal.<\/p>\n<p>Recuerda, para activar tu cerebro, acompa\u00f1a el ejercicio f\u00edsico con meditaci\u00f3n, yoga, lectura y ejercicios de memoria. Estar\u00e1s de puro entrenamiento para estar en forma mentalmente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Usualmente relacionamos el ejercicio f\u00edsico con mantener en forma el cuerpo. Nos ejercitamos para mantener un peso y condici\u00f3n f\u00edsica saludable, para bajar unas libritas, o para tonificar nuestros m\u00fasculos y lucir una buena figura. Pero, sab\u00edas que el ejercicio f\u00edsico es bueno para tu cerebro? Despu\u00e9s de todo, el cerebro es un m\u00fasculo que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":387964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-87114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=87114"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87114\/revisions"}],"predecessor-version":[{"id":387965,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/87114\/revisions\/387965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/387964"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=87114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=87114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=87114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}