{"id":86825,"date":"2013-12-26T17:28:04","date_gmt":"2013-12-26T21:28:04","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20131226\/ponce-donativos-para-unos-si-y-otros-no\/"},"modified":"2025-07-15T23:45:58","modified_gmt":"2025-07-15T23:45:58","slug":"ponce-donativos-para-unos-si-y-otros-no","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20131226\/ponce-donativos-para-unos-si-y-otros-no\/","title":{"rendered":"Ponce: donativos para unos s\u00ed y otros no"},"content":{"rendered":"<p>Sin padrino, no se bautiza.<\/p>\n<p>L\u00edderes de organizaciones sin fines de lucro quedaron at\u00f3nitos esta semana al conocer que la administraci\u00f3n municipal de Ponce concedi\u00f3 sobre medio mill\u00f3n de d\u00f3lares a entidades deportivas, de espect\u00e1culos y hasta con fines de lucro.<\/p>\n<p>Ello justo cuando l\u00edderes y voluntarios de sus instituciones hacen malabares para no suspender operaciones y continuar dando servicios a cientos de personas desvalidas, sin ayuda del Gobierno Municipal.<\/p>\n<p>Uno de los m\u00e1s sorprendidos fue el presidente de la Fundaci\u00f3n Go Gogo, Ulyses Clavell Font\u00e1nez.<\/p>\n<p>La Fundaci\u00f3n Go Gogo es una entidad compuesta por voluntarios que brinda ayuda a m\u00e1s de un centenar de ni\u00f1os enfermos con c\u00e1ncer. Incluso, por iniciativa propia cre\u00f3 el Centro de Oncolog\u00eda Pedi\u00e1trica de Ponce. Aun as\u00ed, no recibe ayuda del Gobierno Municipal de Ponce.<\/p>\n<p>Seg\u00fan explic\u00f3, la administraci\u00f3n municipal \u00fanicamente le ha concedido un donativo de $1,000 y tard\u00f3 un a\u00f1o en desembolsarlo.<\/p>\n<p>&#8216;Con el pasar de los a\u00f1os, hemos aprendido a no solicitar ni depender del Gobierno, y menos del Gobierno Municipal. En realidad, las veces que nos hemos acercado, nunca hemos tenido una acci\u00f3n positiva&#8217;, explic\u00f3 el presidente de la Fundaci\u00f3n Go Gogo.<\/p>\n<p>&#8216;Hay gente que eval\u00faa en qu\u00e9 deben invertir el dinero y entiendo yo que ellos no consideran la salud de los ni\u00f1os como una inversi\u00f3n del pueblo. Prefieren invertirlo en otras actividades que ellos entienden que ser\u00edan m\u00e1s beneficiosas para el pueblo&#8217;, continu\u00f3.<\/p>\n<p>&#8216;Gracias a Dios, hemos podido crear un buen nombre y una organizaci\u00f3n s\u00f3lida que la gente, tanto de Ponce como de todo el pa\u00eds respalda, porque aporta al futuro del pa\u00eds y a la salud de los ni\u00f1os&#8217;, a\u00f1adi\u00f3. &#8216;Hemos tenido que depender de otras personas para levantar algo en nuestra ciudad&#8217;.<\/p>\n<p>El pasado mes de marzo, La Perla del Sur revel\u00f3 c\u00f3mo el Gobierno Municipal de Ponce retras\u00f3 la inauguraci\u00f3n del primer Centro de Oncolog\u00eda Pedi\u00e1trica del Sur, al detener temporeramente la concesi\u00f3n de un permiso de uso para la estructura, en espera de un pago de $660 para arbitrios de construcci\u00f3n.<\/p>\n<p>Esto a\u00fan cuando semanas antes la administraci\u00f3n municipal eximi\u00f3 a la Fundaci\u00f3n Rafael Hern\u00e1ndez Col\u00f3n del pago de $249 mil en arbitrios para la construcci\u00f3n de una biblioteca dedicada al exgobernador y ahora aliado pol\u00edtico de la alcaldesa.<\/p><div class=\"notic-content-middle\" id=\"notic-68647666\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Qu\u00e9 podr\u00edamos hacer? Qu\u00e9 no podr\u00eda hacer la Fundaci\u00f3n Go Gogo con $645 mil?&#8217;, respondi\u00f3 Clavell Font\u00e1nez a preguntas sobre el uso que le podr\u00eda dar esta organizaci\u00f3n a la suma de dinero.<\/p>\n<p>&#8216;Con ese dinero y la voluntad que tenemos yo hago la Sala de Emergencia y abro un \u00e1rea para cirug\u00edas menores de ni\u00f1os. Se pueden hacer una infinidad de cosas&#8217;, sostuvo.<\/p>\n<p><strong>De tripas corazones en Cristo Pobre<\/strong><\/p>\n<p>El administrador del centro para personas sin hogar Cristo Pobre en Ponce, Juan de Dios Vid\u00f3 Soler, tampoco pudo ocultar su asombro. M\u00e1xime cuando su proyecto no se ha beneficiado de semejante generosidad.<\/p>\n<p>El centro Cristo Pobre ofrece servicios gratuitos de alimentos, consejer\u00eda y tratamiento a m\u00e1s de un centenar de personas sin hogar en Ponce.<\/p>\n<p>Recientemente, los altos costos operacionales, incluyendo el pago de utilidades, obligaron a Vid\u00f3 Soler a despedir dos empleados de su limitado equipo de trabajo, por falta de recursos.<\/p>\n<p>Aun as\u00ed, al centro no se le asigna un s\u00f3lo centavo de los sobre $100 millones en presupuesto que maneja anualmente el ayuntamiento.<\/p>\n<p>La \u00fanica asignaci\u00f3n gubernamental que recibe proviene de fondos federales a trav\u00e9s del Programa de Emergencia para Pacientes VIH y la Legislatura Estatal.<\/p>\n<p>Mas sobre el uso que podr\u00eda dar Cristo Pobre a $650 mil en donativos municipales, Vid\u00f3 Soler no repar\u00f3 en responder.<\/p>\n<p>Para leer la historia completa visite <a href=\"http:\/\/www.periodicolaperla.com\/index.php?option=com_content&amp;view=articleid=5725:idoble-vara-se-cantan-sin-fondos-para-organizaciones-beneficascatid=81:locales&gt;&lt;&gt;&lt;&gt;Itemid=198\" target=\"_blank\" la=\"\" perla=\"\" del=\"\" sur=\"\"\/><\/p>","protected":false},"excerpt":{"rendered":"<p>Sin padrino, no se bautiza. L\u00edderes de organizaciones sin fines de lucro quedaron at\u00f3nitos esta semana al conocer que la administraci\u00f3n municipal de Ponce concedi\u00f3 sobre medio mill\u00f3n de d\u00f3lares a entidades deportivas, de espect\u00e1culos y hasta con fines de lucro. Ello justo cuando l\u00edderes y voluntarios de sus instituciones hacen malabares para no suspender [&hellip;]<\/p>","protected":false},"author":0,"featured_media":389520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-86825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/86825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=86825"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/86825\/revisions"}],"predecessor-version":[{"id":389521,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/86825\/revisions\/389521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/389520"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=86825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=86825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=86825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}