{"id":86398,"date":"2016-02-11T18:13:00","date_gmt":"2016-02-11T22:13:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20160211\/salud-informa-sobre-nuevos-casos-de-zika-e-influenza\/"},"modified":"2025-07-16T00:18:50","modified_gmt":"2025-07-16T00:18:50","slug":"salud-informa-sobre-nuevos-casos-de-zika-e-influenza","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160211\/salud-informa-sobre-nuevos-casos-de-zika-e-influenza\/","title":{"rendered":"Salud informa sobre nuevos casos de zika e influenza"},"content":{"rendered":"<p>Nueve casos de zika confirmados por laboratorio se registraron para la semana epidemiol\u00f3gica cuatro, inform\u00f3 la secretaria del Departamento de Salud, Ana R\u00edus Armend\u00e1riz.<\/p>\n<p>La titular de Salud subray\u00f3 que &#8216;la mejor forma de prevenir es haciendo uso de repelente y verificando los alrededores del hogar para eliminar posibles criaderos de mosquitos&#8217;.<\/p>\n<p>Por otra parte, se indic\u00f3 que en la semana epidemiol\u00f3gica cinco (31 de enero al 6 de febrero) se reportaron 1,482 casos de influenza y 52 hospitalizaciones relacionadas a esta.<\/p><div class=\"notic-content-middle\" id=\"notic-2236018955\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La epidemi\u00f3loga del Estado, Brenda Rivera Garc\u00eda, explic\u00f3 que la variante dominando en estos momentos es la H1N1 variante pand\u00e9mica. &#8216;Continuamos exhortando a la vacunaci\u00f3n. La vacuna est\u00e1 disponible y es segura, no esperen m\u00e1s para proveerse esta protecci\u00f3n&#8217;, apunt\u00f3.<\/p>\n<p>Las salubristas recordaron las siguientes cl\u00ednicas masivas de vacunaci\u00f3n: el 18 de febrero en el coliseo Roberto Clemente en San Juan, el 23 de febrero en el coliseo Antonio R. Barcel\u00f3 de Toa Baja, y el 25 del mismo mes en la cancha Salvador Dijols en Ponce.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre este y otros temas relacionados visite http:\/\/www.salud.gov.pr\/<\/p>","protected":false},"excerpt":{"rendered":"<p>Nueve casos de zika confirmados por laboratorio se registraron para la semana epidemiol\u00f3gica cuatro, inform\u00f3 la secretaria del Departamento de Salud, Ana R\u00edus Armend\u00e1riz. La titular de Salud subray\u00f3 que &#8216;la mejor forma de prevenir es haciendo uso de repelente y verificando los alrededores del hogar para eliminar posibles criaderos de mosquitos&#8217;. Por otra parte, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":391948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-86398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/86398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=86398"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/86398\/revisions"}],"predecessor-version":[{"id":391950,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/86398\/revisions\/391950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/391948"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=86398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=86398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=86398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}