{"id":83402,"date":"2013-08-16T00:00:00","date_gmt":"2013-08-16T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20130816\/reabren-expreso-tras-accidente-fatal-esta-madrugada\/"},"modified":"2025-07-16T05:07:41","modified_gmt":"2025-07-16T05:07:41","slug":"reabren-expreso-tras-accidente-fatal-esta-madrugada","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20130816\/reabren-expreso-tras-accidente-fatal-esta-madrugada\/","title":{"rendered":"Reabren expreso tras accidente fatal esta madrugada"},"content":{"rendered":"<p>Un hombre muri\u00f3 en medio de un accidente fatal ocurrido en horas de la madrugada del viernes, lo que provoc\u00f3 el cierre de un tramo de la Autopista Luis A. Ferre entre los municipios de Cayey y Caguas.<\/p>\n<p>El accidente de car\u00e1cter fatal ocurri\u00f3 a eso de las 3:45 de la madrugada a la altura del kil\u00f3metro 29.5, en el tramo que discurre en direcci\u00f3n de Cayey a Caguas, que ya fue reabierto, seg\u00fan fue informado.<\/p>\n<p>El accidente ocurri\u00f3 cuando F\u00e9lix Aguirre Ramos de 58 a\u00f1os residente en Ponce, con un veh\u00edculo Nissan Frontier, color rojo impact\u00f3 con la parte frontal, la parte posterior de un cami\u00f3n de carga, modelo Kenworth el cual transportaba cemento y era conducido por Jos\u00e9 Vargas Mart\u00ednez de 56 a\u00f1os.<\/p><div class=\"notic-content-middle\" id=\"notic-1580029946\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Aguirre Ramos, que aparentemente viajaba solo, muri\u00f3 en el acto tras el impacto contra el cami\u00f3n. Al momento no se sabe que provoc\u00f3 que el hombre impactara el cami\u00f3n.<\/p>\n<p>Agentes de la Divisi\u00f3n de Autopistas del \u00e1rea de Caguas, en uni\u00f3n a la fiscal Roc\u00edo Garc\u00eda, se encuentran investigando los hechos.<\/p>\n<p>Debido a la colisi\u00f3n el carril derecho y el central de ese tramo de autopista fueron cerrados al tr\u00e1nsito, mientras se completaba la investigaci\u00f3n. Al momento, ya la v\u00eda fue reabierta en su totalidad y se espera que el tr\u00e1nsito regrese a la normalidad.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un hombre muri\u00f3 en medio de un accidente fatal ocurrido en horas de la madrugada del viernes, lo que provoc\u00f3 el cierre de un tramo de la Autopista Luis A. Ferre entre los municipios de Cayey y Caguas. El accidente de car\u00e1cter fatal ocurri\u00f3 a eso de las 3:45 de la madrugada a la altura [&hellip;]<\/p>","protected":false},"author":0,"featured_media":411594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-83402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=83402"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83402\/revisions"}],"predecessor-version":[{"id":411595,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83402\/revisions\/411595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/411594"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=83402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=83402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=83402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}