{"id":83207,"date":"2011-07-03T00:00:00","date_gmt":"2011-07-03T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20110703\/piculin-estoy-arrepentido\/"},"modified":"2025-07-16T05:50:05","modified_gmt":"2025-07-16T05:50:05","slug":"piculin-estoy-arrepentido","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20110703\/piculin-estoy-arrepentido\/","title":{"rendered":"&#8216;Picul\u00edn&#8217;: &#8216;Estoy arrepentido&#8217;"},"content":{"rendered":"<p>Jos\u00e9 &#8216;Picul\u00edn&#8217; Ortiz habl\u00f3 c\u00e1ndidamente en la tarde hoy con su amigo Angelo Medina, promotor que fue apoderado de los Cangrejeros de Santurce, y dijo que har\u00e1 una carta abierta al pueblo de Puerto Rico, pues se siente abochornado por su arresto el mi\u00e9rcoles por posesi\u00f3n de marihuana con intenci\u00f3n de distribuir.<\/p>\n<p>&#8216;Me dijo: &#8216;Angelo, estoy arrepentido. Con mucha dignidad le serv\u00ed a mi patria y quiero separar esta otra vida de aquella del deporte\u00bb, relat\u00f3 esta tarde Medina a NotiCel.<\/p>\n<p>&#8216;Tuve la oportunidad de visitarlo. Lo v\u00ed a \u00e9l, y es una combinaci\u00f3n dif\u00edcil de sentimientos explicarte c\u00f3mo fue. Lo v\u00ed bien, pero a la vez preocupado y prepar\u00e1ndose para el proceso que va a enfrentar y, sobre todo, para el de pedirle excusas al pueblo por esta situaci\u00f3n&#8217;, dijo Medina esta tarde, se\u00f1alando que durante la semana Ortiz le har\u00e1 llegar una carta abierta al pueblo de Puerto Rico para que se haga p\u00fablica.<\/p>\n<p>&#8216;Lo v\u00ed reconociendo que ha sido v\u00edctima de una enfermedad, me afirma que necesita ayuda, que entiende que cay\u00f3 en las garras de la droga y que quiere prepararse para comenzar su nueva preparaci\u00f3n&#8217;, agreg\u00f3.<\/p>\n<p>Medina relat\u00f3 que Ortiz se emocion\u00f3 bastante durante la conversaci\u00f3n cuando le habl\u00f3 de una encuesta que vio en un peri\u00f3dico que hab\u00eda en una mesa del centro de rehabilitaci\u00f3n, en la cual la mayor\u00eda de los entrevistados indicaba que respaldan al legendario astro del baloncesto en su proceso de recuperaci\u00f3n y en el l\u00edo legal que enfrenta. &#8216;Se sinti\u00f3 tranquilo, porque vio una encuesta en un peri\u00f3dico donde el 67% le dio el respaldo y que eso lo motiva mucho en este dif\u00edcil momento&#8217;, indic\u00f3.<\/p>\n<p>&#8216;Me dijo: &#8216;Angelo, estoy arrepentido de que esta cuesti\u00f3n se me haya ido a la cabeza. Con mucha dignidad le serv\u00ed a mi patria y quiero separar esta otra vida de aquella del deporte. Cuando yo jugu\u00e9, yo cumpl\u00ed a cabalidad con mi responsabilidad, no quiero que la gente mezcle esto que me pas\u00f3 con lo que hice en el deporte y por mi pa\u00eds, porque son muy distintas y separadas, y por mi patria doy la vida&#8217;. \u00c9l est\u00e1 muy preocupado porque los fan\u00e1ticos y el pueblo en general entiendan que esta es una etapa en su vida muy distinta a la de su carrera en el deporte. Cuando empez\u00f3 el retiro, \u00e9l pens\u00f3 que estaba preparado, pero entiende que con sus amistades y en cuanto a la cuesti\u00f3n social, no tuvo el criterio claro para tomar las decisiones que ha tomado&#8217;, puntualiz\u00f3 Medina.<\/p>\n<p>El promotor Medina finalmente pudo ver a Ortiz, al visitarlo en el centro de rehabilitaci\u00f3n federal en el que se encuentra, y que, seg\u00fan indic\u00f3, est\u00e1 localizado &#8216;en alg\u00fan campo de la zona norte-central de la isla, por esa \u00e1rea de Toa Alta, Dorado, Corozal, Comer\u00edo&#8217;.<\/p>\n<p>La visita, seg\u00fan el empresario, &#8216;no se dio bajo f\u00e1ciles circunstancias&#8230; fue una cita que se arregl\u00f3 entre la defensa y fiscal\u00eda, y no fue f\u00e1cil. Han habido muchas restricciones, y se entiende&#8217;.<\/p>\n<p>Ortiz fue arrestado por agentes federales de Inmigraci\u00f3n y Aduanas el jueves en la ma\u00f1ana en Cayey donde se allan\u00f3 una residencia que \u00e9ste ten\u00eda bajo alquiler. Se le ocuparon 218 plantas de marihuana, equipo para sembrarla y 40 balas compatibles con rifle AR-15. Enfrenta una querella y no una acusasi\u00f3n de Gran Jurado y se le estableci\u00f3 una vista preliminar el 26 de julio. Si fiscal\u00eda federal obtiene una acusaci\u00f3n de Gran Jurado antes de eso, se pasar\u00eda a lectura de cargos y juicio. De ser hallado culpable, enfrentar\u00eda una pena de entre 5 y 40 a\u00f1os de c\u00e1rcel.<\/p><div class=\"notic-content-middle\" id=\"notic-820734810\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Sobre el caso que pudiera enfrentar, Medina dijo que, seg\u00fan le dijo Ortiz, este &#8216;no tiene muchos datos sobre el asunto. Me dijo que se tiene que reunir este martes con su abogado, H\u00e9ctor Ramos, y ah\u00ed sabr\u00e1 bien&#8217;.<\/p>\n<p>El licenciado Ramos, abogado de la oficina de asistencia legal federal que le fue apuntado a Ortiz por la Corte, deber\u00e1 aprovechar bien el fin de semana largo para descansar, pues parece que tendr\u00e1 una agenda llena la semana entrante. No tan solo deber\u00e1 reunirse con Ortiz, sino que Medina dijo que espera comunicarse con \u00e9l en o antes del martes, pues en ese d\u00eda sale del pa\u00eds a atender compromisos de manejo con el grupo Man\u00e1, uno de los artistas que representa.<\/p>\n<p>A ver si eso se da, pues el mismo martes es el d\u00eda en el que el licenciado Joaqu\u00edn Monserrate Matienzo espera reunirse con Ramos. Tal y como adelant\u00f3 el pasado viernes NotiCel, Monserrate Matienzo es el encomendado del presidente del Comit\u00e9 Ol\u00edmpico de Puerto Rico (COPUR), David Bernier, de su hom\u00f3logo de la Federaci\u00f3n de Baloncesto, Carlos Beltr\u00e1n, y del Secretario General Em\u00e9rito de FIBA Am\u00e9rica, Jenaro &#8216;Tuto&#8217; Marchand.<\/p>\n<p>&#8216;El sabe de la noticia de Monserrate Matienzo y entiende tambi\u00e9n que H\u00e9ctor Ramos es excelente, pero del caso \u00e9l no habl\u00f3 mucho. Va a escribir algo y me lo va a enviar en la semana, su propio sentir, para que el pueblo sepa&#8217;, apostill\u00f3 Medina.<\/p>\n<p>Seg\u00fan supo NotiCel, entre las personas con las que Ortiz ha tenido comunicaci\u00f3n se encuentra su compa\u00f1era sentimental, Silvia R\u00edos, quien lo ha confortado en estos momentos dif\u00edciles y con quien lleva ya un tiempo compartiendo.<\/p>\n<p>Adem\u00e1s, el pasado viernes, su ex esposa Nirita Ruiz lo visit\u00f3 y llev\u00f3 a su hija, quien este fin de semana parti\u00f3 hacia Estados Unidos, pues fue becada en una universidad de la NCAA para jugar voleibol.<\/p>\n<p>Medina hizo hincapi\u00e9 en que Ortiz agradece todo el respaldo de sus verdaderos amigos y del pueblo que as\u00ed entienda en d\u00e1rselo &#8216;en estos momentos tan dif\u00edciles en los que \u00e9l est\u00e1 muy arrepentido&#8217;. Incluso, record\u00f3 uno de los m\u00e1s grandes momentos del jugador, que quiz\u00e1s mejor ejemplifica el compromiso que el canastero siempre le demostr\u00f3 a su patria y a su equipo nacional.<\/p>\n<p>&#8216;Me acuerdo en 1989, cuando &#8216;Picu&#8217; jugaba en Espa\u00f1a, viaj\u00f3 a jugar con el equipo nacional en M\u00e9xico, ya regres\u00f3 r\u00e1pido, porque su equipo all\u00e1 no quer\u00eda perderlo, ya que era un momento importante en la temporada. Le ganamos el oro a Estados Unidos en el Premundial ese d\u00eda. As\u00ed era su compromiso&#8217;, dijo Medina.<\/p>\n<p>Marchand, puertorrique\u00f1o que ostenta el puesto Secretario General Em\u00e9rito de FIBA Am\u00e9rica, record\u00f3 que &#8216;eso lo hizo tres o cuatro veces. \u00c9l nunca se perdi\u00f3 un evento de Puerto Rico, al menos mientras yo dirig\u00eda la Federaci\u00f3n&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 &#8216;Picul\u00edn&#8217; Ortiz habl\u00f3 c\u00e1ndidamente en la tarde hoy con su amigo Angelo Medina, promotor que fue apoderado de los Cangrejeros de Santurce, y dijo que har\u00e1 una carta abierta al pueblo de Puerto Rico, pues se siente abochornado por su arresto el mi\u00e9rcoles por posesi\u00f3n de marihuana con intenci\u00f3n de distribuir. &#8216;Me dijo: &#8216;Angelo, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":414178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-83207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=83207"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83207\/revisions"}],"predecessor-version":[{"id":414181,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83207\/revisions\/414181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/414178"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=83207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=83207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=83207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}