{"id":830584,"date":"2025-03-03T11:31:43","date_gmt":"2025-03-03T15:31:43","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/legislatura\/top-stories\/20250303\/senador-juan-oscar-morales-dice-que-no-le-dar-su-voto-a-janet-parra-para-ser-designada\/"},"modified":"2025-08-01T13:42:11","modified_gmt":"2025-08-01T13:42:11","slug":"senador-juan-oscar-morales-dice-que-no-le-dara-su-voto-a-janet-parra-para-ser-confirmada","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20250303\/senador-juan-oscar-morales-dice-que-no-le-dara-su-voto-a-janet-parra-para-ser-confirmada\/","title":{"rendered":"Senador Juan Oscar Morales dice que no le dar\u00e1 su voto a Janet Parra para ser confirmada"},"content":{"rendered":"<h3>El senador penep\u00e9 aleg\u00f3 que no concuerdan muchas respuestas que dio el pasado s\u00e1bado en la vista de nombramientos sobre la descalificaci\u00f3n de su caso en el 2022, versus las declaraciones que ha dado a los medios de comunicaci\u00f3n.<\/h3>\n<p>Ya existe un voto menos dentro de la delegaci\u00f3n del Partido Nuevo Progresista (PNP), por parte del senador Juan Oscar Morales, que no le dar\u00e1 el voto a favor a la licenciada Janet Parra Mercado, para que sea designada oficialmente como secretaria del Departamento de Justicia.<\/p>\n<p>Morales asegur\u00f3 que est\u00e1 seguro de su postura y que por ninguna circunstancia cambiar\u00e1 de opini\u00f3n.<\/p>\n<p>Todo surge desde que el pasado s\u00e1bado, en la vista de nombramientos,  Morales interrog\u00f3 a Parra Mercado sobre la descalificaci\u00f3n de un caso en el 2022, despu\u00e9s de intentar ser la representaci\u00f3n legal de dos integrantes de la organizaci\u00f3n criminal de Delwin Berr\u00edos Navarro, alias \u00abTunt\u00fan\u00bb, justo despu\u00e9s de renunciar como fiscal del Departamento de Justicia.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/20250301\/intercambio-persistente-con-parra-mercado-sobre-su-descalificacion-de-un-caso-en-el-2022\/\" id=\"link-0c06e395c61ce3e4de2aacdcf2714e98\" target=\"_blank\">Intercambio persistente con Parra Mercado sobre su descalificaci\u00f3n de un caso en el 2022<\/a><\/p>\n<p>Seg\u00fan el senador penep\u00e9, la exfiscal hab\u00eda sido \u00abincapaz de defenderse a s\u00ed misma\u00bb (por no llevar el caso ante el Supremo sobre su descalificaci\u00f3n) , c\u00f3mo pod\u00eda administrar y defender a las v\u00edctimas bajo el Departamento de Justicia.<\/p>\n<p>Morales tambi\u00e9n hab\u00eda insistido que sus respuestas ante sus preguntas sobre ese caso, no concordaban con las entrevistas que ha dado en los medios de comunicaci\u00f3n. Por esa raz\u00f3n, no lo convence para que asuma el cargo.<\/p>\n<p>\u00abNo, no puedo estar satisfecho porque yo ten\u00eda la entrevista que ustedes realizaron aqu\u00ed el pasado 13 de enero donde hay varios puntos donde ella contesta y cuando le hago las preguntas el pasado s\u00e1bado, lo que contest\u00f3 en la vista no es lo mismo\u00bb, dijo Morales en entrevista en Primer Round por Magic 97.3 fm.<\/p>\n<p>El senador explic\u00f3 que algunas de las respuestas que no concuerdan es de su participaci\u00f3n en el programa 100 x 35, que ten\u00eda la funci\u00f3n de investigar organizaciones criminales y en la que se alega que se investig\u00f3 a la organizaci\u00f3n que ella estaba fungiendo como abogada. Situaci\u00f3n que la colocaba en una posici\u00f3n de tener informaci\u00f3n privilegiada.<\/p>\n<p>\u00abElla aqu\u00ed neg\u00f3 cualquier v\u00ednculo de participaci\u00f3n con ese plan 100 x 35. Sin embargo, en la vista dice que si, que asign\u00f3 dos fiscales para el norte, dos para el sur, tuvo el expediente del plan 100 x 35 en su oficina, as\u00ed que eso no me concuerda\u00bb, asegur\u00f3 Morales.<\/p>\n<p>Otra de las respuestas que no le convencen a Morales, es cuando se le cuestion\u00f3 del porqu\u00e9 no hab\u00eda apelado en el Supremo la descalificaci\u00f3n del caso.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/top-stories\/20250302\/la-confirmacion-de-janet-parra-puede-demorar-en-lo-que-se-concreta-entrevista-con-fiscales\/\" id=\"link-a2a5239d0fa79eddbbf06f6293f70592\" target=\"_blank\">Confirmaci\u00f3n de Janet Parra puede demorar en lo que se concreta entrevista con fiscales<\/a><\/p>\n<p>\u00abEl alegato que ella hizo en esa entrevista fue porque el Departamento de Justicia ten\u00eda toda esa informaci\u00f3n y ella se le hac\u00eda dif\u00edcil obtener esa informaci\u00f3n. A mi me extra\u00f1a una aseveraci\u00f3n como esa, un abogado y m\u00e1s un fiscal. Todos sabemos cu\u00e1les son los procedimientos en el Departamento de Justicia, para requerir esos documentos\u00bb, dice Morales.<\/p>\n<p>Parra Mercado dio otra versi\u00f3n el pasado s\u00e1bado, su argumento fue que no hab\u00eda apelado al Supremo por miedo a represarias contra sus compa\u00f1eros de Justicia que ten\u00eda que testificar en el caso.<\/p>\n<p>\u00abLa inconsistencia es lo que a mi me preocupa en este caso. As\u00ed que, as\u00ed las cosas, tengo serias dudas de a qui\u00e9n creerle&#8230;tengo serias dudas&#8230;mi voto no lo tiene\u00bb, insisti\u00f3 el senador.<\/p>\n<p>A pesar de que Morales no favorecer\u00e1 su nombramiento, dijo que si como quiera llega ser confirmada \u00abtiene en mi un aliado, pero votar por ella, es algo de conciencia y no lo voy hacer. No hay animosidad en contra de ella, es producto de sus propias expresiones. No ha sido consistente y yo le pido a la secretaria que para la posici\u00f3n que ella est\u00e1 aspirando,  la consistencia es bien importante, la transparencia m\u00e1s todav\u00eda\u00bb, concluy\u00f3.<\/p>\n<p>El l\u00edder senarorial, Thomas Rivera Schatz, ahora se dispone a entrevistar a los fiscales y empleados judiciales que se vieron involucrados como testigos en el caso de descalificaci\u00f3n.<\/p>\n<p>Historia relacionada: <a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/top-stories\/20250301\/janet-parra-procesaria-casos-de-aborto-si-asi-lo-estableciera-la-asamblea-legislativa\/\" id=\"link-9c0c8c43f5d04211640d7b44b8b613c8\" target=\"_blank\">Janet Parra procesar\u00eda casos de aborto si as\u00ed lo estableciera la Asamblea Legislativa<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El senador penep\u00e9 aleg\u00f3 que no concuerdan muchas respuestas que dio el pasado s\u00e1bado en la vista de nombramientos sobre la descalificaci\u00f3n de su caso en el 2022, versus las declaraciones que ha dado a los medios de comunicaci\u00f3n. Ya existe un voto menos dentro de la delegaci\u00f3n del Partido Nuevo Progresista (PNP), por parte [&hellip;]<\/p>","protected":false},"author":29,"featured_media":528924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-830584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/830584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=830584"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/830584\/revisions"}],"predecessor-version":[{"id":839151,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/830584\/revisions\/839151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/528924"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=830584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=830584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=830584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}