{"id":83007,"date":"2018-05-08T00:00:00","date_gmt":"2018-05-08T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20180508\/fallece-madre-de-la-alcaldesa-de-ponce\/"},"modified":"2025-07-16T06:38:01","modified_gmt":"2025-07-16T06:38:01","slug":"fallece-madre-de-la-alcaldesa-de-ponce","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20180508\/fallece-madre-de-la-alcaldesa-de-ponce\/","title":{"rendered":"Fallece madre de la Alcaldesa de Ponce"},"content":{"rendered":"<p><i>Ten\u00eda 94 a\u00f1os.<\/i><\/p>\n<p>La progenitora de la alcaldesa de Ponce, Mar\u00eda &#8216;Mayita&#8217; Melendez Altieri, Elo\u00edsa Altieri, falleci\u00f3 en horas de la noche del lunes a los 94 a\u00f1os.<\/p>\n<p>&#8216;De mi madre aprend\u00ed a ser luchadora, recta y a que uno entra a un trabajo con la cabeza en alto y de igual forma sale. Siempre la recordare con su sonrisa y alegr\u00eda&#8217;, puntualiz\u00f3 la alcaldesa en declaraciones escritas.<\/p>\n<p>\u00c9sta solicit\u00f3 espacio para ella y su familia para atender la situaci\u00f3n privadamente.<\/p><div class=\"notic-content-middle\" id=\"notic-1133862087\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Agradezco a todos las muestras de respeto y solidaridad en este momento de profundo dolor. Mima ya descansa en los brazos del Se\u00f1or&#8217;, expres\u00f3 Melendez Altieri.<\/p>\n<p>De igual modo, el presidente de la Legislatura Municipal de Ponce, Rafael Mateu Cintr\u00f3n expres\u00f3 su pesar ante el fallecimiento de Altieri y exhort\u00f3 al pueblo a unirse en oraci\u00f3n por fortaleza para toda la familia.<\/p>\n<p>&#8216;Durante la sesi\u00f3n extraordinaria que celebramos hoy, nuestro compa\u00f1ero, el Dr. Irizarry Pab\u00f3n elev\u00f3 una oraci\u00f3n por la mam\u00e1 de nuestra Alcaldesa, por lo que confiamos en que ya descansa en paz en los brazos de su Se\u00f1or&#8217;, expres\u00f3 Mateu en declaraciones escritas.<\/p>\n<p>A\u00f1adi\u00f3, &#8216;todos los miembros de la Legislatura Municipal, de la mayor\u00eda y la minor\u00eda, se unen al dolor que enfrenta la familia hoy. Todos estaremos apoyando a nuestra Alcaldesa en este dif\u00edcil momento. Nos resta estar unidos en oraci\u00f3n para que Dios les des las fuerzas que necesitan para enfrentar este dif\u00edcil momento&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ten\u00eda 94 a\u00f1os. La progenitora de la alcaldesa de Ponce, Mar\u00eda &#8216;Mayita&#8217; Melendez Altieri, Elo\u00edsa Altieri, falleci\u00f3 en horas de la noche del lunes a los 94 a\u00f1os. &#8216;De mi madre aprend\u00ed a ser luchadora, recta y a que uno entra a un trabajo con la cabeza en alto y de igual forma sale. Siempre [&hellip;]<\/p>","protected":false},"author":0,"featured_media":416856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-83007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=83007"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83007\/revisions"}],"predecessor-version":[{"id":416858,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/83007\/revisions\/416858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/416856"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=83007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=83007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=83007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}